
{"id":44717,"date":"2026-05-01T15:44:58","date_gmt":"2026-05-01T19:44:58","guid":{"rendered":"https:\/\/www.digepres.gob.do\/?p=42234"},"modified":"2026-06-01T11:53:55","modified_gmt":"2026-06-01T15:53:55","slug":"presupuesto-cierra-la-semana-de-la-etica-promoviendo-buenas-practicas-en-el-servicio-publico-2","status":"publish","type":"post","link":"https:\/\/digepres.gob.do\/en\/presupuesto-cierra-la-semana-de-la-etica-promoviendo-buenas-practicas-en-el-servicio-publico-2\/","title":{"rendered":"The Budget Office concludes Ethics Week by promoting good practices in public service"},"content":{"rendered":"<p><em>The Governmental Integrity and Regulatory Compliance Commission of DIGEPRES reaffirms each year the importance of strengthening integrity, transparency, values and culture of institutional responsibility<\/em><\/p>\n<p>With the motto &quot;Development is in Integrity&quot;, the Governmental Integrity and Regulatory Compliance Commission -CIGCN- of the General Directorate of Budget, successfully concluded the DIGEPRES Ethics Week with the purpose of promoting and strengthening values and ethics within the budgetary institution.<\/p>\n<p>At the opening of DIGEPRES Ethics Week, the welcoming remarks were given by Lidia Castillo, representative of the occasional group of occupational group V, and Paola Chaljub, head of the Communications Department, who both highlighted the importance of the activity and motivated the collaborators to continue complying with each regulation and supporting the actions within the framework of the commemoration of the National Day of Citizen Ethics.<\/p>\n<div class=\"wp-block-image\"><img fetchpriority=\"high\" decoding=\"async\" class=\"wpa-warning wpa-image-missing-alt wp-image-42236 alignleft\" src=\"https:\/\/digepres.gob.do\/wp-content\/uploads\/2026\/05\/WhatsApp-Image-2026-05-01-at-3.41.43-PM-300x200.jpeg\" alt=\"\" width=\"330\" height=\"220\" data-warning=\"Falta el texto alternativo\" \/><\/div>\n<p>The CIGCN celebrated Ethics Week, including in its extensive program the installation of the &quot;Values Swap,&quot; the launch of the Citizen Complaint Box, the &quot;Every Decision Counts&quot; activity aimed at staff from Occupational Groups I and II, and closing with a Film Forum.<\/p>\n<p>The days of activities promoted by the CIGCN address key issues such as corruption prevention, strengthening regulatory compliance and promoting good practices in public service, all within an inclusive and participatory approach.<\/p>\n<p>The DIGEPRES Ethics Week is becoming increasingly established each year as a forum that strengthens integrity, transparency, values, a culture of responsibility, the common good, the fight against corruption, and improved trust in the institution. With this initiative, the Budget Office reaffirms its commitment to continue promoting actions and policies that strengthen public ethics and contribute to building a more just society, institutional strengthening, and civic engagement.<\/p>\n<p>DIGEPRES under the leadership of the General Directorate of Ethics and Governmental Integrity\u00a0<a href=\"https:\/\/www.digeig.gob.do\/\">DIGEIG<\/a>, formed its Governmental Integrity and Regulatory Compliance Commission\u00a0<a href=\"https:\/\/digepres.gob.do\/transparencia\/wp-content\/uploads\/2025\/01\/Codigo-Integridad-Institucional-Digepres.pdf\">(CIGCN)<\/a>\u00a0In compliance with Decree No. 791-21, which declares the process of implementation and election of the Government Integrity and Regulatory Compliance Commissions to be of high national priority\u00a0<a href=\"https:\/\/digepres.gob.do\/transparencia\/wp-content\/uploads\/2025\/01\/Codigo-Integridad-Institucional-Digepres.pdf\">(CIGCN)<\/a>\u00a0in all public institutions.<\/p>\n<div class=\"wp-block-image\"><img decoding=\"async\" class=\"wpa-warning wpa-image-missing-alt wp-image-42237 alignright\" src=\"https:\/\/digepres.gob.do\/wp-content\/uploads\/2026\/05\/WhatsApp-Image-2026-05-01-at-3.42.27-PM-300x200.jpeg\" alt=\"\" width=\"260\" height=\"173\" data-warning=\"Falta el texto alternativo\" \/><\/div>\n<p>The DIGEPRES Ethics Week with the participation of the Director of the General Directorate of Budget, Jos\u00e9 Rijo Presbot; Iv\u00e1n Ram\u00edrez, Deputy Director; Budget Officers, Technicians and Collaborators.<\/p>\n<p>The deployment of activities promoted by the CIGCN of the DIGEPRES, within the framework of the National Day of Citizen Ethics, also seeks to join the actions promoted by the General Directorate of Ethics and Governmental Integrity (<a href=\"https:\/\/www.digeig.gob.do\/\">DIGEIG<\/a>) and honor the historical memory and legacy of Ulises Francisco Espaillat, Dominican statesman, nineteenth president of the country, a symbol of the common good and civic ethics.<\/p>","protected":false},"excerpt":{"rendered":"<p>La Comisi\u00f3n de Integridad Gubernamental y Cumplimiento Normativo de la DIGEPRES reafirma cada a\u00f1o la importancia de fortalecer la integridad, transparencia, valores y cultura de responsabilidad institucional Con el lema \u201cEl Desarrollo est\u00e1 en la Integridad\u201d, la Comisi\u00f3n de Integridad Gubernamental y Cumplimiento Normativo -CIGCN- de la Direcci\u00f3n General de Presupuesto, concluy\u00f3 con \u00e9xito la Semana de la \u00c9tica DIGEPRES con el prop\u00f3sito de fomentar y fortalecer los valores y la \u00e9tica dentro de la instituci\u00f3n presupuestaria. En la apertura de la Semana de la \u00c9tica DIGEPRES, las palabras de bienvenida estuvieron a cargo de Lidia Castillo, representante del grupo ocasional del grupo ocupacional V y de Paola Chaljub, encargada del Departamento de Comunicaciones, quienes indistintamente destacaron la importancia de la actividad y motivaron a los colaboradores a seguir el cumplimiento de cada normativa y apoyar las acciones dentro del marco de la conmemoraci\u00f3n del D\u00eda Nacional de la \u00c9tica Ciudadana. La CIGCN celebr\u00f3 la Semana de la \u00c9tica incluyendo dentro de su amplio programa la instalaci\u00f3n del \u201cTr\u00facalo de Valores\u201d, la puesta en funcionamiento del Buz\u00f3n de Denuncia Ciudadana, la din\u00e1mica \u201cCada Decisi\u00f3n Cuenta\u201d dirigido al personal de Grupos Ocupacionales I y II, y cerrando con un Cinef\u00f3rum. Las jornadas de actividades impulsadas por la CIGCN abordan temas claves como prevenci\u00f3n de la corrupci\u00f3n, fortalecimiento del cumplimiento normativo y promoci\u00f3n de buenas pr\u00e1cticas en el servicio p\u00fablico, todo dentro de un enfoque inclusivo y participativo. La Semana de la \u00c9tica DIGEPRES se consolida cada a\u00f1o como un espacio que fortalece la integridad, transparencia, los valores, cultura de responsabilidad, bien com\u00fan, combate a la corrupci\u00f3n y mejorar la confianza en la instituci\u00f3n. Con esta iniciativa, Presupuesto reafirma su compromiso de continuar impulsando acciones y pol\u00edticas que fortalezcan la \u00e9tica p\u00fablica y la construcci\u00f3n de una sociedad m\u00e1s justa, fortalecimiento institucional y construcci\u00f3n de ciudadan\u00eda. DIGEPRES bajo el liderazgo de la Direcci\u00f3n General de \u00c9tica e Integridad Gubernamental\u00a0DIGEIG, conform\u00f3 su Comisi\u00f3n de Integridad Gubernamental y Cumplimiento Normativo\u00a0(CIGCN)\u00a0en cumplimiento con el Decreto No. 791-21, que declara de alta prioridad nacional el proceso de implementaci\u00f3n y elecci\u00f3n de las Comisiones de Integridad Gubernamental y Cumplimiento Normativo\u00a0(CIGCN)\u00a0en todas las instituciones p\u00fablicas. La Semana de la \u00c9tica DIGEPRES con la participaci\u00f3n de director de la Direcci\u00f3n General de Presupuesto, Jos\u00e9 Rijo Presbot; Iv\u00e1n Ram\u00edrez, subdirector; encargados, t\u00e9cnicos y colaborados de Presupuesto. El despliegue de actividades impulsadas por la CIGCN de la DIGEPRES, en el marco del D\u00eda Nacional de la \u00c9tica Ciudadana, busca, adem\u00e1s, sumarse a las acciones impulsadas por la Direcci\u00f3n General de \u00c9tica e Integridad Gubernamental\u00a0(DIGEIG) y honrar la memoria hist\u00f3rica y legado de Ulises Francisco Espaillat, estadista dominicano, decimonoveno presidente del pa\u00eds s\u00edmbolo del bien com\u00fan y la \u00e9tica ciudadana.<\/p>","protected":false},"author":2,"featured_media":44709,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[],"class_list":["post-44717","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-institucionales"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Presupuesto cierra la Semana de la \u00c9tica promoviendo pr\u00e1cticas.<\/title>\n<meta name=\"description\" content=\"Presupuesto cierra la Semana de la \u00c9tica La Comisi\u00f3n de Integridad Gubernamental y Cumplimiento Normativo de la DIGEPRES reafirma cada a\u00f1o...\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/digepres.gob.do\/en\/presupuesto-cierra-la-semana-de-la-etica-promoviendo-buenas-practicas-en-el-servicio-publico-2\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Presupuesto cierra la Semana de la \u00c9tica promoviendo pr\u00e1cticas.\" \/>\n<meta property=\"og:description\" content=\"Presupuesto cierra la Semana de la \u00c9tica La Comisi\u00f3n de Integridad Gubernamental y Cumplimiento Normativo de la DIGEPRES reafirma cada a\u00f1o...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/digepres.gob.do\/en\/presupuesto-cierra-la-semana-de-la-etica-promoviendo-buenas-practicas-en-el-servicio-publico-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Direcci\u00f3n General de Presupuesto - Rep\u00fablica Dominicana\" \/>\n<meta property=\"article:published_time\" content=\"2026-05-01T19:44:58+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-06-01T15:53:55+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/digepres.gob.do\/wp-content\/uploads\/2026\/05\/WhatsApp-Image-2026-05-01-at-3.49.46-PM.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1706\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Pablo Paez\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Pablo Paez\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/digepres.gob.do\\\/presupuesto-cierra-la-semana-de-la-etica-promoviendo-buenas-practicas-en-el-servicio-publico-2\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/digepres.gob.do\\\/presupuesto-cierra-la-semana-de-la-etica-promoviendo-buenas-practicas-en-el-servicio-publico-2\\\/\"},\"author\":{\"name\":\"Pablo Paez\",\"@id\":\"https:\\\/\\\/digepres.gob.do\\\/#\\\/schema\\\/person\\\/f6f6885c1078d1d53221d15413ab38b5\"},\"headline\":\"Presupuesto cierra la Semana de la \u00c9tica promoviendo buenas pr\u00e1cticas en el servicio p\u00fablico\",\"datePublished\":\"2026-05-01T19:44:58+00:00\",\"dateModified\":\"2026-06-01T15:53:55+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/digepres.gob.do\\\/presupuesto-cierra-la-semana-de-la-etica-promoviendo-buenas-practicas-en-el-servicio-publico-2\\\/\"},\"wordCount\":516,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/digepres.gob.do\\\/presupuesto-cierra-la-semana-de-la-etica-promoviendo-buenas-practicas-en-el-servicio-publico-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/digepres.gob.do\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/WhatsApp-Image-2026-05-01-at-3.49.46-PM.jpeg\",\"articleSection\":[\"Institucionales\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/digepres.gob.do\\\/presupuesto-cierra-la-semana-de-la-etica-promoviendo-buenas-practicas-en-el-servicio-publico-2\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/digepres.gob.do\\\/presupuesto-cierra-la-semana-de-la-etica-promoviendo-buenas-practicas-en-el-servicio-publico-2\\\/\",\"url\":\"https:\\\/\\\/digepres.gob.do\\\/presupuesto-cierra-la-semana-de-la-etica-promoviendo-buenas-practicas-en-el-servicio-publico-2\\\/\",\"name\":\"Presupuesto cierra la Semana de la \u00c9tica promoviendo pr\u00e1cticas.\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/digepres.gob.do\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/digepres.gob.do\\\/presupuesto-cierra-la-semana-de-la-etica-promoviendo-buenas-practicas-en-el-servicio-publico-2\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/digepres.gob.do\\\/presupuesto-cierra-la-semana-de-la-etica-promoviendo-buenas-practicas-en-el-servicio-publico-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/digepres.gob.do\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/WhatsApp-Image-2026-05-01-at-3.49.46-PM.jpeg\",\"datePublished\":\"2026-05-01T19:44:58+00:00\",\"dateModified\":\"2026-06-01T15:53:55+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/digepres.gob.do\\\/#\\\/schema\\\/person\\\/f6f6885c1078d1d53221d15413ab38b5\"},\"description\":\"Presupuesto cierra la Semana de la \u00c9tica La Comisi\u00f3n de Integridad Gubernamental y Cumplimiento Normativo de la DIGEPRES reafirma cada a\u00f1o...\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/digepres.gob.do\\\/presupuesto-cierra-la-semana-de-la-etica-promoviendo-buenas-practicas-en-el-servicio-publico-2\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/digepres.gob.do\\\/presupuesto-cierra-la-semana-de-la-etica-promoviendo-buenas-practicas-en-el-servicio-publico-2\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/digepres.gob.do\\\/presupuesto-cierra-la-semana-de-la-etica-promoviendo-buenas-practicas-en-el-servicio-publico-2\\\/#primaryimage\",\"url\":\"https:\\\/\\\/digepres.gob.do\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/WhatsApp-Image-2026-05-01-at-3.49.46-PM.jpeg\",\"contentUrl\":\"https:\\\/\\\/digepres.gob.do\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/WhatsApp-Image-2026-05-01-at-3.49.46-PM.jpeg\",\"width\":2560,\"height\":1706,\"caption\":\"Presupuesto cierra la Semana\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/digepres.gob.do\\\/presupuesto-cierra-la-semana-de-la-etica-promoviendo-buenas-practicas-en-el-servicio-publico-2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/digepres.gob.do\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Presupuesto cierra la Semana de la \u00c9tica promoviendo buenas pr\u00e1cticas en el servicio p\u00fablico\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/digepres.gob.do\\\/#website\",\"url\":\"https:\\\/\\\/digepres.gob.do\\\/\",\"name\":\"Direcci\u00f3n General de Presupuesto - Rep\u00fablica Dominicana\",\"description\":\"Somos el \u00d3rgano Rector del Sistema Presupuestario Dominicano por mandato de la Ley 423-06.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/digepres.gob.do\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/digepres.gob.do\\\/#\\\/schema\\\/person\\\/f6f6885c1078d1d53221d15413ab38b5\",\"name\":\"Pablo Paez\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e9d364ce257be032b8adf031185529d2677ad33d9298b62704d967cd574fa801?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e9d364ce257be032b8adf031185529d2677ad33d9298b62704d967cd574fa801?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e9d364ce257be032b8adf031185529d2677ad33d9298b62704d967cd574fa801?s=96&d=mm&r=g\",\"caption\":\"Pablo Paez\"},\"url\":\"https:\\\/\\\/digepres.gob.do\\\/en\\\/author\\\/ppaez\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Presupuesto cierra la Semana de la \u00c9tica promoviendo pr\u00e1cticas.","description":"Presupuesto cierra la Semana de la \u00c9tica La Comisi\u00f3n de Integridad Gubernamental y Cumplimiento Normativo de la DIGEPRES reafirma cada a\u00f1o...","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/digepres.gob.do\/en\/presupuesto-cierra-la-semana-de-la-etica-promoviendo-buenas-practicas-en-el-servicio-publico-2\/","og_locale":"en_US","og_type":"article","og_title":"Presupuesto cierra la Semana de la \u00c9tica promoviendo pr\u00e1cticas.","og_description":"Presupuesto cierra la Semana de la \u00c9tica La Comisi\u00f3n de Integridad Gubernamental y Cumplimiento Normativo de la DIGEPRES reafirma cada a\u00f1o...","og_url":"https:\/\/digepres.gob.do\/en\/presupuesto-cierra-la-semana-de-la-etica-promoviendo-buenas-practicas-en-el-servicio-publico-2\/","og_site_name":"Direcci\u00f3n General de Presupuesto - Rep\u00fablica Dominicana","article_published_time":"2026-05-01T19:44:58+00:00","article_modified_time":"2026-06-01T15:53:55+00:00","og_image":[{"width":2560,"height":1706,"url":"https:\/\/digepres.gob.do\/wp-content\/uploads\/2026\/05\/WhatsApp-Image-2026-05-01-at-3.49.46-PM.jpeg","type":"image\/jpeg"}],"author":"Pablo Paez","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Pablo Paez","Est. reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/digepres.gob.do\/presupuesto-cierra-la-semana-de-la-etica-promoviendo-buenas-practicas-en-el-servicio-publico-2\/#article","isPartOf":{"@id":"https:\/\/digepres.gob.do\/presupuesto-cierra-la-semana-de-la-etica-promoviendo-buenas-practicas-en-el-servicio-publico-2\/"},"author":{"name":"Pablo Paez","@id":"https:\/\/digepres.gob.do\/#\/schema\/person\/f6f6885c1078d1d53221d15413ab38b5"},"headline":"Presupuesto cierra la Semana de la \u00c9tica promoviendo buenas pr\u00e1cticas en el servicio p\u00fablico","datePublished":"2026-05-01T19:44:58+00:00","dateModified":"2026-06-01T15:53:55+00:00","mainEntityOfPage":{"@id":"https:\/\/digepres.gob.do\/presupuesto-cierra-la-semana-de-la-etica-promoviendo-buenas-practicas-en-el-servicio-publico-2\/"},"wordCount":516,"commentCount":0,"image":{"@id":"https:\/\/digepres.gob.do\/presupuesto-cierra-la-semana-de-la-etica-promoviendo-buenas-practicas-en-el-servicio-publico-2\/#primaryimage"},"thumbnailUrl":"https:\/\/digepres.gob.do\/wp-content\/uploads\/2026\/05\/WhatsApp-Image-2026-05-01-at-3.49.46-PM.jpeg","articleSection":["Institucionales"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/digepres.gob.do\/presupuesto-cierra-la-semana-de-la-etica-promoviendo-buenas-practicas-en-el-servicio-publico-2\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/digepres.gob.do\/presupuesto-cierra-la-semana-de-la-etica-promoviendo-buenas-practicas-en-el-servicio-publico-2\/","url":"https:\/\/digepres.gob.do\/presupuesto-cierra-la-semana-de-la-etica-promoviendo-buenas-practicas-en-el-servicio-publico-2\/","name":"Presupuesto cierra la Semana de la \u00c9tica promoviendo pr\u00e1cticas.","isPartOf":{"@id":"https:\/\/digepres.gob.do\/#website"},"primaryImageOfPage":{"@id":"https:\/\/digepres.gob.do\/presupuesto-cierra-la-semana-de-la-etica-promoviendo-buenas-practicas-en-el-servicio-publico-2\/#primaryimage"},"image":{"@id":"https:\/\/digepres.gob.do\/presupuesto-cierra-la-semana-de-la-etica-promoviendo-buenas-practicas-en-el-servicio-publico-2\/#primaryimage"},"thumbnailUrl":"https:\/\/digepres.gob.do\/wp-content\/uploads\/2026\/05\/WhatsApp-Image-2026-05-01-at-3.49.46-PM.jpeg","datePublished":"2026-05-01T19:44:58+00:00","dateModified":"2026-06-01T15:53:55+00:00","author":{"@id":"https:\/\/digepres.gob.do\/#\/schema\/person\/f6f6885c1078d1d53221d15413ab38b5"},"description":"Presupuesto cierra la Semana de la \u00c9tica La Comisi\u00f3n de Integridad Gubernamental y Cumplimiento Normativo de la DIGEPRES reafirma cada a\u00f1o...","breadcrumb":{"@id":"https:\/\/digepres.gob.do\/presupuesto-cierra-la-semana-de-la-etica-promoviendo-buenas-practicas-en-el-servicio-publico-2\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/digepres.gob.do\/presupuesto-cierra-la-semana-de-la-etica-promoviendo-buenas-practicas-en-el-servicio-publico-2\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/digepres.gob.do\/presupuesto-cierra-la-semana-de-la-etica-promoviendo-buenas-practicas-en-el-servicio-publico-2\/#primaryimage","url":"https:\/\/digepres.gob.do\/wp-content\/uploads\/2026\/05\/WhatsApp-Image-2026-05-01-at-3.49.46-PM.jpeg","contentUrl":"https:\/\/digepres.gob.do\/wp-content\/uploads\/2026\/05\/WhatsApp-Image-2026-05-01-at-3.49.46-PM.jpeg","width":2560,"height":1706,"caption":"Presupuesto cierra la Semana"},{"@type":"BreadcrumbList","@id":"https:\/\/digepres.gob.do\/presupuesto-cierra-la-semana-de-la-etica-promoviendo-buenas-practicas-en-el-servicio-publico-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/digepres.gob.do\/"},{"@type":"ListItem","position":2,"name":"Presupuesto cierra la Semana de la \u00c9tica promoviendo buenas pr\u00e1cticas en el servicio p\u00fablico"}]},{"@type":"WebSite","@id":"https:\/\/digepres.gob.do\/#website","url":"https:\/\/digepres.gob.do\/","name":"Direcci\u00f3n General de Presupuesto - Rep\u00fablica Dominicana","description":"Somos el \u00d3rgano Rector del Sistema Presupuestario Dominicano por mandato de la Ley 423-06.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/digepres.gob.do\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/digepres.gob.do\/#\/schema\/person\/f6f6885c1078d1d53221d15413ab38b5","name":"Pablo Paez","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/e9d364ce257be032b8adf031185529d2677ad33d9298b62704d967cd574fa801?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/e9d364ce257be032b8adf031185529d2677ad33d9298b62704d967cd574fa801?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/e9d364ce257be032b8adf031185529d2677ad33d9298b62704d967cd574fa801?s=96&d=mm&r=g","caption":"Pablo Paez"},"url":"https:\/\/digepres.gob.do\/en\/author\/ppaez\/"}]}},"_links":{"self":[{"href":"https:\/\/digepres.gob.do\/en\/wp-json\/wp\/v2\/posts\/44717","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/digepres.gob.do\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/digepres.gob.do\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/digepres.gob.do\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/digepres.gob.do\/en\/wp-json\/wp\/v2\/comments?post=44717"}],"version-history":[{"count":2,"href":"https:\/\/digepres.gob.do\/en\/wp-json\/wp\/v2\/posts\/44717\/revisions"}],"predecessor-version":[{"id":44890,"href":"https:\/\/digepres.gob.do\/en\/wp-json\/wp\/v2\/posts\/44717\/revisions\/44890"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/digepres.gob.do\/en\/wp-json\/wp\/v2\/media\/44709"}],"wp:attachment":[{"href":"https:\/\/digepres.gob.do\/en\/wp-json\/wp\/v2\/media?parent=44717"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/digepres.gob.do\/en\/wp-json\/wp\/v2\/categories?post=44717"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/digepres.gob.do\/en\/wp-json\/wp\/v2\/tags?post=44717"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}