
{"id":43469,"date":"2025-11-25T15:52:52","date_gmt":"2025-11-25T19:52:52","guid":{"rendered":"https:\/\/www.digepres.gob.do\/?p=41040"},"modified":"2026-02-18T15:14:58","modified_gmt":"2026-02-18T19:14:58","slug":"digepres-realiza-encuentro-ciudadano-con-jovenes-y-adultos-con-discapacidad-y-neurodiversidad","status":"publish","type":"post","link":"https:\/\/digepres.gob.do\/en\/digepres-realiza-encuentro-ciudadano-con-jovenes-y-adultos-con-discapacidad-y-neurodiversidad\/","title":{"rendered":"DIGEPRES realiza Encuentro Ciudadano con j\u00f3venes y adultos con discapacidad y neurodiversidad"},"content":{"rendered":"<p class=\"wp-block-paragraph\"><em>\u00a0La actividad responde a una solicitud de la consultora ABRAZA para el programa \u201cPr\u00e1cticas de empleo Inclusivo\u201d y con el apoyo de la Universidad Nacional Pedro Henr\u00edquez Ure\u00f1a <a href=\"https:\/\/unphu.edu.do\/\" type=\"link\" id=\"https:\/\/unphu.edu.do\/\">(UNPHU)<\/a> <\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">The <a href=\"https:\/\/digepres.gob.do\/en\/\" type=\"link\" id=\"https:\/\/www.digepres.gob.do\/\">General Budget Directorate<\/a> <a href=\"https:\/\/www.instagram.com\/digepresrd\/\" type=\"link\" id=\"https:\/\/www.instagram.com\/digepresrd\/\">(DIGEPRES)<\/a> realiz\u00f3 un Encuentro Ciudadano para socializar aspectos del Presupuesto General del Estado<a href=\"https:\/\/digepres.gob.do\/en\/presupuesto\/gobierno-general-nacional\/proyecto-de-ley-de-presupuesto-2026\/\" type=\"link\" id=\"https:\/\/www.digepres.gob.do\/presupuesto\/gobierno-general-nacional\/proyecto-de-ley-de-presupuesto-2026\/\"> (PGE)<\/a> dirigido a j\u00f3venes y adultos que integran el programa \u201cPr\u00e1cticas de empleo Inclusivo\u201d, iniciativa de la consultora ABRAZA, que cuenta con el apoyo de la Universidad Nacional Pedro Henr\u00edquez Ure\u00f1a <a href=\"https:\/\/unphu.edu.do\/\" type=\"link\" id=\"https:\/\/unphu.edu.do\/\">(UNPHU)<\/a>, y que busca capacitar y abrir espacios laborales a personas adultas con discapacidad y neurodiversidad.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Las palabras de introducci\u00f3n al evento estuvieron a cargo de Rossana Santana, directora ejecutiva de ABRAZA, que al dar las palabras de bienvenida agradeci\u00f3 a <a href=\"https:\/\/www.instagram.com\/digepresrd\/\" type=\"link\" id=\"https:\/\/www.instagram.com\/digepresrd\/\">DIGEPRES<\/a> y al Consejo de Nacional de Discapacidad <a href=\"https:\/\/conadis.gob.do\/\" type=\"link\" id=\"https:\/\/conadis.gob.do\/\">(CONADIS)<\/a> por apoyar y reforzar las acciones de inclusi\u00f3n en la sociedad dominicana.<\/p>\n\n\n\n<figure class=\"wp-block-image alignright size-full is-resized\"><img fetchpriority=\"high\" decoding=\"async\" width=\"700\" height=\"466\" src=\"https:\/\/digepres.gob.do\/wp-content\/uploads\/2025\/11\/WhatsApp-Image-2025-11-25-at-1.10.30-PM-1-700x466-1.jpeg\" alt=\"DIGEPRES realiza Encuentro Ciudadano \" class=\"wp-image-43491\" style=\"width:362px;height:auto\" srcset=\"https:\/\/digepres.gob.do\/wp-content\/uploads\/2025\/11\/WhatsApp-Image-2025-11-25-at-1.10.30-PM-1-700x466-1.jpeg 700w, https:\/\/digepres.gob.do\/wp-content\/uploads\/2025\/11\/WhatsApp-Image-2025-11-25-at-1.10.30-PM-1-700x466-1-300x200.jpeg 300w, https:\/\/digepres.gob.do\/wp-content\/uploads\/2025\/11\/WhatsApp-Image-2025-11-25-at-1.10.30-PM-1-700x466-1-18x12.jpeg 18w\" sizes=\"(max-width: 700px) 100vw, 700px\" \/><\/figure>\n\n\n\n<div class=\"wp-block-image\"><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">En la actividad Rafael Jovine, director de Estudios Econ\u00f3micos y Seguimiento Financiero de Presupuesto, y facilitador del evento, agradeci\u00f3 a la alta casa de estudios por la invitaci\u00f3n pasando a presentar y explicar de forma llana aspectos nodales del<a href=\"https:\/\/digepres.gob.do\/en\/presupuesto\/gobierno-general-nacional\/proyecto-de-ley-de-presupuesto-2026\/\" type=\"link\" id=\"https:\/\/www.digepres.gob.do\/presupuesto\/gobierno-general-nacional\/proyecto-de-ley-de-presupuesto-2026\/\"> PGE<\/a>, partiendo de los ingresos, gastos, recaudaciones, servicios p\u00fablicos y obras a ejecutar por el Gobierno en todo el territorio nacional. <em>\u201cEl Presupuesto General del Estado en palabras sencillas estima los ingresos y gastos del gobierno en todo un a\u00f1o\u201d<\/em>, explic\u00f3 Jovine a los participantes. Asimismo, indic\u00f3 que el presupuesto tiene la misma funcionalidad si aplicamos sus criterios en una casa, empresa o todo un pa\u00eds.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Jovine al dirigirse a los presentes present\u00f3 las herramientas ciudadanas que permiten cerrar brechas entre las instituciones p\u00fablicas y la gente. El economista tambi\u00e9n mostr\u00f3 las v\u00edas de acceso a las informaciones compiladas en el portal Digepres,gob.do, indicado paso a paso los procesos de b\u00fasquedas para que los ciudadanos tengan un mayor conocimiento de la localizaci\u00f3n de la informaci\u00f3n que es de car\u00e1cter p\u00fablico.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Como parte de las acciones present\u00f3 los accesos a videos interactivos, encuentros ciudadanos, documentos y reportes que muestran el estado de las finanzas p\u00fablicas y el portal Presupuesto Ciudadano, que resume los cinco tomos del <a href=\"https:\/\/digepres.gob.do\/en\/presupuesto\/gobierno-general-nacional\/proyecto-de-ley-de-presupuesto-2026\/\" type=\"link\" id=\"https:\/\/www.digepres.gob.do\/presupuesto\/gobierno-general-nacional\/proyecto-de-ley-de-presupuesto-2026\/\">PGE<\/a> de manera m\u00e1s gr\u00e1fica y sencilla.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En la actividad educativa particip\u00f3 una representaci\u00f3n de Presupuesto que estuvo integrada por David Cana\u00e1n, encargado del Departamento de Recursos Humanos de Presupuesto; Karla Ure\u00f1a, encargada del departamento de Planificaci\u00f3n y Desarrollo; Laura V. De la Cruz, encargada de la divisi\u00f3n de Calidad en la Gesti\u00f3n; Airon Fern\u00e1ndez, especialistas de Estudios Econ\u00f3micos; Bryan Alexis Thompson P\u00e9rez, analista de Calidad en la Gesti\u00f3n; Raquel Mart\u00ednez, analista de Calidad en la Gesti\u00f3n; Awilda Polanco, encargada de la divisi\u00f3n de Desarrollo Institucional y Amanda Hilario, t\u00e9cnico administrativo de Planificaci\u00f3n y Desarrollo.<\/p>\n\n\n\n<figure class=\"wp-block-image alignleft size-full is-resized\"><img decoding=\"async\" width=\"700\" height=\"466\" src=\"https:\/\/digepres.gob.do\/wp-content\/uploads\/2025\/11\/WhatsApp-Image-2025-11-25-at-1.10.31-PM-700x466-1.jpeg\" alt=\"\" class=\"wp-image-43492\" style=\"width:404px;height:auto\" srcset=\"https:\/\/digepres.gob.do\/wp-content\/uploads\/2025\/11\/WhatsApp-Image-2025-11-25-at-1.10.31-PM-700x466-1.jpeg 700w, https:\/\/digepres.gob.do\/wp-content\/uploads\/2025\/11\/WhatsApp-Image-2025-11-25-at-1.10.31-PM-700x466-1-300x200.jpeg 300w, https:\/\/digepres.gob.do\/wp-content\/uploads\/2025\/11\/WhatsApp-Image-2025-11-25-at-1.10.31-PM-700x466-1-18x12.jpeg 18w\" sizes=\"(max-width: 700px) 100vw, 700px\" \/><\/figure>\n\n\n\n<div class=\"wp-block-image\"><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">El contenido del encuentro gir\u00f3 en presentar conceptos del <a href=\"https:\/\/digepres.gob.do\/en\/presupuesto\/gobierno-general-nacional\/proyecto-de-ley-de-presupuesto-2026\/\" type=\"link\" id=\"https:\/\/www.digepres.gob.do\/presupuesto\/gobierno-general-nacional\/proyecto-de-ley-de-presupuesto-2026\/\">PGE<\/a>, de d\u00f3nde viene y en qu\u00e9 se gasta, c\u00f3mo consultar a trav\u00e9s del portal, herramientas ciudadanas y participaci\u00f3n social. En la actividad se dedic\u00f3 un espacio de micr\u00f3fono abierto para responder preguntas de los participantes.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La actividad cont\u00f3 adem\u00e1s con representantes del Consejo Nacional de Discapacidad\u00a0<a href=\"https:\/\/conadis.gob.do\/\" type=\"link\" id=\"https:\/\/conadis.gob.do\/\">(CONADIS)<\/a>, de la consultora ABRAZA y la Universidad Nacional Pedro Henr\u00edquez Ure\u00f1a <a href=\"https:\/\/unphu.edu.do\/\" type=\"link\" id=\"https:\/\/unphu.edu.do\/\">(UNPHU)<\/a>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Sobre ABRAZA<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Encuentro Ciudadano es una iniciativa de la actual gesti\u00f3n presupuestaria que encabeza Jos\u00e9 Rijo Presbot, que busca impulsar el di\u00e1logo abierto entre Presupuesto y los distintos sectores clave de la sociedad civil, con el objetivo de procurar la participaci\u00f3n ciudadana, el control social y eficientizar las pol\u00edticas p\u00fablicas y programas que se contemplan en el <a href=\"https:\/\/digepres.gob.do\/en\/presupuesto\/gobierno-general-nacional\/proyecto-de-ley-de-presupuesto-2026\/\" type=\"link\" id=\"https:\/\/www.digepres.gob.do\/presupuesto\/gobierno-general-nacional\/proyecto-de-ley-de-presupuesto-2026\/\">PGE.<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">ABRAZA&nbsp;es una instituci\u00f3n con m\u00e1s de 10 a\u00f1os de experiencia en responsabilidad social. Dentro de sus prioridades siempre la inclusi\u00f3n de personas con discapacidad y neurodiversidad, tanto desde la perspectiva empresarial como de las Asociaciones Sin Fines de Lucro (ASFL), apoyado en la gesti\u00f3n de alianzas estrat\u00e9gicas para la inclusi\u00f3n laboral a nivel corporativo.<\/p>","protected":false},"excerpt":{"rendered":"<p>\u00a0La actividad responde a una solicitud de la consultora ABRAZA para el programa \u201cPr\u00e1cticas de empleo Inclusivo\u201d y con el apoyo de la Universidad Nacional Pedro Henr\u00edquez Ure\u00f1a (UNPHU) La Direcci\u00f3n General de Presupuesto (DIGEPRES) realiz\u00f3 un Encuentro Ciudadano para socializar aspectos del Presupuesto General del Estado (PGE) dirigido a j\u00f3venes y adultos que integran el programa \u201cPr\u00e1cticas de empleo Inclusivo\u201d, iniciativa de la consultora ABRAZA, que cuenta con el apoyo de la Universidad Nacional Pedro Henr\u00edquez Ure\u00f1a (UNPHU), y que busca capacitar y abrir espacios laborales a personas adultas con discapacidad y neurodiversidad. Las palabras de introducci\u00f3n al evento estuvieron a cargo de Rossana Santana, directora ejecutiva de ABRAZA, que al dar las palabras de bienvenida agradeci\u00f3 a DIGEPRES y al Consejo de Nacional de Discapacidad (CONADIS) por apoyar y reforzar las acciones de inclusi\u00f3n en la sociedad dominicana. En la actividad Rafael Jovine, director de Estudios Econ\u00f3micos y Seguimiento Financiero de Presupuesto, y facilitador del evento, agradeci\u00f3 a la alta casa de estudios por la invitaci\u00f3n pasando a presentar y explicar de forma llana aspectos nodales del PGE, partiendo de los ingresos, gastos, recaudaciones, servicios p\u00fablicos y obras a ejecutar por el Gobierno en todo el territorio nacional. \u201cEl Presupuesto General del Estado en palabras sencillas estima los ingresos y gastos del gobierno en todo un a\u00f1o\u201d, explic\u00f3 Jovine a los participantes. Asimismo, indic\u00f3 que el presupuesto tiene la misma funcionalidad si aplicamos sus criterios en una casa, empresa o todo un pa\u00eds. Jovine al dirigirse a los presentes present\u00f3 las herramientas ciudadanas que permiten cerrar brechas entre las instituciones p\u00fablicas y la gente. El economista tambi\u00e9n mostr\u00f3 las v\u00edas de acceso a las informaciones compiladas en el portal Digepres,gob.do, indicado paso a paso los procesos de b\u00fasquedas para que los ciudadanos tengan un mayor conocimiento de la localizaci\u00f3n de la informaci\u00f3n que es de car\u00e1cter p\u00fablico. Como parte de las acciones present\u00f3 los accesos a videos interactivos, encuentros ciudadanos, documentos y reportes que muestran el estado de las finanzas p\u00fablicas y el portal Presupuesto Ciudadano, que resume los cinco tomos del PGE de manera m\u00e1s gr\u00e1fica y sencilla. En la actividad educativa particip\u00f3 una representaci\u00f3n de Presupuesto que estuvo integrada por David Cana\u00e1n, encargado del Departamento de Recursos Humanos de Presupuesto; Karla Ure\u00f1a, encargada del departamento de Planificaci\u00f3n y Desarrollo; Laura V. De la Cruz, encargada de la divisi\u00f3n de Calidad en la Gesti\u00f3n; Airon Fern\u00e1ndez, especialistas de Estudios Econ\u00f3micos; Bryan Alexis Thompson P\u00e9rez, analista de Calidad en la Gesti\u00f3n; Raquel Mart\u00ednez, analista de Calidad en la Gesti\u00f3n; Awilda Polanco, encargada de la divisi\u00f3n de Desarrollo Institucional y Amanda Hilario, t\u00e9cnico administrativo de Planificaci\u00f3n y Desarrollo. El contenido del encuentro gir\u00f3 en presentar conceptos del PGE, de d\u00f3nde viene y en qu\u00e9 se gasta, c\u00f3mo consultar a trav\u00e9s del portal, herramientas ciudadanas y participaci\u00f3n social. En la actividad se dedic\u00f3 un espacio de micr\u00f3fono abierto para responder preguntas de los participantes. La actividad cont\u00f3 adem\u00e1s con representantes del Consejo Nacional de Discapacidad\u00a0(CONADIS), de la consultora ABRAZA y la Universidad Nacional Pedro Henr\u00edquez Ure\u00f1a (UNPHU). Sobre ABRAZA Encuentro Ciudadano es una iniciativa de la actual gesti\u00f3n presupuestaria que encabeza Jos\u00e9 Rijo Presbot, que busca impulsar el di\u00e1logo abierto entre Presupuesto y los distintos sectores clave de la sociedad civil, con el objetivo de procurar la participaci\u00f3n ciudadana, el control social y eficientizar las pol\u00edticas p\u00fablicas y programas que se contemplan en el PGE. ABRAZA&nbsp;es una instituci\u00f3n con m\u00e1s de 10 a\u00f1os de experiencia en responsabilidad social. Dentro de sus prioridades siempre la inclusi\u00f3n de personas con discapacidad y neurodiversidad, tanto desde la perspectiva empresarial como de las Asociaciones Sin Fines de Lucro (ASFL), apoyado en la gesti\u00f3n de alianzas estrat\u00e9gicas para la inclusi\u00f3n laboral a nivel corporativo.<\/p>","protected":false},"author":2,"featured_media":43490,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[],"class_list":["post-43469","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-institucionales"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>DIGEPRES realiza Encuentro Ciudadano - Presupuesto<\/title>\n<meta name=\"description\" content=\"DIGEPRES realiza Encuentro Ciudadano con j\u00f3venes y adultos con discapacidad y neurodiversidad: \u00a0La actividad responde a una solicitud...\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/digepres.gob.do\/en\/digepres-realiza-encuentro-ciudadano-con-jovenes-y-adultos-con-discapacidad-y-neurodiversidad\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"DIGEPRES realiza Encuentro Ciudadano - Presupuesto\" \/>\n<meta property=\"og:description\" content=\"DIGEPRES realiza Encuentro Ciudadano con j\u00f3venes y adultos con discapacidad y neurodiversidad: \u00a0La actividad responde a una solicitud...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/digepres.gob.do\/en\/digepres-realiza-encuentro-ciudadano-con-jovenes-y-adultos-con-discapacidad-y-neurodiversidad\/\" \/>\n<meta property=\"og:site_name\" content=\"Direcci\u00f3n General de Presupuesto - Rep\u00fablica Dominicana\" \/>\n<meta property=\"article:published_time\" content=\"2025-11-25T19:52:52+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-02-18T19:14:58+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/digepres.gob.do\/wp-content\/uploads\/2025\/11\/WhatsApp-Image-2025-11-25-at-1.10.30-PM.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1703\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Pablo Paez\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Pablo Paez\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/digepres.gob.do\\\/digepres-realiza-encuentro-ciudadano-con-jovenes-y-adultos-con-discapacidad-y-neurodiversidad\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/digepres.gob.do\\\/digepres-realiza-encuentro-ciudadano-con-jovenes-y-adultos-con-discapacidad-y-neurodiversidad\\\/\"},\"author\":{\"name\":\"Pablo Paez\",\"@id\":\"https:\\\/\\\/digepres.gob.do\\\/#\\\/schema\\\/person\\\/f6f6885c1078d1d53221d15413ab38b5\"},\"headline\":\"DIGEPRES realiza Encuentro Ciudadano con j\u00f3venes y adultos con discapacidad y neurodiversidad\",\"datePublished\":\"2025-11-25T19:52:52+00:00\",\"dateModified\":\"2026-02-18T19:14:58+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/digepres.gob.do\\\/digepres-realiza-encuentro-ciudadano-con-jovenes-y-adultos-con-discapacidad-y-neurodiversidad\\\/\"},\"wordCount\":697,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/digepres.gob.do\\\/digepres-realiza-encuentro-ciudadano-con-jovenes-y-adultos-con-discapacidad-y-neurodiversidad\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/digepres.gob.do\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/WhatsApp-Image-2025-11-25-at-1.10.30-PM.jpeg\",\"articleSection\":[\"Institucionales\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/digepres.gob.do\\\/digepres-realiza-encuentro-ciudadano-con-jovenes-y-adultos-con-discapacidad-y-neurodiversidad\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/digepres.gob.do\\\/digepres-realiza-encuentro-ciudadano-con-jovenes-y-adultos-con-discapacidad-y-neurodiversidad\\\/\",\"url\":\"https:\\\/\\\/digepres.gob.do\\\/digepres-realiza-encuentro-ciudadano-con-jovenes-y-adultos-con-discapacidad-y-neurodiversidad\\\/\",\"name\":\"DIGEPRES realiza Encuentro Ciudadano - Presupuesto\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/digepres.gob.do\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/digepres.gob.do\\\/digepres-realiza-encuentro-ciudadano-con-jovenes-y-adultos-con-discapacidad-y-neurodiversidad\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/digepres.gob.do\\\/digepres-realiza-encuentro-ciudadano-con-jovenes-y-adultos-con-discapacidad-y-neurodiversidad\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/digepres.gob.do\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/WhatsApp-Image-2025-11-25-at-1.10.30-PM.jpeg\",\"datePublished\":\"2025-11-25T19:52:52+00:00\",\"dateModified\":\"2026-02-18T19:14:58+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/digepres.gob.do\\\/#\\\/schema\\\/person\\\/f6f6885c1078d1d53221d15413ab38b5\"},\"description\":\"DIGEPRES realiza Encuentro Ciudadano con j\u00f3venes y adultos con discapacidad y neurodiversidad: \u00a0La actividad responde a una solicitud...\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/digepres.gob.do\\\/digepres-realiza-encuentro-ciudadano-con-jovenes-y-adultos-con-discapacidad-y-neurodiversidad\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/digepres.gob.do\\\/digepres-realiza-encuentro-ciudadano-con-jovenes-y-adultos-con-discapacidad-y-neurodiversidad\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/digepres.gob.do\\\/digepres-realiza-encuentro-ciudadano-con-jovenes-y-adultos-con-discapacidad-y-neurodiversidad\\\/#primaryimage\",\"url\":\"https:\\\/\\\/digepres.gob.do\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/WhatsApp-Image-2025-11-25-at-1.10.30-PM.jpeg\",\"contentUrl\":\"https:\\\/\\\/digepres.gob.do\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/WhatsApp-Image-2025-11-25-at-1.10.30-PM.jpeg\",\"width\":2560,\"height\":1703,\"caption\":\"DIGEPRES realiza Encuentro Ciudadano\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/digepres.gob.do\\\/digepres-realiza-encuentro-ciudadano-con-jovenes-y-adultos-con-discapacidad-y-neurodiversidad\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/digepres.gob.do\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"DIGEPRES realiza Encuentro Ciudadano con j\u00f3venes y adultos con discapacidad y neurodiversidad\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/digepres.gob.do\\\/#website\",\"url\":\"https:\\\/\\\/digepres.gob.do\\\/\",\"name\":\"Direcci\u00f3n General de Presupuesto - Rep\u00fablica Dominicana\",\"description\":\"Somos el \u00d3rgano Rector del Sistema Presupuestario Dominicano por mandato de la Ley 423-06.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/digepres.gob.do\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/digepres.gob.do\\\/#\\\/schema\\\/person\\\/f6f6885c1078d1d53221d15413ab38b5\",\"name\":\"Pablo Paez\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e9d364ce257be032b8adf031185529d2677ad33d9298b62704d967cd574fa801?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e9d364ce257be032b8adf031185529d2677ad33d9298b62704d967cd574fa801?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e9d364ce257be032b8adf031185529d2677ad33d9298b62704d967cd574fa801?s=96&d=mm&r=g\",\"caption\":\"Pablo Paez\"},\"url\":\"https:\\\/\\\/digepres.gob.do\\\/en\\\/author\\\/ppaez\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"DIGEPRES realiza Encuentro Ciudadano - Presupuesto","description":"DIGEPRES realiza Encuentro Ciudadano con j\u00f3venes y adultos con discapacidad y neurodiversidad: \u00a0La actividad responde a una solicitud...","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/digepres.gob.do\/en\/digepres-realiza-encuentro-ciudadano-con-jovenes-y-adultos-con-discapacidad-y-neurodiversidad\/","og_locale":"en_US","og_type":"article","og_title":"DIGEPRES realiza Encuentro Ciudadano - Presupuesto","og_description":"DIGEPRES realiza Encuentro Ciudadano con j\u00f3venes y adultos con discapacidad y neurodiversidad: \u00a0La actividad responde a una solicitud...","og_url":"https:\/\/digepres.gob.do\/en\/digepres-realiza-encuentro-ciudadano-con-jovenes-y-adultos-con-discapacidad-y-neurodiversidad\/","og_site_name":"Direcci\u00f3n General de Presupuesto - Rep\u00fablica Dominicana","article_published_time":"2025-11-25T19:52:52+00:00","article_modified_time":"2026-02-18T19:14:58+00:00","og_image":[{"width":2560,"height":1703,"url":"https:\/\/digepres.gob.do\/wp-content\/uploads\/2025\/11\/WhatsApp-Image-2025-11-25-at-1.10.30-PM.jpeg","type":"image\/jpeg"}],"author":"Pablo Paez","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Pablo Paez","Est. reading time":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/digepres.gob.do\/digepres-realiza-encuentro-ciudadano-con-jovenes-y-adultos-con-discapacidad-y-neurodiversidad\/#article","isPartOf":{"@id":"https:\/\/digepres.gob.do\/digepres-realiza-encuentro-ciudadano-con-jovenes-y-adultos-con-discapacidad-y-neurodiversidad\/"},"author":{"name":"Pablo Paez","@id":"https:\/\/digepres.gob.do\/#\/schema\/person\/f6f6885c1078d1d53221d15413ab38b5"},"headline":"DIGEPRES realiza Encuentro Ciudadano con j\u00f3venes y adultos con discapacidad y neurodiversidad","datePublished":"2025-11-25T19:52:52+00:00","dateModified":"2026-02-18T19:14:58+00:00","mainEntityOfPage":{"@id":"https:\/\/digepres.gob.do\/digepres-realiza-encuentro-ciudadano-con-jovenes-y-adultos-con-discapacidad-y-neurodiversidad\/"},"wordCount":697,"commentCount":0,"image":{"@id":"https:\/\/digepres.gob.do\/digepres-realiza-encuentro-ciudadano-con-jovenes-y-adultos-con-discapacidad-y-neurodiversidad\/#primaryimage"},"thumbnailUrl":"https:\/\/digepres.gob.do\/wp-content\/uploads\/2025\/11\/WhatsApp-Image-2025-11-25-at-1.10.30-PM.jpeg","articleSection":["Institucionales"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/digepres.gob.do\/digepres-realiza-encuentro-ciudadano-con-jovenes-y-adultos-con-discapacidad-y-neurodiversidad\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/digepres.gob.do\/digepres-realiza-encuentro-ciudadano-con-jovenes-y-adultos-con-discapacidad-y-neurodiversidad\/","url":"https:\/\/digepres.gob.do\/digepres-realiza-encuentro-ciudadano-con-jovenes-y-adultos-con-discapacidad-y-neurodiversidad\/","name":"DIGEPRES realiza Encuentro Ciudadano - Presupuesto","isPartOf":{"@id":"https:\/\/digepres.gob.do\/#website"},"primaryImageOfPage":{"@id":"https:\/\/digepres.gob.do\/digepres-realiza-encuentro-ciudadano-con-jovenes-y-adultos-con-discapacidad-y-neurodiversidad\/#primaryimage"},"image":{"@id":"https:\/\/digepres.gob.do\/digepres-realiza-encuentro-ciudadano-con-jovenes-y-adultos-con-discapacidad-y-neurodiversidad\/#primaryimage"},"thumbnailUrl":"https:\/\/digepres.gob.do\/wp-content\/uploads\/2025\/11\/WhatsApp-Image-2025-11-25-at-1.10.30-PM.jpeg","datePublished":"2025-11-25T19:52:52+00:00","dateModified":"2026-02-18T19:14:58+00:00","author":{"@id":"https:\/\/digepres.gob.do\/#\/schema\/person\/f6f6885c1078d1d53221d15413ab38b5"},"description":"DIGEPRES realiza Encuentro Ciudadano con j\u00f3venes y adultos con discapacidad y neurodiversidad: \u00a0La actividad responde a una solicitud...","breadcrumb":{"@id":"https:\/\/digepres.gob.do\/digepres-realiza-encuentro-ciudadano-con-jovenes-y-adultos-con-discapacidad-y-neurodiversidad\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/digepres.gob.do\/digepres-realiza-encuentro-ciudadano-con-jovenes-y-adultos-con-discapacidad-y-neurodiversidad\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/digepres.gob.do\/digepres-realiza-encuentro-ciudadano-con-jovenes-y-adultos-con-discapacidad-y-neurodiversidad\/#primaryimage","url":"https:\/\/digepres.gob.do\/wp-content\/uploads\/2025\/11\/WhatsApp-Image-2025-11-25-at-1.10.30-PM.jpeg","contentUrl":"https:\/\/digepres.gob.do\/wp-content\/uploads\/2025\/11\/WhatsApp-Image-2025-11-25-at-1.10.30-PM.jpeg","width":2560,"height":1703,"caption":"DIGEPRES realiza Encuentro Ciudadano"},{"@type":"BreadcrumbList","@id":"https:\/\/digepres.gob.do\/digepres-realiza-encuentro-ciudadano-con-jovenes-y-adultos-con-discapacidad-y-neurodiversidad\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/digepres.gob.do\/"},{"@type":"ListItem","position":2,"name":"DIGEPRES realiza Encuentro Ciudadano con j\u00f3venes y adultos con discapacidad y neurodiversidad"}]},{"@type":"WebSite","@id":"https:\/\/digepres.gob.do\/#website","url":"https:\/\/digepres.gob.do\/","name":"Direcci\u00f3n General de Presupuesto - Rep\u00fablica Dominicana","description":"Somos el \u00d3rgano Rector del Sistema Presupuestario Dominicano por mandato de la Ley 423-06.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/digepres.gob.do\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/digepres.gob.do\/#\/schema\/person\/f6f6885c1078d1d53221d15413ab38b5","name":"Pablo Paez","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/e9d364ce257be032b8adf031185529d2677ad33d9298b62704d967cd574fa801?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/e9d364ce257be032b8adf031185529d2677ad33d9298b62704d967cd574fa801?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/e9d364ce257be032b8adf031185529d2677ad33d9298b62704d967cd574fa801?s=96&d=mm&r=g","caption":"Pablo Paez"},"url":"https:\/\/digepres.gob.do\/en\/author\/ppaez\/"}]}},"_links":{"self":[{"href":"https:\/\/digepres.gob.do\/en\/wp-json\/wp\/v2\/posts\/43469","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/digepres.gob.do\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/digepres.gob.do\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/digepres.gob.do\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/digepres.gob.do\/en\/wp-json\/wp\/v2\/comments?post=43469"}],"version-history":[{"count":2,"href":"https:\/\/digepres.gob.do\/en\/wp-json\/wp\/v2\/posts\/43469\/revisions"}],"predecessor-version":[{"id":43621,"href":"https:\/\/digepres.gob.do\/en\/wp-json\/wp\/v2\/posts\/43469\/revisions\/43621"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/digepres.gob.do\/en\/wp-json\/wp\/v2\/media\/43490"}],"wp:attachment":[{"href":"https:\/\/digepres.gob.do\/en\/wp-json\/wp\/v2\/media?parent=43469"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/digepres.gob.do\/en\/wp-json\/wp\/v2\/categories?post=43469"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/digepres.gob.do\/en\/wp-json\/wp\/v2\/tags?post=43469"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}