
{"id":43467,"date":"2025-11-06T19:05:34","date_gmt":"2025-11-06T23:05:34","guid":{"rendered":"https:\/\/www.digepres.gob.do\/?p=40934"},"modified":"2026-02-09T12:20:58","modified_gmt":"2026-02-09T16:20:58","slug":"concluye-seminario-internacional-de-presupuesto-publico-y-se-destaca-desempeno-presupuestario-ejemplar-de-rd","status":"publish","type":"post","link":"https:\/\/digepres.gob.do\/en\/concluye-seminario-internacional-de-presupuesto-publico-y-se-destaca-desempeno-presupuestario-ejemplar-de-rd\/","title":{"rendered":"Concluye Seminario Internacional de Presupuesto P\u00fablico y se destaca desempe\u00f1o presupuestario ejemplar de RD"},"content":{"rendered":"<p class=\"wp-block-paragraph\"><em>El seminario cont\u00f3 con m\u00e1s de 500 participantes de 22 pa\u00edses, entre directores de presupuesto, conferencistas y expertos en materia presupuestaria<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Concluy\u00f3 con \u00e9xito el 52 Seminario Internacional de Presupuesto\u00a0P\u00fablico, coordinado por la Direcci\u00f3n General de Presupuesto <a href=\"https:\/\/digepres.gob.do\/en\/\" type=\"link\" id=\"https:\/\/digepres.gob.do\/\">(DIGEPRES)<\/a> y la Asociaci\u00f3n Internacional de Presupuesto P\u00fablico<a href=\"https:\/\/asip.org.ar\/\" type=\"link\" id=\"https:\/\/asip.org.ar\/\"> (ASIP)<\/a>, que reuni\u00f3 a directores de Presupuesto, especialistas de Am\u00e9rica Latina y el Caribe para intercambiar experiencias, innovaciones y pr\u00e1cticas efectivas en la gesti\u00f3n financiera. El evento, que abord\u00f3 el tema \u201cL<em>a geopol\u00edtica internacional y la fiscalidad en tiempos de transformaci\u00f3n global\u201d<\/em>, se llev\u00f3 a cabo del 4 al 6 de noviembre con Rep\u00fablica Dominicana como pa\u00eds sede y anfitri\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El acto de clausura estuvo encabezado por Jos\u00e9 Rijo Presbot, director general de Presupuesto; Jos\u00e9 Luis Araya, director general de Presupuesto Nacional de Costa Rica y presidente del Consejo Directivo de la <a href=\"https:\/\/asip.org.ar\/\" type=\"link\" id=\"https:\/\/asip.org.ar\/\">ASIP<\/a>; y Manoel G\u00f3mez de Lima, presidente del consejo Deliberante de <a href=\"https:\/\/asip.org.ar\/\" type=\"link\" id=\"https:\/\/asip.org.ar\/\">ASIP.<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En las palabras de cierre, Rijo Presbot destac\u00f3 la importancia de fortalecer la cooperaci\u00f3n entre pa\u00edses compartiendo ejercicios y buenas pr\u00e1cticas. <em>\u201cLa Rep\u00fablica Dominicana asume su compromiso con la regi\u00f3n como parte de este esfuerzo de cooperaci\u00f3n permanente<\/em>\u201d, destac\u00f3 el director de Presupuesto y motiv\u00f3 a actuar siempre conforme a la ley y normas presupuestarias.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En tanto que, Jos\u00e9 Luis Araya, presidente del Consejo Directivo de <a href=\"https:\/\/asip.org.ar\/\" type=\"link\" id=\"https:\/\/asip.org.ar\/\">ASIP<\/a>, agradeci\u00f3 al Gobierno dominicano y a la Organizaci\u00f3n para la Cooperaci\u00f3n y el Desarrollo Econ\u00f3micos<a href=\"https:\/\/www.oecd.org\/en.html\" type=\"link\" id=\"https:\/\/www.oecd.org\/en.html\"> (OCDE)<\/a> por su apoyo, exhortando a los miembros a aplicar los conocimientos adquiridos con el prop\u00f3sito de mejorar la gesti\u00f3n p\u00fablica y promover el bienestar ciudadano.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">De su lado, Manoel G\u00f3mes, presidente del Consejo Deliberante de <a href=\"https:\/\/asip.org.ar\/\" type=\"link\" id=\"https:\/\/asip.org.ar\/\">ASIP<\/a>, se sum\u00f3 a las felicitaciones al equipo coordinador del evento por la dedicaci\u00f3n y trabajo durante el Seminario Internacional de Presupuesto P\u00fablico.<\/p>\n\n\n\n<figure class=\"wp-block-image alignright\"><img decoding=\"async\" src=\"https:\/\/digepres.gob.do\/wp-content\/uploads\/2025\/11\/Image-17-300x200.jpg\" alt=\"Concluye Seminario Internacional de\" class=\"wp-image-40936\" title=\"Concluye Seminario Internacional de\"\/><\/figure>\n\n\n\n<div class=\"wp-block-image\"><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">El seminario constituy\u00f3 un espacio de an\u00e1lisis del \u00e1mbito presupuestario y cambios geopol\u00edticos actuales; adem\u00e1s, cont\u00f3 con un amplio programa destinado a conferencias, exposiciones y paneles con oradores expertos en materia econ\u00f3mica del \u00e1mbito local e internacional.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Rafael Jovine, director de Estudios Econ\u00f3micos y Seguimiento Financiero de la <a href=\"https:\/\/digepres.gob.do\/en\/\" type=\"link\" id=\"https:\/\/digepres.gob.do\/\">DIGEPRES<\/a>, quien fungi\u00f3 como presidente de la mesa directiva del Seminario, indic\u00f3 que el encuentro de <a href=\"https:\/\/asip.org.ar\/\" type=\"link\" id=\"https:\/\/asip.org.ar\/\">ASIP<\/a> rescata los retos econ\u00f3micos y geopol\u00edticos que enfrentan los pa\u00edses, y resalt\u00f3 que \u201c<em>el encuentro, promueve el an\u00e1lisis de las circunstancias actuales y sus posibles efectos en la gesti\u00f3n de las finanzas p\u00fablicas\u201d. <\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Buenas pr\u00e1cticas y retos presupuestarios de la regi\u00f3n<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En el 52 Seminario Internacional sobre Presupuesto&nbsp;P\u00fablico las reuniones t\u00e9cnicas, conferencias y reflexiones en su primer d\u00eda abord\u00f3 temas del \u00e1mbito de la geopol\u00edtica internacional, pr\u00e1cticas presupuestarias en salud, presupuesto con enfoque en ni\u00f1ez, presupuesto p\u00fablico en Brasil, avances tecnol\u00f3gicos de los presupuestos, estado de implementaci\u00f3n del presupuesto basado en resultado de los pa\u00edses.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los participantes y oradores tuvieron la oportunidad de discutir sobre la obligaci\u00f3n de los gobiernos de rendir cuentas de inversiones y resultados, enfoque del presupuesto por programas y resultados para garantizar la transparencia y porvenir ciudadano, derechos de la infancia a trav\u00e9s del presupuesto p\u00fablico y gasto en salud, cobertura y calidad sanitaria.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Asimismo, sobre las fluctuaciones econ\u00f3micas, plurianualidad, disciplina fiscal, importancia de la informaci\u00f3n accesible en l\u00ednea para fomento de la transparencia y toma de decisiones y presupuesto por resultado.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Entre los panelistas, se contaron Guillermo Valentino, responsable de la Oficina Nacional de Presupuesto de Argentina; Gavino Severino, oficial de Pol\u00edticas Sociales de UNICEF RD; Camila Vammalle, representante de la Organizaci\u00f3n de Cooperaci\u00f3n y Desarrollo Econ\u00f3micos <a href=\"https:\/\/www.oecd.org\/en.html\" type=\"link\" id=\"https:\/\/www.oecd.org\/en.html\">(OCDE)<\/a>; Clayton Luiz Montes, secretario de Presupuesto Federal de Brasil y Victor Reis de Abriu Calvacante, director de la Secretar\u00eda de Presupuesto Oficial de Brasil.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La Rep\u00fablica Dominicana desarroll\u00f3 un panel con el tema \u201c<em>El Presupuesto como instrumento de transformaci\u00f3n y valor de lo p\u00fablico\u201d<\/em>, a cargo de Mar\u00eda V\u00edctoria Ort\u00edz, encargada del Departamento de Normas y Metodolog\u00edas; Juan Portalat\u00edn, del Departamento de Gesti\u00f3n Financiera de Formulaci\u00f3n y Ejecuci\u00f3n Presupuestaria; Sorangel Gonz\u00e1lez, del Departamento de An\u00e1lisis y Estudios Econ\u00f3micos; Mar\u00eda Jos\u00e9 Castro, de la divisi\u00f3n de Ministerios de Salud P\u00fablica y Asistencia Social y Trabajo de DIGEPRES.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Las exposiciones del panel dominicano se vincularon a t\u00f3picos sobre el presupuesto verde, equidad de g\u00e9nero, gasto p\u00fablico destinado al cambio clim\u00e1tico, la biodiversidad, gesti\u00f3n de desastre, control social y la transparencia del presupuesto de cara al ciudadano, pol\u00edticas presupuestarias dirigidas a la ni\u00f1ez y adolescencia, mejoras del marco fiscal y de gastos prioritarios dentro de la gesti\u00f3n financiera p\u00fablica y el nuevo Sistema Integrado de Gesti\u00f3n Financiera SIGEF 2.0.<\/p>\n\n\n\n<figure class=\"wp-block-image alignright size-full is-resized\"><img fetchpriority=\"high\" decoding=\"async\" width=\"300\" height=\"168\" src=\"http:\/\/digepres.gob.do\/wp-content\/uploads\/2025\/11\/Image-18-300x168-1.jpg\" alt=\"Concluye Seminario Internacional\" class=\"wp-image-43479\" style=\"width:485px;height:auto\" title=\"Concluye Seminario Internacional de\" srcset=\"https:\/\/digepres.gob.do\/wp-content\/uploads\/2025\/11\/Image-18-300x168-1.jpg 300w, https:\/\/digepres.gob.do\/wp-content\/uploads\/2025\/11\/Image-18-300x168-1-18x10.jpg 18w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/figure>\n\n\n\n<div class=\"wp-block-image\"><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Los temas abordados por pa\u00eds por los panelistas giraron sobre el contexto nacional de pol\u00edticas, situaci\u00f3n macroecon\u00f3mica y desaf\u00edos actuales de Argentina, adaptabilidad de Brasil de cara al COVID-19 e importancia de la adaptabilidad del presupuesto p\u00fablico como instrumento de estabilizaci\u00f3n, presupuesto, modelo econ\u00f3mico y plan de desarrollo cubano. Entre los pa\u00edses panelistas estuvieron Argentina, Brasil, Costa Rica, El Salvador, Uruguay, Paraguay, Panam\u00e1, Puerto Rico, Honduras, Rep\u00fablica de Cuba, Rep\u00fablica Dominicana, M\u00e9xico, Guatemala, Colombia, Per\u00fa.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El evento cont\u00f3 con el apoyo y coordinaci\u00f3n de la Asociaci\u00f3n Internacional de Presupuesto P\u00fablico <a href=\"https:\/\/asip.org.ar\/\">(ASIP)<\/a>, de la Organizaci\u00f3n para la Cooperaci\u00f3n y el Desarrollo Econ\u00f3micos <a href=\"https:\/\/www.oecd.org\/en.html\" type=\"link\" id=\"https:\/\/www.oecd.org\/en.html\">(OCDE)<\/a> y la Direcci\u00f3n General de Presupuesto de la Rep\u00fablica Dominicana <a href=\"https:\/\/digepres.gob.do\/en\/\">(DIGEPRES)<\/a>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El evento en su acto inaugural cont\u00f3 con la presencia y palabras centrales del presidente de la Rep\u00fablica Dominicana, Luis Abinader, y con la participaci\u00f3n de funcionarios del \u00e1mbito p\u00fablico, de la cooperaci\u00f3n internacional, representantes miembros de<a href=\"https:\/\/asip.org.ar\/\" type=\"link\" id=\"https:\/\/asip.org.ar\/\"> ASIP<\/a> y m\u00e1s de 500 participantes tanto de Rep\u00fablica Dominicana, Argentina, Brasil, Costa Rica, Paraguay, Uruguay, El Salvador, Guatemala, Colombia, M\u00e9xico, Per\u00fa, Puerto Rico, Panam\u00e1, Chile y otros pa\u00edses de la regi\u00f3n.<\/p>","protected":false},"excerpt":{"rendered":"<p>El seminario cont\u00f3 con m\u00e1s de 500 participantes de 22 pa\u00edses, entre directores de presupuesto, conferencistas y expertos en materia presupuestaria Concluy\u00f3 con \u00e9xito el 52 Seminario Internacional de Presupuesto\u00a0P\u00fablico, coordinado por la Direcci\u00f3n General de Presupuesto (DIGEPRES) y la Asociaci\u00f3n Internacional de Presupuesto P\u00fablico (ASIP), que reuni\u00f3 a directores de Presupuesto, especialistas de Am\u00e9rica Latina y el Caribe para intercambiar experiencias, innovaciones y pr\u00e1cticas efectivas en la gesti\u00f3n financiera. El evento, que abord\u00f3 el tema \u201cLa geopol\u00edtica internacional y la fiscalidad en tiempos de transformaci\u00f3n global\u201d, se llev\u00f3 a cabo del 4 al 6 de noviembre con Rep\u00fablica Dominicana como pa\u00eds sede y anfitri\u00f3n. El acto de clausura estuvo encabezado por Jos\u00e9 Rijo Presbot, director general de Presupuesto; Jos\u00e9 Luis Araya, director general de Presupuesto Nacional de Costa Rica y presidente del Consejo Directivo de la ASIP; y Manoel G\u00f3mez de Lima, presidente del consejo Deliberante de ASIP. En las palabras de cierre, Rijo Presbot destac\u00f3 la importancia de fortalecer la cooperaci\u00f3n entre pa\u00edses compartiendo ejercicios y buenas pr\u00e1cticas. \u201cLa Rep\u00fablica Dominicana asume su compromiso con la regi\u00f3n como parte de este esfuerzo de cooperaci\u00f3n permanente\u201d, destac\u00f3 el director de Presupuesto y motiv\u00f3 a actuar siempre conforme a la ley y normas presupuestarias. En tanto que, Jos\u00e9 Luis Araya, presidente del Consejo Directivo de ASIP, agradeci\u00f3 al Gobierno dominicano y a la Organizaci\u00f3n para la Cooperaci\u00f3n y el Desarrollo Econ\u00f3micos (OCDE) por su apoyo, exhortando a los miembros a aplicar los conocimientos adquiridos con el prop\u00f3sito de mejorar la gesti\u00f3n p\u00fablica y promover el bienestar ciudadano. De su lado, Manoel G\u00f3mes, presidente del Consejo Deliberante de ASIP, se sum\u00f3 a las felicitaciones al equipo coordinador del evento por la dedicaci\u00f3n y trabajo durante el Seminario Internacional de Presupuesto P\u00fablico. El seminario constituy\u00f3 un espacio de an\u00e1lisis del \u00e1mbito presupuestario y cambios geopol\u00edticos actuales; adem\u00e1s, cont\u00f3 con un amplio programa destinado a conferencias, exposiciones y paneles con oradores expertos en materia econ\u00f3mica del \u00e1mbito local e internacional. Rafael Jovine, director de Estudios Econ\u00f3micos y Seguimiento Financiero de la DIGEPRES, quien fungi\u00f3 como presidente de la mesa directiva del Seminario, indic\u00f3 que el encuentro de ASIP rescata los retos econ\u00f3micos y geopol\u00edticos que enfrentan los pa\u00edses, y resalt\u00f3 que \u201cel encuentro, promueve el an\u00e1lisis de las circunstancias actuales y sus posibles efectos en la gesti\u00f3n de las finanzas p\u00fablicas\u201d. Buenas pr\u00e1cticas y retos presupuestarios de la regi\u00f3n En el 52 Seminario Internacional sobre Presupuesto&nbsp;P\u00fablico las reuniones t\u00e9cnicas, conferencias y reflexiones en su primer d\u00eda abord\u00f3 temas del \u00e1mbito de la geopol\u00edtica internacional, pr\u00e1cticas presupuestarias en salud, presupuesto con enfoque en ni\u00f1ez, presupuesto p\u00fablico en Brasil, avances tecnol\u00f3gicos de los presupuestos, estado de implementaci\u00f3n del presupuesto basado en resultado de los pa\u00edses. Los participantes y oradores tuvieron la oportunidad de discutir sobre la obligaci\u00f3n de los gobiernos de rendir cuentas de inversiones y resultados, enfoque del presupuesto por programas y resultados para garantizar la transparencia y porvenir ciudadano, derechos de la infancia a trav\u00e9s del presupuesto p\u00fablico y gasto en salud, cobertura y calidad sanitaria. Asimismo, sobre las fluctuaciones econ\u00f3micas, plurianualidad, disciplina fiscal, importancia de la informaci\u00f3n accesible en l\u00ednea para fomento de la transparencia y toma de decisiones y presupuesto por resultado. Entre los panelistas, se contaron Guillermo Valentino, responsable de la Oficina Nacional de Presupuesto de Argentina; Gavino Severino, oficial de Pol\u00edticas Sociales de UNICEF RD; Camila Vammalle, representante de la Organizaci\u00f3n de Cooperaci\u00f3n y Desarrollo Econ\u00f3micos (OCDE); Clayton Luiz Montes, secretario de Presupuesto Federal de Brasil y Victor Reis de Abriu Calvacante, director de la Secretar\u00eda de Presupuesto Oficial de Brasil. La Rep\u00fablica Dominicana desarroll\u00f3 un panel con el tema \u201cEl Presupuesto como instrumento de transformaci\u00f3n y valor de lo p\u00fablico\u201d, a cargo de Mar\u00eda V\u00edctoria Ort\u00edz, encargada del Departamento de Normas y Metodolog\u00edas; Juan Portalat\u00edn, del Departamento de Gesti\u00f3n Financiera de Formulaci\u00f3n y Ejecuci\u00f3n Presupuestaria; Sorangel Gonz\u00e1lez, del Departamento de An\u00e1lisis y Estudios Econ\u00f3micos; Mar\u00eda Jos\u00e9 Castro, de la divisi\u00f3n de Ministerios de Salud P\u00fablica y Asistencia Social y Trabajo de DIGEPRES. Las exposiciones del panel dominicano se vincularon a t\u00f3picos sobre el presupuesto verde, equidad de g\u00e9nero, gasto p\u00fablico destinado al cambio clim\u00e1tico, la biodiversidad, gesti\u00f3n de desastre, control social y la transparencia del presupuesto de cara al ciudadano, pol\u00edticas presupuestarias dirigidas a la ni\u00f1ez y adolescencia, mejoras del marco fiscal y de gastos prioritarios dentro de la gesti\u00f3n financiera p\u00fablica y el nuevo Sistema Integrado de Gesti\u00f3n Financiera SIGEF 2.0. Los temas abordados por pa\u00eds por los panelistas giraron sobre el contexto nacional de pol\u00edticas, situaci\u00f3n macroecon\u00f3mica y desaf\u00edos actuales de Argentina, adaptabilidad de Brasil de cara al COVID-19 e importancia de la adaptabilidad del presupuesto p\u00fablico como instrumento de estabilizaci\u00f3n, presupuesto, modelo econ\u00f3mico y plan de desarrollo cubano. Entre los pa\u00edses panelistas estuvieron Argentina, Brasil, Costa Rica, El Salvador, Uruguay, Paraguay, Panam\u00e1, Puerto Rico, Honduras, Rep\u00fablica de Cuba, Rep\u00fablica Dominicana, M\u00e9xico, Guatemala, Colombia, Per\u00fa. El evento cont\u00f3 con el apoyo y coordinaci\u00f3n de la Asociaci\u00f3n Internacional de Presupuesto P\u00fablico (ASIP), de la Organizaci\u00f3n para la Cooperaci\u00f3n y el Desarrollo Econ\u00f3micos (OCDE) y la Direcci\u00f3n General de Presupuesto de la Rep\u00fablica Dominicana (DIGEPRES). El evento en su acto inaugural cont\u00f3 con la presencia y palabras centrales del presidente de la Rep\u00fablica Dominicana, Luis Abinader, y con la participaci\u00f3n de funcionarios del \u00e1mbito p\u00fablico, de la cooperaci\u00f3n internacional, representantes miembros de ASIP y m\u00e1s de 500 participantes tanto de Rep\u00fablica Dominicana, Argentina, Brasil, Costa Rica, Paraguay, Uruguay, El Salvador, Guatemala, Colombia, M\u00e9xico, Per\u00fa, Puerto Rico, Panam\u00e1, Chile y otros pa\u00edses de la regi\u00f3n.<\/p>","protected":false},"author":1,"featured_media":43477,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[],"class_list":["post-43467","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-institucionales"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Concluye Seminario Internacional de Presupuesto P\u00fablico<\/title>\n<meta name=\"description\" content=\"Concluye Seminario Internacional de Presupuesto P\u00fablico y se destaca desempe\u00f1o presupuestario ejemplar de RD\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/digepres.gob.do\/en\/concluye-seminario-internacional-de-presupuesto-publico-y-se-destaca-desempeno-presupuestario-ejemplar-de-rd\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Concluye Seminario Internacional de Presupuesto P\u00fablico\" \/>\n<meta property=\"og:description\" content=\"Concluye Seminario Internacional de Presupuesto P\u00fablico y se destaca desempe\u00f1o presupuestario ejemplar de RD\" \/>\n<meta property=\"og:url\" content=\"https:\/\/digepres.gob.do\/en\/concluye-seminario-internacional-de-presupuesto-publico-y-se-destaca-desempeno-presupuestario-ejemplar-de-rd\/\" \/>\n<meta property=\"og:site_name\" content=\"Direcci\u00f3n General de Presupuesto - Rep\u00fablica Dominicana\" \/>\n<meta property=\"article:published_time\" content=\"2025-11-06T23:05:34+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-02-09T16:20:58+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/digepres.gob.do\/wp-content\/uploads\/2025\/11\/52.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"721\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"dafernandez\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"dafernandez\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/digepres.gob.do\\\/concluye-seminario-internacional-de-presupuesto-publico-y-se-destaca-desempeno-presupuestario-ejemplar-de-rd\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/digepres.gob.do\\\/concluye-seminario-internacional-de-presupuesto-publico-y-se-destaca-desempeno-presupuestario-ejemplar-de-rd\\\/\"},\"author\":{\"name\":\"dafernandez\",\"@id\":\"https:\\\/\\\/digepres.gob.do\\\/#\\\/schema\\\/person\\\/9823839a90c039ae0556d32bc6badf75\"},\"headline\":\"Concluye Seminario Internacional de Presupuesto P\u00fablico y se destaca desempe\u00f1o presupuestario ejemplar de RD\",\"datePublished\":\"2025-11-06T23:05:34+00:00\",\"dateModified\":\"2026-02-09T16:20:58+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/digepres.gob.do\\\/concluye-seminario-internacional-de-presupuesto-publico-y-se-destaca-desempeno-presupuestario-ejemplar-de-rd\\\/\"},\"wordCount\":1047,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/digepres.gob.do\\\/concluye-seminario-internacional-de-presupuesto-publico-y-se-destaca-desempeno-presupuestario-ejemplar-de-rd\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/digepres.gob.do\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/52.jpg\",\"articleSection\":[\"Institucionales\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/digepres.gob.do\\\/concluye-seminario-internacional-de-presupuesto-publico-y-se-destaca-desempeno-presupuestario-ejemplar-de-rd\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/digepres.gob.do\\\/concluye-seminario-internacional-de-presupuesto-publico-y-se-destaca-desempeno-presupuestario-ejemplar-de-rd\\\/\",\"url\":\"https:\\\/\\\/digepres.gob.do\\\/concluye-seminario-internacional-de-presupuesto-publico-y-se-destaca-desempeno-presupuestario-ejemplar-de-rd\\\/\",\"name\":\"Concluye Seminario Internacional de Presupuesto P\u00fablico\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/digepres.gob.do\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/digepres.gob.do\\\/concluye-seminario-internacional-de-presupuesto-publico-y-se-destaca-desempeno-presupuestario-ejemplar-de-rd\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/digepres.gob.do\\\/concluye-seminario-internacional-de-presupuesto-publico-y-se-destaca-desempeno-presupuestario-ejemplar-de-rd\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/digepres.gob.do\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/52.jpg\",\"datePublished\":\"2025-11-06T23:05:34+00:00\",\"dateModified\":\"2026-02-09T16:20:58+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/digepres.gob.do\\\/#\\\/schema\\\/person\\\/9823839a90c039ae0556d32bc6badf75\"},\"description\":\"Concluye Seminario Internacional de Presupuesto P\u00fablico y se destaca desempe\u00f1o presupuestario ejemplar de RD\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/digepres.gob.do\\\/concluye-seminario-internacional-de-presupuesto-publico-y-se-destaca-desempeno-presupuestario-ejemplar-de-rd\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/digepres.gob.do\\\/concluye-seminario-internacional-de-presupuesto-publico-y-se-destaca-desempeno-presupuestario-ejemplar-de-rd\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/digepres.gob.do\\\/concluye-seminario-internacional-de-presupuesto-publico-y-se-destaca-desempeno-presupuestario-ejemplar-de-rd\\\/#primaryimage\",\"url\":\"https:\\\/\\\/digepres.gob.do\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/52.jpg\",\"contentUrl\":\"https:\\\/\\\/digepres.gob.do\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/52.jpg\",\"width\":1280,\"height\":721,\"caption\":\"Concluye Seminario Internacional\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/digepres.gob.do\\\/concluye-seminario-internacional-de-presupuesto-publico-y-se-destaca-desempeno-presupuestario-ejemplar-de-rd\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/digepres.gob.do\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Concluye Seminario Internacional de Presupuesto P\u00fablico y se destaca desempe\u00f1o presupuestario ejemplar de RD\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/digepres.gob.do\\\/#website\",\"url\":\"https:\\\/\\\/digepres.gob.do\\\/\",\"name\":\"Direcci\u00f3n General de Presupuesto - Rep\u00fablica Dominicana\",\"description\":\"Somos el \u00d3rgano Rector del Sistema Presupuestario Dominicano por mandato de la Ley 423-06.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/digepres.gob.do\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/digepres.gob.do\\\/#\\\/schema\\\/person\\\/9823839a90c039ae0556d32bc6badf75\",\"name\":\"dafernandez\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9de94fae9628ce6653f66759a266949a3dbd04e8a51ec89f380a94945597ca59?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9de94fae9628ce6653f66759a266949a3dbd04e8a51ec89f380a94945597ca59?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9de94fae9628ce6653f66759a266949a3dbd04e8a51ec89f380a94945597ca59?s=96&d=mm&r=g\",\"caption\":\"dafernandez\"},\"sameAs\":[\"http:\\\/\\\/digepres.gob.do\"],\"url\":\"https:\\\/\\\/digepres.gob.do\\\/en\\\/author\\\/dafernandez\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Concluye Seminario Internacional de Presupuesto P\u00fablico","description":"Concluye Seminario Internacional de Presupuesto P\u00fablico y se destaca desempe\u00f1o presupuestario ejemplar de RD","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/digepres.gob.do\/en\/concluye-seminario-internacional-de-presupuesto-publico-y-se-destaca-desempeno-presupuestario-ejemplar-de-rd\/","og_locale":"en_US","og_type":"article","og_title":"Concluye Seminario Internacional de Presupuesto P\u00fablico","og_description":"Concluye Seminario Internacional de Presupuesto P\u00fablico y se destaca desempe\u00f1o presupuestario ejemplar de RD","og_url":"https:\/\/digepres.gob.do\/en\/concluye-seminario-internacional-de-presupuesto-publico-y-se-destaca-desempeno-presupuestario-ejemplar-de-rd\/","og_site_name":"Direcci\u00f3n General de Presupuesto - Rep\u00fablica Dominicana","article_published_time":"2025-11-06T23:05:34+00:00","article_modified_time":"2026-02-09T16:20:58+00:00","og_image":[{"width":1280,"height":721,"url":"https:\/\/digepres.gob.do\/wp-content\/uploads\/2025\/11\/52.jpg","type":"image\/jpeg"}],"author":"dafernandez","twitter_card":"summary_large_image","twitter_misc":{"Written by":"dafernandez","Est. reading time":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/digepres.gob.do\/concluye-seminario-internacional-de-presupuesto-publico-y-se-destaca-desempeno-presupuestario-ejemplar-de-rd\/#article","isPartOf":{"@id":"https:\/\/digepres.gob.do\/concluye-seminario-internacional-de-presupuesto-publico-y-se-destaca-desempeno-presupuestario-ejemplar-de-rd\/"},"author":{"name":"dafernandez","@id":"https:\/\/digepres.gob.do\/#\/schema\/person\/9823839a90c039ae0556d32bc6badf75"},"headline":"Concluye Seminario Internacional de Presupuesto P\u00fablico y se destaca desempe\u00f1o presupuestario ejemplar de RD","datePublished":"2025-11-06T23:05:34+00:00","dateModified":"2026-02-09T16:20:58+00:00","mainEntityOfPage":{"@id":"https:\/\/digepres.gob.do\/concluye-seminario-internacional-de-presupuesto-publico-y-se-destaca-desempeno-presupuestario-ejemplar-de-rd\/"},"wordCount":1047,"commentCount":0,"image":{"@id":"https:\/\/digepres.gob.do\/concluye-seminario-internacional-de-presupuesto-publico-y-se-destaca-desempeno-presupuestario-ejemplar-de-rd\/#primaryimage"},"thumbnailUrl":"https:\/\/digepres.gob.do\/wp-content\/uploads\/2025\/11\/52.jpg","articleSection":["Institucionales"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/digepres.gob.do\/concluye-seminario-internacional-de-presupuesto-publico-y-se-destaca-desempeno-presupuestario-ejemplar-de-rd\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/digepres.gob.do\/concluye-seminario-internacional-de-presupuesto-publico-y-se-destaca-desempeno-presupuestario-ejemplar-de-rd\/","url":"https:\/\/digepres.gob.do\/concluye-seminario-internacional-de-presupuesto-publico-y-se-destaca-desempeno-presupuestario-ejemplar-de-rd\/","name":"Concluye Seminario Internacional de Presupuesto P\u00fablico","isPartOf":{"@id":"https:\/\/digepres.gob.do\/#website"},"primaryImageOfPage":{"@id":"https:\/\/digepres.gob.do\/concluye-seminario-internacional-de-presupuesto-publico-y-se-destaca-desempeno-presupuestario-ejemplar-de-rd\/#primaryimage"},"image":{"@id":"https:\/\/digepres.gob.do\/concluye-seminario-internacional-de-presupuesto-publico-y-se-destaca-desempeno-presupuestario-ejemplar-de-rd\/#primaryimage"},"thumbnailUrl":"https:\/\/digepres.gob.do\/wp-content\/uploads\/2025\/11\/52.jpg","datePublished":"2025-11-06T23:05:34+00:00","dateModified":"2026-02-09T16:20:58+00:00","author":{"@id":"https:\/\/digepres.gob.do\/#\/schema\/person\/9823839a90c039ae0556d32bc6badf75"},"description":"Concluye Seminario Internacional de Presupuesto P\u00fablico y se destaca desempe\u00f1o presupuestario ejemplar de RD","breadcrumb":{"@id":"https:\/\/digepres.gob.do\/concluye-seminario-internacional-de-presupuesto-publico-y-se-destaca-desempeno-presupuestario-ejemplar-de-rd\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/digepres.gob.do\/concluye-seminario-internacional-de-presupuesto-publico-y-se-destaca-desempeno-presupuestario-ejemplar-de-rd\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/digepres.gob.do\/concluye-seminario-internacional-de-presupuesto-publico-y-se-destaca-desempeno-presupuestario-ejemplar-de-rd\/#primaryimage","url":"https:\/\/digepres.gob.do\/wp-content\/uploads\/2025\/11\/52.jpg","contentUrl":"https:\/\/digepres.gob.do\/wp-content\/uploads\/2025\/11\/52.jpg","width":1280,"height":721,"caption":"Concluye Seminario Internacional"},{"@type":"BreadcrumbList","@id":"https:\/\/digepres.gob.do\/concluye-seminario-internacional-de-presupuesto-publico-y-se-destaca-desempeno-presupuestario-ejemplar-de-rd\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/digepres.gob.do\/"},{"@type":"ListItem","position":2,"name":"Concluye Seminario Internacional de Presupuesto P\u00fablico y se destaca desempe\u00f1o presupuestario ejemplar de RD"}]},{"@type":"WebSite","@id":"https:\/\/digepres.gob.do\/#website","url":"https:\/\/digepres.gob.do\/","name":"Direcci\u00f3n General de Presupuesto - Rep\u00fablica Dominicana","description":"Somos el \u00d3rgano Rector del Sistema Presupuestario Dominicano por mandato de la Ley 423-06.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/digepres.gob.do\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/digepres.gob.do\/#\/schema\/person\/9823839a90c039ae0556d32bc6badf75","name":"dafernandez","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/9de94fae9628ce6653f66759a266949a3dbd04e8a51ec89f380a94945597ca59?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/9de94fae9628ce6653f66759a266949a3dbd04e8a51ec89f380a94945597ca59?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/9de94fae9628ce6653f66759a266949a3dbd04e8a51ec89f380a94945597ca59?s=96&d=mm&r=g","caption":"dafernandez"},"sameAs":["http:\/\/digepres.gob.do"],"url":"https:\/\/digepres.gob.do\/en\/author\/dafernandez\/"}]}},"_links":{"self":[{"href":"https:\/\/digepres.gob.do\/en\/wp-json\/wp\/v2\/posts\/43467","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/digepres.gob.do\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/digepres.gob.do\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/digepres.gob.do\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/digepres.gob.do\/en\/wp-json\/wp\/v2\/comments?post=43467"}],"version-history":[{"count":4,"href":"https:\/\/digepres.gob.do\/en\/wp-json\/wp\/v2\/posts\/43467\/revisions"}],"predecessor-version":[{"id":43504,"href":"https:\/\/digepres.gob.do\/en\/wp-json\/wp\/v2\/posts\/43467\/revisions\/43504"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/digepres.gob.do\/en\/wp-json\/wp\/v2\/media\/43477"}],"wp:attachment":[{"href":"https:\/\/digepres.gob.do\/en\/wp-json\/wp\/v2\/media?parent=43467"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/digepres.gob.do\/en\/wp-json\/wp\/v2\/categories?post=43467"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/digepres.gob.do\/en\/wp-json\/wp\/v2\/tags?post=43467"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}