
{"id":40022,"date":"2025-07-15T15:05:40","date_gmt":"2025-07-15T19:05:40","guid":{"rendered":"https:\/\/www.digepres.gob.do\/?p=40022"},"modified":"2025-09-15T10:31:04","modified_gmt":"2025-09-15T14:31:04","slug":"digepres-y-articulacion-nacional-campesina-realizan-encuentro-ciudadano-para-socializar-propuestas-de-politicas-publicas-para-el-fomento-de-la-agricultura-familiar","status":"publish","type":"post","link":"https:\/\/digepres.gob.do\/en\/digepres-y-articulacion-nacional-campesina-realizan-encuentro-ciudadano-para-socializar-propuestas-de-politicas-publicas-para-el-fomento-de-la-agricultura-familiar\/","title":{"rendered":"DIGEPRES y Articulaci\u00f3n Nacional Campesina realizan Encuentro Ciudadano para socializar propuestas de pol\u00edticas p\u00fablicas para el fomento de la agricultura familiar."},"content":{"rendered":"<p>\t\t\t\t<em>La actividad fue un espacio adem\u00e1s para destacar acciones del Gobierno en materia agr\u00edcola de sostenibilidad, aumento y diversificaci\u00f3n de la producci\u00f3n nacional.<\/em><\/p>\n<p>The <a href=\"https:\/\/digepres.gob.do\/en\/\">General Budget Directorate<\/a> <a href=\"https:\/\/www.instagram.com\/digepresrd\/\">(DIGEPRES)<\/a> y la Articulaci\u00f3n Nacional Campesina <a href=\"https:\/\/viacampesina.org\/es\/evento\/articulaciacional-campesina\/\">(ANC)<\/a> llevaron a cabo un <a href=\"https:\/\/digepres.gob.do\/en\/presupuesto-ciudadano\/encuentro-ciudadano-en-digepres\/\">Encuentro Ciudadano<\/a> para socializar desaf\u00edos, promover acciones, avances y articulaciones alrededor del sector agropecuario y su impacto en las zonas rurales del pa\u00eds.<\/p>\n<p>En el encuentro, se destac\u00f3 como punto prioritario la necesidad de fortalecer pol\u00edticas p\u00fablicas focalizadas en la agricultura familiar, ya que esta enfrenta desaf\u00edos para el acceso a recursos productivos como la tierra, el agua, financiamiento o apoyo t\u00e9cnico para lograr que sea sostenible y resiliente.<\/p>\n<p>La actividad cont\u00f3 con la participaci\u00f3n del director de la <a href=\"https:\/\/digepres.gob.do\/en\/\">General Budget Directorate<\/a>, <a href=\"https:\/\/www.instagram.com\/digepresrd\/\">Jos\u00e9 Rijo Presbot<\/a>; Hero P\u00e9rez, coordinador de\u00a0Articulaci\u00f3n Nacional Campesina <a href=\"https:\/\/viacampesina.org\/es\/evento\/articulaciacional-campesina\/\">(ANC)<\/a>; Guadalupe Valdez, del Centro de Investigaci\u00f3n y Promoci\u00f3n Social <a href=\"https:\/\/www.ciprosrd.org\/\">(CIPROS)<\/a>; Carlos Alc\u00e1ntara, director de Agricultura Familiar del Ministerio de Agricultura; Odilys Hidalgo, directora de Servicios Presupuestarios; Rafael Jovine, director de Estudios Econ\u00f3micos y Seguimiento Financiero; Sorangel Gonz\u00e1lez, encargada del Departamento de An\u00e1lisis y Estudios Econ\u00f3micos; Jhannet Taveras Bichara, encargada de Servicios Econ\u00f3micos y Airon Fern\u00e1ndez, especialista en Estudios Econ\u00f3micos.<\/p>\n<p>Las palabras de bienvenida al encuentro estuvieron a cargo del director de Presupuesto, quien en su intervenci\u00f3n inici\u00f3 con un breve contexto sobre el panorama fiscal del Estado dominicano, espec\u00edficamente, en relaci\u00f3n con la distribuci\u00f3n actual del Presupuesto General del Estado<a href=\"https:\/\/digepres.gob.do\/en\/presupuesto\/gobierno-general-nacional\/ley-de-presupuesto-general-del-estado-2025\/\"> (PGE)<\/a>, el nuevo proceso de formulaci\u00f3n del PGE 2026, techos presupuestarios y prioridades para eficientizar los recursos del Estado.<\/p>\n<div class=\"wp-block-image\">\n<div class=\"wp-block-image\"><img fetchpriority=\"high\" decoding=\"async\" class=\"wpa-warning wpa-image-missing-alt alignright wp-image-40025 size-medium\" title=\"DIGEPRES y Articulaci\u00f3n Nacional Campesina\" src=\"https:\/\/www.digepres.gob.do\/wp-content\/uploads\/2025\/07\/IMG_8475-scaled-300x200.jpg\" alt=\"DIGEPRES y Articulaci\u00f3n Nacional Campesina\" width=\"300\" height=\"200\" data-warning=\"Falta el texto alternativo\" \/><\/div>\n<\/div>\n<p>Hero P\u00e9rez, coordinador de\u00a0Articulaci\u00f3n Nacional Campesina <a href=\"https:\/\/viacampesina.org\/es\/evento\/articulaciacional-campesina\/\">ANC<\/a>, en su exposici\u00f3n explic\u00f3 la importancia del desarrollo de la agricultura en sentido general y la familiar, y planteando que esta \u00faltima produce aproximadamente del 70 al 80% de los alimentos del pa\u00eds. P\u00e9rez, adem\u00e1s, socializ\u00f3 con los presentes las dificultades del sector se\u00f1alando las desventajas frente al sector empresarial en temas de importaci\u00f3n, exportaci\u00f3n, titulaci\u00f3n, tecnificaci\u00f3n, formalizaci\u00f3n del sector, acceso al financiamiento y pol\u00edticas p\u00fablicas. <em>\u201cSi se aplicara la regulaci\u00f3n del sector agr\u00edcola familiar y se crearan fondos directos a ese sector se desarrollar\u00eda la misma en zonas rurales y urbanas\u201d,<\/em> dijo el representante de la <a href=\"https:\/\/viacampesina.org\/es\/evento\/articulaciacional-campesina\/\">ANC<\/a>.<\/p>\n<p>Asimismo, P\u00e9rez hizo referencias a las legislaciones que existen en el pa\u00eds para promover la agricultura familiar como la Ley No. 8 del Ministerio de Agricultura, que incluye la promoci\u00f3n del desarrollo agr\u00edcola, la asistencia t\u00e9cnica a los productores y la regulaci\u00f3n de las actividades agropecuarias, y del Decreto 610-22, que reconoce su importancia para la seguridad alimentaria y el desarrollo socioecon\u00f3mico de las comunidades rurales, de igual forma a los Objetivo de Desarrollo Sostenible 2 (ODS 2), que\u00a0busca poner fin al hambre, la seguridad alimentaria, mejorar la nutrici\u00f3n y promover la agricultura sostenible para el a\u00f1o 2030, de lo cual Rep\u00fablica Dominicana es signatario.<\/p>\n<p>En ese sentido, <a href=\"https:\/\/www.instagram.com\/digepresrd\/\">Jos\u00e9 Rijo Presbot<\/a>, director de Presupuesto y el equipo de t\u00e9cnicos presente socializaron la diversidad de programas que impulsa el Ministerio de Agricultura como parte de las acciones que el Gobierno realiza para potenciar el sector. El equipo de Presupuesto resalt\u00f3 labores realizadas en materia de irrigaci\u00f3n, entrega de semillas, programas de tecnificaci\u00f3n, subsidios para fertilizantes y carburantes que impactan al sector de manera positiva.<\/p>\n<p>Guadalupe Valdez, de <a href=\"https:\/\/www.ciprosrd.org\/\">CIPROS,<\/a> se encarg\u00f3 de presentar las propuestas de Pol\u00edticas P\u00fablicas Regionales para el Fomento\u00a0 de la Agricultura Familiar, elaboradas de forma participativa por los Comit\u00e9s Regionales de Agricultura Familiar, orientadas a fortalecer la seguridad alimentaria, el desarrollo rural y la sostenibilidad de la agricultura familiar; y aprovech\u00f3 el espacio para se\u00f1alar la necesidad de promover procesos de di\u00e1logo entre los actores del sector, educar en materia de pol\u00edticas p\u00fablicas, ampliar y dinamizar los Comit\u00e9s Regionales, promover el empleo y desarrollo rural, y ampliar los recursos dirigidos a peque\u00f1os productores.<\/p>\n<div class=\"wp-block-image\"><img decoding=\"async\" class=\"wpa-warning wpa-image-missing-alt alignleft wp-image-40024\" title=\"DIGEPRES y Articulaci\u00f3n Nacional Campesina\" src=\"https:\/\/www.digepres.gob.do\/wp-content\/uploads\/2025\/07\/IMG_8485-scaled-300x200.jpg\" alt=\"DIGEPRES y Articulaci\u00f3n Nacional Campesina\" width=\"372\" height=\"248\" data-warning=\"Falta el texto alternativo\" \/><\/div>\n<p><strong>Iniciativas desde el Gobierno<\/strong><\/p>\n<p>Se recuerda que, el gobierno de presidente <a href=\"https:\/\/www.instagram.com\/luisabinader\/\">Luis Abinader<\/a> en materia agr\u00edcola se ha enfocado en el aumento y diversificaci\u00f3n de la producci\u00f3n nacional, con el objetivo de fortalecer la seguridad alimentaria y la econom\u00eda del pa\u00eds. Entre las iniciativas\u00a0del gobierno en materia agr\u00edcola, se destacan la mecanizaci\u00f3n, el apoyo a cultivos de exportaci\u00f3n como el cacao y el impulso a la producci\u00f3n de vegetales en invernaderos, adem\u00e1s de programas de apoyo a peque\u00f1os agricultores.<\/p>\n<p><strong>Calendario de Formulaci\u00f3n presupuestaria 2026<\/strong><\/p>\n<p>Es importante destacar que, acorde al Calendario de formulaci\u00f3n presupuestaria 2026, este 15 de julio las instituciones p\u00fablicas del Gobierno General Nacional deben iniciar el proceso de Elaboraci\u00f3n de los Anteproyectos de Presupuestos Institucionales anuales y plurianuales F\u00edsico-Financieros. Este proceso se extiende hasta el 31 de agosto del presente a\u00f1o, ofreciendo la oportunidad para que, acorde al tope presupuestario del Ministerio de Agricultura y su estructura program\u00e1tica, se pueda dar cabida a las recomendaciones de <a href=\"https:\/\/viacampesina.org\/es\/evento\/articulaciacional-campesina\/\">ANC<\/a> en materia de agricultura familiar. El <a href=\"https:\/\/digepres.gob.do\/en\/presupuesto-ciudadano\/encuentro-ciudadano-en-digepres\/\">Encuentro Ciudadano<\/a> fue realizado en el sal\u00f3n del Despacho de Presupuesto.\t\t<\/p>","protected":false},"excerpt":{"rendered":"<p>La actividad fue un espacio adem\u00e1s para destacar acciones del Gobierno en materia agr\u00edcola de sostenibilidad, aumento y diversificaci\u00f3n de la producci\u00f3n nacional. La Direcci\u00f3n General de Presupuesto (DIGEPRES) y la Articulaci\u00f3n Nacional Campesina (ANC) llevaron a cabo un Encuentro Ciudadano para socializar desaf\u00edos, promover acciones, avances y articulaciones alrededor del sector agropecuario y su impacto en las zonas rurales del pa\u00eds. En el encuentro, se destac\u00f3 como punto prioritario la necesidad de fortalecer pol\u00edticas p\u00fablicas focalizadas en la agricultura familiar, ya que esta enfrenta desaf\u00edos para el acceso a recursos productivos como la tierra, el agua, financiamiento o apoyo t\u00e9cnico para lograr que sea sostenible y resiliente. La actividad cont\u00f3 con la participaci\u00f3n del director de la Direcci\u00f3n General de Presupuesto, Jos\u00e9 Rijo Presbot; Hero P\u00e9rez, coordinador de\u00a0Articulaci\u00f3n Nacional Campesina (ANC); Guadalupe Valdez, del Centro de Investigaci\u00f3n y Promoci\u00f3n Social (CIPROS); Carlos Alc\u00e1ntara, director de Agricultura Familiar del Ministerio de Agricultura; Odilys Hidalgo, directora de Servicios Presupuestarios; Rafael Jovine, director de Estudios Econ\u00f3micos y Seguimiento Financiero; Sorangel Gonz\u00e1lez, encargada del Departamento de An\u00e1lisis y Estudios Econ\u00f3micos; Jhannet Taveras Bichara, encargada de Servicios Econ\u00f3micos y Airon Fern\u00e1ndez, especialista en Estudios Econ\u00f3micos. Las palabras de bienvenida al encuentro estuvieron a cargo del director de Presupuesto, quien en su intervenci\u00f3n inici\u00f3 con un breve contexto sobre el panorama fiscal del Estado dominicano, espec\u00edficamente, en relaci\u00f3n con la distribuci\u00f3n actual del Presupuesto General del Estado (PGE), el nuevo proceso de formulaci\u00f3n del PGE 2026, techos presupuestarios y prioridades para eficientizar los recursos del Estado. Hero P\u00e9rez, coordinador de\u00a0Articulaci\u00f3n Nacional Campesina ANC, en su exposici\u00f3n explic\u00f3 la importancia del desarrollo de la agricultura en sentido general y la familiar, y planteando que esta \u00faltima produce aproximadamente del 70 al 80% de los alimentos del pa\u00eds. P\u00e9rez, adem\u00e1s, socializ\u00f3 con los presentes las dificultades del sector se\u00f1alando las desventajas frente al sector empresarial en temas de importaci\u00f3n, exportaci\u00f3n, titulaci\u00f3n, tecnificaci\u00f3n, formalizaci\u00f3n del sector, acceso al financiamiento y pol\u00edticas p\u00fablicas. \u201cSi se aplicara la regulaci\u00f3n del sector agr\u00edcola familiar y se crearan fondos directos a ese sector se desarrollar\u00eda la misma en zonas rurales y urbanas\u201d, dijo el representante de la ANC. Asimismo, P\u00e9rez hizo referencias a las legislaciones que existen en el pa\u00eds para promover la agricultura familiar como la Ley No. 8 del Ministerio de Agricultura, que incluye la promoci\u00f3n del desarrollo agr\u00edcola, la asistencia t\u00e9cnica a los productores y la regulaci\u00f3n de las actividades agropecuarias, y del Decreto 610-22, que reconoce su importancia para la seguridad alimentaria y el desarrollo socioecon\u00f3mico de las comunidades rurales, de igual forma a los Objetivo de Desarrollo Sostenible 2 (ODS 2), que\u00a0busca poner fin al hambre, la seguridad alimentaria, mejorar la nutrici\u00f3n y promover la agricultura sostenible para el a\u00f1o 2030, de lo cual Rep\u00fablica Dominicana es signatario. En ese sentido, Jos\u00e9 Rijo Presbot, director de Presupuesto y el equipo de t\u00e9cnicos presente socializaron la diversidad de programas que impulsa el Ministerio de Agricultura como parte de las acciones que el Gobierno realiza para potenciar el sector. El equipo de Presupuesto resalt\u00f3 labores realizadas en materia de irrigaci\u00f3n, entrega de semillas, programas de tecnificaci\u00f3n, subsidios para fertilizantes y carburantes que impactan al sector de manera positiva. Guadalupe Valdez, de CIPROS, se encarg\u00f3 de presentar las propuestas de Pol\u00edticas P\u00fablicas Regionales para el Fomento\u00a0 de la Agricultura Familiar, elaboradas de forma participativa por los Comit\u00e9s Regionales de Agricultura Familiar, orientadas a fortalecer la seguridad alimentaria, el desarrollo rural y la sostenibilidad de la agricultura familiar; y aprovech\u00f3 el espacio para se\u00f1alar la necesidad de promover procesos de di\u00e1logo entre los actores del sector, educar en materia de pol\u00edticas p\u00fablicas, ampliar y dinamizar los Comit\u00e9s Regionales, promover el empleo y desarrollo rural, y ampliar los recursos dirigidos a peque\u00f1os productores. Iniciativas desde el Gobierno Se recuerda que, el gobierno de presidente Luis Abinader en materia agr\u00edcola se ha enfocado en el aumento y diversificaci\u00f3n de la producci\u00f3n nacional, con el objetivo de fortalecer la seguridad alimentaria y la econom\u00eda del pa\u00eds. Entre las iniciativas\u00a0del gobierno en materia agr\u00edcola, se destacan la mecanizaci\u00f3n, el apoyo a cultivos de exportaci\u00f3n como el cacao y el impulso a la producci\u00f3n de vegetales en invernaderos, adem\u00e1s de programas de apoyo a peque\u00f1os agricultores. Calendario de Formulaci\u00f3n presupuestaria 2026 Es importante destacar que, acorde al Calendario de formulaci\u00f3n presupuestaria 2026, este 15 de julio las instituciones p\u00fablicas del Gobierno General Nacional deben iniciar el proceso de Elaboraci\u00f3n de los Anteproyectos de Presupuestos Institucionales anuales y plurianuales F\u00edsico-Financieros. Este proceso se extiende hasta el 31 de agosto del presente a\u00f1o, ofreciendo la oportunidad para que, acorde al tope presupuestario del Ministerio de Agricultura y su estructura program\u00e1tica, se pueda dar cabida a las recomendaciones de ANC en materia de agricultura familiar. El Encuentro Ciudadano fue realizado en el sal\u00f3n del Despacho de Presupuesto.<\/p>","protected":false},"author":2,"featured_media":40397,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[],"class_list":["post-40022","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-institucionales"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>DIGEPRES y Articulaci\u00f3n Nacional Campesina realizan Encuentro C.<\/title>\n<meta name=\"description\" content=\"DIGEPRES y Articulaci\u00f3n Nacional Campesina realizan Encuentro Ciudadano para socializar propuestas de pol\u00edticas p\u00fablicas para el fomento de la agricultura..\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/digepres.gob.do\/en\/digepres-y-articulacion-nacional-campesina-realizan-encuentro-ciudadano-para-socializar-propuestas-de-politicas-publicas-para-el-fomento-de-la-agricultura-familiar\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"DIGEPRES y Articulaci\u00f3n Nacional Campesina realizan Encuentro C.\" \/>\n<meta property=\"og:description\" content=\"DIGEPRES y Articulaci\u00f3n Nacional Campesina realizan Encuentro Ciudadano para socializar propuestas de pol\u00edticas p\u00fablicas para el fomento de la agricultura..\" \/>\n<meta property=\"og:url\" content=\"https:\/\/digepres.gob.do\/en\/digepres-y-articulacion-nacional-campesina-realizan-encuentro-ciudadano-para-socializar-propuestas-de-politicas-publicas-para-el-fomento-de-la-agricultura-familiar\/\" \/>\n<meta property=\"og:site_name\" content=\"Direcci\u00f3n General de Presupuesto - Rep\u00fablica Dominicana\" \/>\n<meta property=\"article:published_time\" content=\"2025-07-15T19:05:40+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-09-15T14:31:04+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/digepres.gob.do\/wp-content\/uploads\/2025\/09\/DIGEPRES-y-Articulacion-Nacional-Campesina-realizan-Encuentro-Ciudadano-para-socializar-propuestas-de-politicas-publicas-para-el-fomento-de-la-agricultura-familiar-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1703\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Pablo Paez\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Pablo Paez\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/digepres.gob.do\\\/digepres-y-articulacion-nacional-campesina-realizan-encuentro-ciudadano-para-socializar-propuestas-de-politicas-publicas-para-el-fomento-de-la-agricultura-familiar\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/digepres.gob.do\\\/digepres-y-articulacion-nacional-campesina-realizan-encuentro-ciudadano-para-socializar-propuestas-de-politicas-publicas-para-el-fomento-de-la-agricultura-familiar\\\/\"},\"author\":{\"name\":\"Pablo Paez\",\"@id\":\"https:\\\/\\\/digepres.gob.do\\\/#\\\/schema\\\/person\\\/f6f6885c1078d1d53221d15413ab38b5\"},\"headline\":\"DIGEPRES y Articulaci\u00f3n Nacional Campesina realizan Encuentro Ciudadano para socializar propuestas de pol\u00edticas p\u00fablicas para el fomento de la agricultura familiar.\",\"datePublished\":\"2025-07-15T19:05:40+00:00\",\"dateModified\":\"2025-09-15T14:31:04+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/digepres.gob.do\\\/digepres-y-articulacion-nacional-campesina-realizan-encuentro-ciudadano-para-socializar-propuestas-de-politicas-publicas-para-el-fomento-de-la-agricultura-familiar\\\/\"},\"wordCount\":904,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/digepres.gob.do\\\/digepres-y-articulacion-nacional-campesina-realizan-encuentro-ciudadano-para-socializar-propuestas-de-politicas-publicas-para-el-fomento-de-la-agricultura-familiar\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/digepres.gob.do\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/DIGEPRES-y-Articulacion-Nacional-Campesina-realizan-Encuentro-Ciudadano-para-socializar-propuestas-de-politicas-publicas-para-el-fomento-de-la-agricultura-familiar-1.jpg\",\"articleSection\":[\"Institucionales\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/digepres.gob.do\\\/digepres-y-articulacion-nacional-campesina-realizan-encuentro-ciudadano-para-socializar-propuestas-de-politicas-publicas-para-el-fomento-de-la-agricultura-familiar\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/digepres.gob.do\\\/digepres-y-articulacion-nacional-campesina-realizan-encuentro-ciudadano-para-socializar-propuestas-de-politicas-publicas-para-el-fomento-de-la-agricultura-familiar\\\/\",\"url\":\"https:\\\/\\\/digepres.gob.do\\\/digepres-y-articulacion-nacional-campesina-realizan-encuentro-ciudadano-para-socializar-propuestas-de-politicas-publicas-para-el-fomento-de-la-agricultura-familiar\\\/\",\"name\":\"DIGEPRES y Articulaci\u00f3n Nacional Campesina realizan Encuentro C.\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/digepres.gob.do\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/digepres.gob.do\\\/digepres-y-articulacion-nacional-campesina-realizan-encuentro-ciudadano-para-socializar-propuestas-de-politicas-publicas-para-el-fomento-de-la-agricultura-familiar\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/digepres.gob.do\\\/digepres-y-articulacion-nacional-campesina-realizan-encuentro-ciudadano-para-socializar-propuestas-de-politicas-publicas-para-el-fomento-de-la-agricultura-familiar\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/digepres.gob.do\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/DIGEPRES-y-Articulacion-Nacional-Campesina-realizan-Encuentro-Ciudadano-para-socializar-propuestas-de-politicas-publicas-para-el-fomento-de-la-agricultura-familiar-1.jpg\",\"datePublished\":\"2025-07-15T19:05:40+00:00\",\"dateModified\":\"2025-09-15T14:31:04+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/digepres.gob.do\\\/#\\\/schema\\\/person\\\/f6f6885c1078d1d53221d15413ab38b5\"},\"description\":\"DIGEPRES y Articulaci\u00f3n Nacional Campesina realizan Encuentro Ciudadano para socializar propuestas de pol\u00edticas p\u00fablicas para el fomento de la agricultura..\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/digepres.gob.do\\\/digepres-y-articulacion-nacional-campesina-realizan-encuentro-ciudadano-para-socializar-propuestas-de-politicas-publicas-para-el-fomento-de-la-agricultura-familiar\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/digepres.gob.do\\\/digepres-y-articulacion-nacional-campesina-realizan-encuentro-ciudadano-para-socializar-propuestas-de-politicas-publicas-para-el-fomento-de-la-agricultura-familiar\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/digepres.gob.do\\\/digepres-y-articulacion-nacional-campesina-realizan-encuentro-ciudadano-para-socializar-propuestas-de-politicas-publicas-para-el-fomento-de-la-agricultura-familiar\\\/#primaryimage\",\"url\":\"https:\\\/\\\/digepres.gob.do\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/DIGEPRES-y-Articulacion-Nacional-Campesina-realizan-Encuentro-Ciudadano-para-socializar-propuestas-de-politicas-publicas-para-el-fomento-de-la-agricultura-familiar-1.jpg\",\"contentUrl\":\"https:\\\/\\\/digepres.gob.do\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/DIGEPRES-y-Articulacion-Nacional-Campesina-realizan-Encuentro-Ciudadano-para-socializar-propuestas-de-politicas-publicas-para-el-fomento-de-la-agricultura-familiar-1.jpg\",\"width\":2560,\"height\":1703},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/digepres.gob.do\\\/digepres-y-articulacion-nacional-campesina-realizan-encuentro-ciudadano-para-socializar-propuestas-de-politicas-publicas-para-el-fomento-de-la-agricultura-familiar\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/digepres.gob.do\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"DIGEPRES y Articulaci\u00f3n Nacional Campesina realizan Encuentro Ciudadano para socializar propuestas de pol\u00edticas p\u00fablicas para el fomento de la agricultura familiar.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/digepres.gob.do\\\/#website\",\"url\":\"https:\\\/\\\/digepres.gob.do\\\/\",\"name\":\"Direcci\u00f3n General de Presupuesto - Rep\u00fablica Dominicana\",\"description\":\"Somos el \u00d3rgano Rector del Sistema Presupuestario Dominicano por mandato de la Ley 423-06.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/digepres.gob.do\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/digepres.gob.do\\\/#\\\/schema\\\/person\\\/f6f6885c1078d1d53221d15413ab38b5\",\"name\":\"Pablo Paez\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e9d364ce257be032b8adf031185529d2677ad33d9298b62704d967cd574fa801?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e9d364ce257be032b8adf031185529d2677ad33d9298b62704d967cd574fa801?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e9d364ce257be032b8adf031185529d2677ad33d9298b62704d967cd574fa801?s=96&d=mm&r=g\",\"caption\":\"Pablo Paez\"},\"url\":\"https:\\\/\\\/digepres.gob.do\\\/en\\\/author\\\/ppaez\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"DIGEPRES y Articulaci\u00f3n Nacional Campesina realizan Encuentro C.","description":"DIGEPRES y Articulaci\u00f3n Nacional Campesina realizan Encuentro Ciudadano para socializar propuestas de pol\u00edticas p\u00fablicas para el fomento de la agricultura..","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/digepres.gob.do\/en\/digepres-y-articulacion-nacional-campesina-realizan-encuentro-ciudadano-para-socializar-propuestas-de-politicas-publicas-para-el-fomento-de-la-agricultura-familiar\/","og_locale":"en_US","og_type":"article","og_title":"DIGEPRES y Articulaci\u00f3n Nacional Campesina realizan Encuentro C.","og_description":"DIGEPRES y Articulaci\u00f3n Nacional Campesina realizan Encuentro Ciudadano para socializar propuestas de pol\u00edticas p\u00fablicas para el fomento de la agricultura..","og_url":"https:\/\/digepres.gob.do\/en\/digepres-y-articulacion-nacional-campesina-realizan-encuentro-ciudadano-para-socializar-propuestas-de-politicas-publicas-para-el-fomento-de-la-agricultura-familiar\/","og_site_name":"Direcci\u00f3n General de Presupuesto - Rep\u00fablica Dominicana","article_published_time":"2025-07-15T19:05:40+00:00","article_modified_time":"2025-09-15T14:31:04+00:00","og_image":[{"width":2560,"height":1703,"url":"https:\/\/digepres.gob.do\/wp-content\/uploads\/2025\/09\/DIGEPRES-y-Articulacion-Nacional-Campesina-realizan-Encuentro-Ciudadano-para-socializar-propuestas-de-politicas-publicas-para-el-fomento-de-la-agricultura-familiar-1.jpg","type":"image\/jpeg"}],"author":"Pablo Paez","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Pablo Paez","Est. reading time":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/digepres.gob.do\/digepres-y-articulacion-nacional-campesina-realizan-encuentro-ciudadano-para-socializar-propuestas-de-politicas-publicas-para-el-fomento-de-la-agricultura-familiar\/#article","isPartOf":{"@id":"https:\/\/digepres.gob.do\/digepres-y-articulacion-nacional-campesina-realizan-encuentro-ciudadano-para-socializar-propuestas-de-politicas-publicas-para-el-fomento-de-la-agricultura-familiar\/"},"author":{"name":"Pablo Paez","@id":"https:\/\/digepres.gob.do\/#\/schema\/person\/f6f6885c1078d1d53221d15413ab38b5"},"headline":"DIGEPRES y Articulaci\u00f3n Nacional Campesina realizan Encuentro Ciudadano para socializar propuestas de pol\u00edticas p\u00fablicas para el fomento de la agricultura familiar.","datePublished":"2025-07-15T19:05:40+00:00","dateModified":"2025-09-15T14:31:04+00:00","mainEntityOfPage":{"@id":"https:\/\/digepres.gob.do\/digepres-y-articulacion-nacional-campesina-realizan-encuentro-ciudadano-para-socializar-propuestas-de-politicas-publicas-para-el-fomento-de-la-agricultura-familiar\/"},"wordCount":904,"commentCount":0,"image":{"@id":"https:\/\/digepres.gob.do\/digepres-y-articulacion-nacional-campesina-realizan-encuentro-ciudadano-para-socializar-propuestas-de-politicas-publicas-para-el-fomento-de-la-agricultura-familiar\/#primaryimage"},"thumbnailUrl":"https:\/\/digepres.gob.do\/wp-content\/uploads\/2025\/09\/DIGEPRES-y-Articulacion-Nacional-Campesina-realizan-Encuentro-Ciudadano-para-socializar-propuestas-de-politicas-publicas-para-el-fomento-de-la-agricultura-familiar-1.jpg","articleSection":["Institucionales"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/digepres.gob.do\/digepres-y-articulacion-nacional-campesina-realizan-encuentro-ciudadano-para-socializar-propuestas-de-politicas-publicas-para-el-fomento-de-la-agricultura-familiar\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/digepres.gob.do\/digepres-y-articulacion-nacional-campesina-realizan-encuentro-ciudadano-para-socializar-propuestas-de-politicas-publicas-para-el-fomento-de-la-agricultura-familiar\/","url":"https:\/\/digepres.gob.do\/digepres-y-articulacion-nacional-campesina-realizan-encuentro-ciudadano-para-socializar-propuestas-de-politicas-publicas-para-el-fomento-de-la-agricultura-familiar\/","name":"DIGEPRES y Articulaci\u00f3n Nacional Campesina realizan Encuentro C.","isPartOf":{"@id":"https:\/\/digepres.gob.do\/#website"},"primaryImageOfPage":{"@id":"https:\/\/digepres.gob.do\/digepres-y-articulacion-nacional-campesina-realizan-encuentro-ciudadano-para-socializar-propuestas-de-politicas-publicas-para-el-fomento-de-la-agricultura-familiar\/#primaryimage"},"image":{"@id":"https:\/\/digepres.gob.do\/digepres-y-articulacion-nacional-campesina-realizan-encuentro-ciudadano-para-socializar-propuestas-de-politicas-publicas-para-el-fomento-de-la-agricultura-familiar\/#primaryimage"},"thumbnailUrl":"https:\/\/digepres.gob.do\/wp-content\/uploads\/2025\/09\/DIGEPRES-y-Articulacion-Nacional-Campesina-realizan-Encuentro-Ciudadano-para-socializar-propuestas-de-politicas-publicas-para-el-fomento-de-la-agricultura-familiar-1.jpg","datePublished":"2025-07-15T19:05:40+00:00","dateModified":"2025-09-15T14:31:04+00:00","author":{"@id":"https:\/\/digepres.gob.do\/#\/schema\/person\/f6f6885c1078d1d53221d15413ab38b5"},"description":"DIGEPRES y Articulaci\u00f3n Nacional Campesina realizan Encuentro Ciudadano para socializar propuestas de pol\u00edticas p\u00fablicas para el fomento de la agricultura..","breadcrumb":{"@id":"https:\/\/digepres.gob.do\/digepres-y-articulacion-nacional-campesina-realizan-encuentro-ciudadano-para-socializar-propuestas-de-politicas-publicas-para-el-fomento-de-la-agricultura-familiar\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/digepres.gob.do\/digepres-y-articulacion-nacional-campesina-realizan-encuentro-ciudadano-para-socializar-propuestas-de-politicas-publicas-para-el-fomento-de-la-agricultura-familiar\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/digepres.gob.do\/digepres-y-articulacion-nacional-campesina-realizan-encuentro-ciudadano-para-socializar-propuestas-de-politicas-publicas-para-el-fomento-de-la-agricultura-familiar\/#primaryimage","url":"https:\/\/digepres.gob.do\/wp-content\/uploads\/2025\/09\/DIGEPRES-y-Articulacion-Nacional-Campesina-realizan-Encuentro-Ciudadano-para-socializar-propuestas-de-politicas-publicas-para-el-fomento-de-la-agricultura-familiar-1.jpg","contentUrl":"https:\/\/digepres.gob.do\/wp-content\/uploads\/2025\/09\/DIGEPRES-y-Articulacion-Nacional-Campesina-realizan-Encuentro-Ciudadano-para-socializar-propuestas-de-politicas-publicas-para-el-fomento-de-la-agricultura-familiar-1.jpg","width":2560,"height":1703},{"@type":"BreadcrumbList","@id":"https:\/\/digepres.gob.do\/digepres-y-articulacion-nacional-campesina-realizan-encuentro-ciudadano-para-socializar-propuestas-de-politicas-publicas-para-el-fomento-de-la-agricultura-familiar\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/digepres.gob.do\/"},{"@type":"ListItem","position":2,"name":"DIGEPRES y Articulaci\u00f3n Nacional Campesina realizan Encuentro Ciudadano para socializar propuestas de pol\u00edticas p\u00fablicas para el fomento de la agricultura familiar."}]},{"@type":"WebSite","@id":"https:\/\/digepres.gob.do\/#website","url":"https:\/\/digepres.gob.do\/","name":"Direcci\u00f3n General de Presupuesto - Rep\u00fablica Dominicana","description":"Somos el \u00d3rgano Rector del Sistema Presupuestario Dominicano por mandato de la Ley 423-06.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/digepres.gob.do\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/digepres.gob.do\/#\/schema\/person\/f6f6885c1078d1d53221d15413ab38b5","name":"Pablo Paez","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/e9d364ce257be032b8adf031185529d2677ad33d9298b62704d967cd574fa801?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/e9d364ce257be032b8adf031185529d2677ad33d9298b62704d967cd574fa801?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/e9d364ce257be032b8adf031185529d2677ad33d9298b62704d967cd574fa801?s=96&d=mm&r=g","caption":"Pablo Paez"},"url":"https:\/\/digepres.gob.do\/en\/author\/ppaez\/"}]}},"_links":{"self":[{"href":"https:\/\/digepres.gob.do\/en\/wp-json\/wp\/v2\/posts\/40022","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/digepres.gob.do\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/digepres.gob.do\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/digepres.gob.do\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/digepres.gob.do\/en\/wp-json\/wp\/v2\/comments?post=40022"}],"version-history":[{"count":1,"href":"https:\/\/digepres.gob.do\/en\/wp-json\/wp\/v2\/posts\/40022\/revisions"}],"predecessor-version":[{"id":40370,"href":"https:\/\/digepres.gob.do\/en\/wp-json\/wp\/v2\/posts\/40022\/revisions\/40370"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/digepres.gob.do\/en\/wp-json\/wp\/v2\/media\/40397"}],"wp:attachment":[{"href":"https:\/\/digepres.gob.do\/en\/wp-json\/wp\/v2\/media?parent=40022"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/digepres.gob.do\/en\/wp-json\/wp\/v2\/categories?post=40022"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/digepres.gob.do\/en\/wp-json\/wp\/v2\/tags?post=40022"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}