
{"id":37935,"date":"2024-10-22T16:06:44","date_gmt":"2024-10-22T20:06:44","guid":{"rendered":"https:\/\/www.digepres.gob.do\/?p=37935"},"modified":"2025-09-15T08:49:34","modified_gmt":"2025-09-15T12:49:34","slug":"director-de-presupuesto-realiza-encuentro-ciudadano-con-estudiantes-y-profesores-de-la-uasd-en-hato-mayor","status":"publish","type":"post","link":"https:\/\/digepres.gob.do\/en\/director-de-presupuesto-realiza-encuentro-ciudadano-con-estudiantes-y-profesores-de-la-uasd-en-hato-mayor\/","title":{"rendered":"Director de Presupuesto realiza Encuentro Ciudadano con estudiantes y profesores de la UASD en Hato Mayor"},"content":{"rendered":"<p>\t\t\t\tRijo Presbot destac\u00f3 varios proyectos de inversi\u00f3n p\u00fablica que est\u00e1 llevando a cabo el Gobierno en la provincia<\/p>\n<p>Hato Mayor. &#8211; La Direcci\u00f3n General de Presupuesto<a href=\"https:\/\/digepres.gob.do\/en\/\"> (Digepres)<\/a> llev\u00f3 a cabo un Encuentro Ciudadano en la sede de la Universidad Aut\u00f3noma de Santo Domingo <a href=\"https:\/\/uasd.edu.do\/\">(UASD)<\/a> de la provincia Hato Mayor. El evento estuvo dirigido a estudiantes, profesores y ciudadanos interesados en conocer la formulaci\u00f3n y las distintas etapas del Presupuesto General del Estado (PGE), as\u00ed como el <a href=\"https:\/\/digepres.gob.do\/en\/presupuesto\/gobierno-general-nacional\/proyecto-de-ley-de-presupuesto-2025-2\/\">proyecto de Ley de Presupuesto para el a\u00f1o 2025<\/a> sometido ante el Congreso Nacional para su discusi\u00f3n y aprobaci\u00f3n.<\/p>\n<p>Jos\u00e9 Rijo Presbot, director general de Presupuesto, lider\u00f3 el evento que se enfoc\u00f3 en analizar el presupuesto p\u00fablico desde una perspectiva t\u00e9cnica, jur\u00eddica, pol\u00edtica, destacando adem\u00e1s en su presentaci\u00f3n, la importancia del derecho a saber, fundamental en una sociedad democr\u00e1tica y participativa.<\/p>\n<p>En la actividad, acompa\u00f1aron al director de Presupuesto, Eloy Bastardo, en representaci\u00f3n \u00c1ngel Erich Cedano Cabrera, director de UASD-Hato Mayor; Maribel Sim\u00f3n de Reyes, gobernadora provincial de Hato Mayor; Francisco Solano Hern\u00e1ndez, alcalde municipal de Sabana de la Mar, as\u00ed como, representantes de la UASD.<\/p>\n<p>Al comenzar su exposici\u00f3n, Rijo Presbot explic\u00f3 de manera detallada las normas y principios democr\u00e1ticos necesarios para el buen funcionamiento del Estado. En su intervenci\u00f3n, subray\u00f3 que el PGE busca distribuir los recursos p\u00fablicos para responder a las demandas sociales del pa\u00eds<em>. \u201cContamos con voluntad pol\u00edtica para que las cosas se hagan como deben de ser\u201d,<\/em><em>\u00a0<\/em>destac\u00f3 Rijo Presbot.<\/p>\n<div class=\"wp-block-image\"><img fetchpriority=\"high\" decoding=\"async\" class=\"wpa-warning wpa-image-missing-alt alignright wp-image-37937\" src=\"https:\/\/www.digepres.gob.do\/wp-content\/uploads\/2024\/10\/WhatsApp-Image-2024-10-22-at-1.36.39-PM-1-300x200.jpeg\" alt=\"Director de Presupuesto realiza\" width=\"368\" height=\"245\" data-warning=\"Falta el texto alternativo\" \/><\/div>\n<p>Durante su discurso, Rijo subray\u00f3 la importancia, adem\u00e1s, del Sistema Integrado de Administraci\u00f3n Financiera del Estado (SIAFE), destacando su funci\u00f3n en asegurar la alineaci\u00f3n adecuada entre el Presupuesto y el Plan Nacional de Desarrollo.<\/p>\n<p>Rijo Presbot al explicar los detalles del proceso de formulaci\u00f3n y etapas del PGE dijo que el \u00e9xito de su implementaci\u00f3n, depende de una adecuada planificaci\u00f3n financiera relacionada a los objetivos y metas establecidos enfocados bajo una l\u00f3gica democr\u00e1tica que incluye la participaci\u00f3n ciudadana, representaci\u00f3n pol\u00edtica, transparencia y rendici\u00f3n de cuentas, equidad y responsabilidad fiscal. \u201c<em>La l\u00f3gica democr\u00e1tica del presupuesto se basa en la idea de que los recursos p\u00fablicos deben ser gestionados de manera transparente, equitativa y conforme a las necesidades y prioridades de la sociedad, representadas a trav\u00e9s de los mecanismos de participaci\u00f3n ciudadana y las instituciones del Estado\u201d<\/em>, destac\u00f3 Rijo Presbot durante el Encuentro Ciudadano.<\/p>\n<p>El director de Presupuesto trat\u00f3 diversos temas, entre los cuales se incluyeron los impactos de los shocks externos negativos en el PGE, vinculaci\u00f3n del plan presupuestario con un enfoque en resultados, el crecimiento econ\u00f3mico, la inflaci\u00f3n y el gasto social, entre otros aspectos. En su exposici\u00f3n, el director abord\u00f3 tambi\u00e9n el impacto de los conflictos internacionales en la econom\u00eda local, haciendo referencia a los subsidios a los combustibles como una medida clave para contener la inflaci\u00f3n y mitigar los efectos de la crisis global<em>.<\/em><em>\u00a0<\/em><\/p>\n<p><strong>Proyectos de inversi\u00f3n provincia Hato Mayor<\/strong><\/p>\n<p>En el Encuentro Ciudadano, Rijo Presbot dio a conocer varios proyectos de inversi\u00f3n que est\u00e1 llevando a cabo el Gobierno, as\u00ed como otros que est\u00e1n en planificaci\u00f3n. Entre estos proyectos, resalt\u00f3 la construcci\u00f3n del puente sobre el r\u00edo Guamira, un puente mixto sobre el r\u00edo Pa\u00f1a Pa\u00f1a, la extensi\u00f3n de la Universidad Aut\u00f3noma de Santo Domingo (UASD) y la ampliaci\u00f3n de las instalaciones educativas para la educaci\u00f3n inicial en Francisco del Rosario S\u00e1nchez y Monte Coca, entre otras obras de infraestructura.<\/p>\n<p>Los Encuentros Ciudadanos son espacios que fomentan la participaci\u00f3n y el di\u00e1logo, reflejando el compromiso de esta gesti\u00f3n por fortalecer la participaci\u00f3n p\u00fablica en todas las fases del ciclo presupuestario. Con ello, se busca mejorar los niveles de transparencia y fomentar el control social.<\/p>\n<p>&nbsp;\t\t<\/p>","protected":false},"excerpt":{"rendered":"<p>Rijo Presbot destac\u00f3 varios proyectos de inversi\u00f3n p\u00fablica que est\u00e1 llevando a cabo el Gobierno en la provincia Hato Mayor. &#8211; La Direcci\u00f3n General de Presupuesto (Digepres) llev\u00f3 a cabo un Encuentro Ciudadano en la sede de la Universidad Aut\u00f3noma de Santo Domingo (UASD) de la provincia Hato Mayor. El evento estuvo dirigido a estudiantes, profesores y ciudadanos interesados en conocer la formulaci\u00f3n y las distintas etapas del Presupuesto General del Estado (PGE), as\u00ed como el proyecto de Ley de Presupuesto para el a\u00f1o 2025 sometido ante el Congreso Nacional para su discusi\u00f3n y aprobaci\u00f3n. Jos\u00e9 Rijo Presbot, director general de Presupuesto, lider\u00f3 el evento que se enfoc\u00f3 en analizar el presupuesto p\u00fablico desde una perspectiva t\u00e9cnica, jur\u00eddica, pol\u00edtica, destacando adem\u00e1s en su presentaci\u00f3n, la importancia del derecho a saber, fundamental en una sociedad democr\u00e1tica y participativa. En la actividad, acompa\u00f1aron al director de Presupuesto, Eloy Bastardo, en representaci\u00f3n \u00c1ngel Erich Cedano Cabrera, director de UASD-Hato Mayor; Maribel Sim\u00f3n de Reyes, gobernadora provincial de Hato Mayor; Francisco Solano Hern\u00e1ndez, alcalde municipal de Sabana de la Mar, as\u00ed como, representantes de la UASD. Al comenzar su exposici\u00f3n, Rijo Presbot explic\u00f3 de manera detallada las normas y principios democr\u00e1ticos necesarios para el buen funcionamiento del Estado. En su intervenci\u00f3n, subray\u00f3 que el PGE busca distribuir los recursos p\u00fablicos para responder a las demandas sociales del pa\u00eds. \u201cContamos con voluntad pol\u00edtica para que las cosas se hagan como deben de ser\u201d,\u00a0destac\u00f3 Rijo Presbot. Durante su discurso, Rijo subray\u00f3 la importancia, adem\u00e1s, del Sistema Integrado de Administraci\u00f3n Financiera del Estado (SIAFE), destacando su funci\u00f3n en asegurar la alineaci\u00f3n adecuada entre el Presupuesto y el Plan Nacional de Desarrollo. Rijo Presbot al explicar los detalles del proceso de formulaci\u00f3n y etapas del PGE dijo que el \u00e9xito de su implementaci\u00f3n, depende de una adecuada planificaci\u00f3n financiera relacionada a los objetivos y metas establecidos enfocados bajo una l\u00f3gica democr\u00e1tica que incluye la participaci\u00f3n ciudadana, representaci\u00f3n pol\u00edtica, transparencia y rendici\u00f3n de cuentas, equidad y responsabilidad fiscal. \u201cLa l\u00f3gica democr\u00e1tica del presupuesto se basa en la idea de que los recursos p\u00fablicos deben ser gestionados de manera transparente, equitativa y conforme a las necesidades y prioridades de la sociedad, representadas a trav\u00e9s de los mecanismos de participaci\u00f3n ciudadana y las instituciones del Estado\u201d, destac\u00f3 Rijo Presbot durante el Encuentro Ciudadano. El director de Presupuesto trat\u00f3 diversos temas, entre los cuales se incluyeron los impactos de los shocks externos negativos en el PGE, vinculaci\u00f3n del plan presupuestario con un enfoque en resultados, el crecimiento econ\u00f3mico, la inflaci\u00f3n y el gasto social, entre otros aspectos. En su exposici\u00f3n, el director abord\u00f3 tambi\u00e9n el impacto de los conflictos internacionales en la econom\u00eda local, haciendo referencia a los subsidios a los combustibles como una medida clave para contener la inflaci\u00f3n y mitigar los efectos de la crisis global.\u00a0 Proyectos de inversi\u00f3n provincia Hato Mayor En el Encuentro Ciudadano, Rijo Presbot dio a conocer varios proyectos de inversi\u00f3n que est\u00e1 llevando a cabo el Gobierno, as\u00ed como otros que est\u00e1n en planificaci\u00f3n. Entre estos proyectos, resalt\u00f3 la construcci\u00f3n del puente sobre el r\u00edo Guamira, un puente mixto sobre el r\u00edo Pa\u00f1a Pa\u00f1a, la extensi\u00f3n de la Universidad Aut\u00f3noma de Santo Domingo (UASD) y la ampliaci\u00f3n de las instalaciones educativas para la educaci\u00f3n inicial en Francisco del Rosario S\u00e1nchez y Monte Coca, entre otras obras de infraestructura. Los Encuentros Ciudadanos son espacios que fomentan la participaci\u00f3n y el di\u00e1logo, reflejando el compromiso de esta gesti\u00f3n por fortalecer la participaci\u00f3n p\u00fablica en todas las fases del ciclo presupuestario. Con ello, se busca mejorar los niveles de transparencia y fomentar el control social. &nbsp;<\/p>","protected":false},"author":2,"featured_media":38344,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[],"class_list":["post-37935","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-institucionales"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Director de Presupuesto realiza Encuentro Ciudadano - DIGEPRES<\/title>\n<meta name=\"description\" content=\"Director de Presupuesto realiza Encuentro Ciudadano con estudiantes y profesores de la UASD en Hato Mayor, Rijo destac\u00f3 varios proyectos de inversi\u00f3n...\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/digepres.gob.do\/en\/director-de-presupuesto-realiza-encuentro-ciudadano-con-estudiantes-y-profesores-de-la-uasd-en-hato-mayor\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Director de Presupuesto realiza Encuentro Ciudadano - DIGEPRES\" \/>\n<meta property=\"og:description\" content=\"Director de Presupuesto realiza Encuentro Ciudadano con estudiantes y profesores de la UASD en Hato Mayor, Rijo destac\u00f3 varios proyectos de inversi\u00f3n...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/digepres.gob.do\/en\/director-de-presupuesto-realiza-encuentro-ciudadano-con-estudiantes-y-profesores-de-la-uasd-en-hato-mayor\/\" \/>\n<meta property=\"og:site_name\" content=\"Direcci\u00f3n General de Presupuesto - Rep\u00fablica Dominicana\" \/>\n<meta property=\"article:published_time\" content=\"2024-10-22T20:06:44+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-09-15T12:49:34+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/digepres.gob.do\/wp-content\/uploads\/2024\/10\/Director-de-Presupuesto-realiza-Encuentro-Ciudadano-con-estudiantes-y-profesores-de-la-UASD-en-Hato-Mayor.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"852\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Pablo Paez\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Pablo Paez\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/digepres.gob.do\\\/en\\\/director-de-presupuesto-realiza-encuentro-ciudadano-con-estudiantes-y-profesores-de-la-uasd-en-hato-mayor\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/digepres.gob.do\\\/en\\\/director-de-presupuesto-realiza-encuentro-ciudadano-con-estudiantes-y-profesores-de-la-uasd-en-hato-mayor\\\/\"},\"author\":{\"name\":\"Pablo Paez\",\"@id\":\"https:\\\/\\\/digepres.gob.do\\\/#\\\/schema\\\/person\\\/f6f6885c1078d1d53221d15413ab38b5\"},\"headline\":\"Director de Presupuesto realiza Encuentro Ciudadano con estudiantes y profesores de la UASD en Hato Mayor\",\"datePublished\":\"2024-10-22T20:06:44+00:00\",\"dateModified\":\"2025-09-15T12:49:34+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/digepres.gob.do\\\/en\\\/director-de-presupuesto-realiza-encuentro-ciudadano-con-estudiantes-y-profesores-de-la-uasd-en-hato-mayor\\\/\"},\"wordCount\":683,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/digepres.gob.do\\\/en\\\/director-de-presupuesto-realiza-encuentro-ciudadano-con-estudiantes-y-profesores-de-la-uasd-en-hato-mayor\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/digepres.gob.do\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/Director-de-Presupuesto-realiza-Encuentro-Ciudadano-con-estudiantes-y-profesores-de-la-UASD-en-Hato-Mayor.jpeg\",\"articleSection\":[\"Institucionales\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/digepres.gob.do\\\/en\\\/director-de-presupuesto-realiza-encuentro-ciudadano-con-estudiantes-y-profesores-de-la-uasd-en-hato-mayor\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/digepres.gob.do\\\/en\\\/director-de-presupuesto-realiza-encuentro-ciudadano-con-estudiantes-y-profesores-de-la-uasd-en-hato-mayor\\\/\",\"url\":\"https:\\\/\\\/digepres.gob.do\\\/en\\\/director-de-presupuesto-realiza-encuentro-ciudadano-con-estudiantes-y-profesores-de-la-uasd-en-hato-mayor\\\/\",\"name\":\"Director de Presupuesto realiza Encuentro Ciudadano - DIGEPRES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/digepres.gob.do\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/digepres.gob.do\\\/en\\\/director-de-presupuesto-realiza-encuentro-ciudadano-con-estudiantes-y-profesores-de-la-uasd-en-hato-mayor\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/digepres.gob.do\\\/en\\\/director-de-presupuesto-realiza-encuentro-ciudadano-con-estudiantes-y-profesores-de-la-uasd-en-hato-mayor\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/digepres.gob.do\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/Director-de-Presupuesto-realiza-Encuentro-Ciudadano-con-estudiantes-y-profesores-de-la-UASD-en-Hato-Mayor.jpeg\",\"datePublished\":\"2024-10-22T20:06:44+00:00\",\"dateModified\":\"2025-09-15T12:49:34+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/digepres.gob.do\\\/#\\\/schema\\\/person\\\/f6f6885c1078d1d53221d15413ab38b5\"},\"description\":\"Director de Presupuesto realiza Encuentro Ciudadano con estudiantes y profesores de la UASD en Hato Mayor, Rijo destac\u00f3 varios proyectos de inversi\u00f3n...\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/digepres.gob.do\\\/en\\\/director-de-presupuesto-realiza-encuentro-ciudadano-con-estudiantes-y-profesores-de-la-uasd-en-hato-mayor\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/digepres.gob.do\\\/en\\\/director-de-presupuesto-realiza-encuentro-ciudadano-con-estudiantes-y-profesores-de-la-uasd-en-hato-mayor\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/digepres.gob.do\\\/en\\\/director-de-presupuesto-realiza-encuentro-ciudadano-con-estudiantes-y-profesores-de-la-uasd-en-hato-mayor\\\/#primaryimage\",\"url\":\"https:\\\/\\\/digepres.gob.do\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/Director-de-Presupuesto-realiza-Encuentro-Ciudadano-con-estudiantes-y-profesores-de-la-UASD-en-Hato-Mayor.jpeg\",\"contentUrl\":\"https:\\\/\\\/digepres.gob.do\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/Director-de-Presupuesto-realiza-Encuentro-Ciudadano-con-estudiantes-y-profesores-de-la-UASD-en-Hato-Mayor.jpeg\",\"width\":1280,\"height\":852,\"caption\":\"Director de Presupuesto realiza Encuentro Ciudadano con estudiantes y profesores de la UASD en Hato Mayor\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/digepres.gob.do\\\/en\\\/director-de-presupuesto-realiza-encuentro-ciudadano-con-estudiantes-y-profesores-de-la-uasd-en-hato-mayor\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/digepres.gob.do\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Director de Presupuesto realiza Encuentro Ciudadano con estudiantes y profesores de la UASD en Hato Mayor\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/digepres.gob.do\\\/#website\",\"url\":\"https:\\\/\\\/digepres.gob.do\\\/\",\"name\":\"Direcci\u00f3n General de Presupuesto - Rep\u00fablica Dominicana\",\"description\":\"Somos el \u00d3rgano Rector del Sistema Presupuestario Dominicano por mandato de la Ley 423-06.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/digepres.gob.do\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/digepres.gob.do\\\/#\\\/schema\\\/person\\\/f6f6885c1078d1d53221d15413ab38b5\",\"name\":\"Pablo Paez\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e9d364ce257be032b8adf031185529d2677ad33d9298b62704d967cd574fa801?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e9d364ce257be032b8adf031185529d2677ad33d9298b62704d967cd574fa801?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e9d364ce257be032b8adf031185529d2677ad33d9298b62704d967cd574fa801?s=96&d=mm&r=g\",\"caption\":\"Pablo Paez\"},\"url\":\"https:\\\/\\\/digepres.gob.do\\\/en\\\/author\\\/ppaez\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Director de Presupuesto realiza Encuentro Ciudadano - DIGEPRES","description":"Director de Presupuesto realiza Encuentro Ciudadano con estudiantes y profesores de la UASD en Hato Mayor, Rijo destac\u00f3 varios proyectos de inversi\u00f3n...","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/digepres.gob.do\/en\/director-de-presupuesto-realiza-encuentro-ciudadano-con-estudiantes-y-profesores-de-la-uasd-en-hato-mayor\/","og_locale":"en_US","og_type":"article","og_title":"Director de Presupuesto realiza Encuentro Ciudadano - DIGEPRES","og_description":"Director de Presupuesto realiza Encuentro Ciudadano con estudiantes y profesores de la UASD en Hato Mayor, Rijo destac\u00f3 varios proyectos de inversi\u00f3n...","og_url":"https:\/\/digepres.gob.do\/en\/director-de-presupuesto-realiza-encuentro-ciudadano-con-estudiantes-y-profesores-de-la-uasd-en-hato-mayor\/","og_site_name":"Direcci\u00f3n General de Presupuesto - Rep\u00fablica Dominicana","article_published_time":"2024-10-22T20:06:44+00:00","article_modified_time":"2025-09-15T12:49:34+00:00","og_image":[{"width":1280,"height":852,"url":"https:\/\/digepres.gob.do\/wp-content\/uploads\/2024\/10\/Director-de-Presupuesto-realiza-Encuentro-Ciudadano-con-estudiantes-y-profesores-de-la-UASD-en-Hato-Mayor.jpeg","type":"image\/jpeg"}],"author":"Pablo Paez","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Pablo Paez","Est. reading time":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/digepres.gob.do\/en\/director-de-presupuesto-realiza-encuentro-ciudadano-con-estudiantes-y-profesores-de-la-uasd-en-hato-mayor\/#article","isPartOf":{"@id":"https:\/\/digepres.gob.do\/en\/director-de-presupuesto-realiza-encuentro-ciudadano-con-estudiantes-y-profesores-de-la-uasd-en-hato-mayor\/"},"author":{"name":"Pablo Paez","@id":"https:\/\/digepres.gob.do\/#\/schema\/person\/f6f6885c1078d1d53221d15413ab38b5"},"headline":"Director de Presupuesto realiza Encuentro Ciudadano con estudiantes y profesores de la UASD en Hato Mayor","datePublished":"2024-10-22T20:06:44+00:00","dateModified":"2025-09-15T12:49:34+00:00","mainEntityOfPage":{"@id":"https:\/\/digepres.gob.do\/en\/director-de-presupuesto-realiza-encuentro-ciudadano-con-estudiantes-y-profesores-de-la-uasd-en-hato-mayor\/"},"wordCount":683,"commentCount":0,"image":{"@id":"https:\/\/digepres.gob.do\/en\/director-de-presupuesto-realiza-encuentro-ciudadano-con-estudiantes-y-profesores-de-la-uasd-en-hato-mayor\/#primaryimage"},"thumbnailUrl":"https:\/\/digepres.gob.do\/wp-content\/uploads\/2024\/10\/Director-de-Presupuesto-realiza-Encuentro-Ciudadano-con-estudiantes-y-profesores-de-la-UASD-en-Hato-Mayor.jpeg","articleSection":["Institucionales"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/digepres.gob.do\/en\/director-de-presupuesto-realiza-encuentro-ciudadano-con-estudiantes-y-profesores-de-la-uasd-en-hato-mayor\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/digepres.gob.do\/en\/director-de-presupuesto-realiza-encuentro-ciudadano-con-estudiantes-y-profesores-de-la-uasd-en-hato-mayor\/","url":"https:\/\/digepres.gob.do\/en\/director-de-presupuesto-realiza-encuentro-ciudadano-con-estudiantes-y-profesores-de-la-uasd-en-hato-mayor\/","name":"Director de Presupuesto realiza Encuentro Ciudadano - DIGEPRES","isPartOf":{"@id":"https:\/\/digepres.gob.do\/#website"},"primaryImageOfPage":{"@id":"https:\/\/digepres.gob.do\/en\/director-de-presupuesto-realiza-encuentro-ciudadano-con-estudiantes-y-profesores-de-la-uasd-en-hato-mayor\/#primaryimage"},"image":{"@id":"https:\/\/digepres.gob.do\/en\/director-de-presupuesto-realiza-encuentro-ciudadano-con-estudiantes-y-profesores-de-la-uasd-en-hato-mayor\/#primaryimage"},"thumbnailUrl":"https:\/\/digepres.gob.do\/wp-content\/uploads\/2024\/10\/Director-de-Presupuesto-realiza-Encuentro-Ciudadano-con-estudiantes-y-profesores-de-la-UASD-en-Hato-Mayor.jpeg","datePublished":"2024-10-22T20:06:44+00:00","dateModified":"2025-09-15T12:49:34+00:00","author":{"@id":"https:\/\/digepres.gob.do\/#\/schema\/person\/f6f6885c1078d1d53221d15413ab38b5"},"description":"Director de Presupuesto realiza Encuentro Ciudadano con estudiantes y profesores de la UASD en Hato Mayor, Rijo destac\u00f3 varios proyectos de inversi\u00f3n...","breadcrumb":{"@id":"https:\/\/digepres.gob.do\/en\/director-de-presupuesto-realiza-encuentro-ciudadano-con-estudiantes-y-profesores-de-la-uasd-en-hato-mayor\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/digepres.gob.do\/en\/director-de-presupuesto-realiza-encuentro-ciudadano-con-estudiantes-y-profesores-de-la-uasd-en-hato-mayor\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/digepres.gob.do\/en\/director-de-presupuesto-realiza-encuentro-ciudadano-con-estudiantes-y-profesores-de-la-uasd-en-hato-mayor\/#primaryimage","url":"https:\/\/digepres.gob.do\/wp-content\/uploads\/2024\/10\/Director-de-Presupuesto-realiza-Encuentro-Ciudadano-con-estudiantes-y-profesores-de-la-UASD-en-Hato-Mayor.jpeg","contentUrl":"https:\/\/digepres.gob.do\/wp-content\/uploads\/2024\/10\/Director-de-Presupuesto-realiza-Encuentro-Ciudadano-con-estudiantes-y-profesores-de-la-UASD-en-Hato-Mayor.jpeg","width":1280,"height":852,"caption":"Director de Presupuesto realiza Encuentro Ciudadano con estudiantes y profesores de la UASD en Hato Mayor"},{"@type":"BreadcrumbList","@id":"https:\/\/digepres.gob.do\/en\/director-de-presupuesto-realiza-encuentro-ciudadano-con-estudiantes-y-profesores-de-la-uasd-en-hato-mayor\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/digepres.gob.do\/"},{"@type":"ListItem","position":2,"name":"Director de Presupuesto realiza Encuentro Ciudadano con estudiantes y profesores de la UASD en Hato Mayor"}]},{"@type":"WebSite","@id":"https:\/\/digepres.gob.do\/#website","url":"https:\/\/digepres.gob.do\/","name":"Direcci\u00f3n General de Presupuesto - Rep\u00fablica Dominicana","description":"Somos el \u00d3rgano Rector del Sistema Presupuestario Dominicano por mandato de la Ley 423-06.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/digepres.gob.do\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/digepres.gob.do\/#\/schema\/person\/f6f6885c1078d1d53221d15413ab38b5","name":"Pablo Paez","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/e9d364ce257be032b8adf031185529d2677ad33d9298b62704d967cd574fa801?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/e9d364ce257be032b8adf031185529d2677ad33d9298b62704d967cd574fa801?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/e9d364ce257be032b8adf031185529d2677ad33d9298b62704d967cd574fa801?s=96&d=mm&r=g","caption":"Pablo Paez"},"url":"https:\/\/digepres.gob.do\/en\/author\/ppaez\/"}]}},"_links":{"self":[{"href":"https:\/\/digepres.gob.do\/en\/wp-json\/wp\/v2\/posts\/37935","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/digepres.gob.do\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/digepres.gob.do\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/digepres.gob.do\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/digepres.gob.do\/en\/wp-json\/wp\/v2\/comments?post=37935"}],"version-history":[{"count":1,"href":"https:\/\/digepres.gob.do\/en\/wp-json\/wp\/v2\/posts\/37935\/revisions"}],"predecessor-version":[{"id":38346,"href":"https:\/\/digepres.gob.do\/en\/wp-json\/wp\/v2\/posts\/37935\/revisions\/38346"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/digepres.gob.do\/en\/wp-json\/wp\/v2\/media\/38344"}],"wp:attachment":[{"href":"https:\/\/digepres.gob.do\/en\/wp-json\/wp\/v2\/media?parent=37935"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/digepres.gob.do\/en\/wp-json\/wp\/v2\/categories?post=37935"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/digepres.gob.do\/en\/wp-json\/wp\/v2\/tags?post=37935"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}