
{"id":35843,"date":"2024-06-26T11:24:11","date_gmt":"2024-06-26T15:24:11","guid":{"rendered":"https:\/\/www.digepres.gob.do\/?p=35843"},"modified":"2025-09-15T09:25:17","modified_gmt":"2025-09-15T13:25:17","slug":"fundacion-solidaridad-entrega-resultados","status":"publish","type":"post","link":"https:\/\/digepres.gob.do\/en\/fundacion-solidaridad-entrega-resultados\/","title":{"rendered":"Fundaci\u00f3n Solidaridad presents results of the Open Budget Survey: Dominican Republic ranks number 1 in the continent in public budget participation"},"content":{"rendered":"<p>\t\t\t\tLa Encuesta Presupuesto Abierto, de la International Budget Partnership, indica que el pa\u00eds registr\u00f3 un aumento de 22 puntos, con relaci\u00f3n a la calificaci\u00f3n del 2021<\/p>\n<p>En el marco de un Encuentro Ciudadano con Presupuesto, la Fundaci\u00f3n Solidaridad, organizaci\u00f3n que representa en el pa\u00eds a International Budget Partnership, entreg\u00f3 a la Direcci\u00f3n General de Presupuesto (<a href=\"https:\/\/digepres.gob.do\/en\/\">Digepres<\/a>) los resultados pa\u00eds de la edici\u00f3n 2023 de la Encuesta Presupuesto Abierto, en la que Rep\u00fablica Dominicana obtuvo una puntuaci\u00f3n de 48 puntos en Participaci\u00f3n P\u00fablica, duplicando la evaluaci\u00f3n del a\u00f1o 2021. En esta versi\u00f3n la Encuesta Presupuesto Abierto Rep\u00fablica Dominicana de La International Budget Partnership <a href=\"https:\/\/internationalbudget.org\/\">(IBP)<\/a> los resultados ubican al pa\u00eds en el cuarto puesto a nivel mundial dentro de 125 pa\u00edses y el primer lugar entre los pa\u00edses de Am\u00e9rica Latina y El Caribe, seg\u00fan datos de la Encuesta Presupuesto Abierto Rep\u00fablica Dominicana de La International Budget Partnership <a href=\"https:\/\/internationalbudget.org\/\">(IBP)<\/a>.<img fetchpriority=\"high\" decoding=\"async\" class=\"wp-image-35845 alignright\" src=\"https:\/\/www.digepres.gob.do\/wp-content\/uploads\/2024\/06\/WhatsApp-Image-2024-06-26-at-10.53.01-AM-300x199.jpeg\" alt=\"\" width=\"317\" height=\"210\" \/><\/p>\n<p>La Encuesta tambi\u00e9n indica que Rep\u00fablica Dominicana aument\u00f3 de 22 puntos, en 2021, a 48 en 2023, registrando un incremento de 26 puntos entre ambas mediciones, datos que fueron socializados durante la entrega formal del documento a la Direcci\u00f3n General de Presupuesto. La Encuesta de Presupuesto Abierto <a href=\"https:\/\/internationalbudget.org\/open-budget-survey\/\">(Open Budget Survey OBS)<\/a> es el resultado de una investigaci\u00f3n colaborativa entre la Asociaci\u00f3n Internacional de Presupuesto (International Budget Partnership, IBP) y organizaciones de la sociedad civil en 125 pa\u00edses, representando diversas regiones y niveles de ingresos durante un periodo de 16 meses.<\/p>\n<p>La actividad estuvo encabezada por Jos\u00e9 Rijo Presbot, director general de Presupuesto; Iv\u00e1n Ram\u00edrez, subdirector general de Presupuesto; Milagros Ort\u00edz Bosch; directora de la Direcci\u00f3n General de \u00c9tica e Integridad Gubernamental <a href=\"https:\/\/www.digeig.gob.do\/\">(DIGEIG)<\/a>; R\u00f3mulo Arias Moscat, director general de Contabilidad Gubernamental; Derby de los Santos, viceministro del Tesoro; Camila Hern\u00e1ndez Villam\u00e1n; encargada del Departamento de Estudios Fiscales de la Direcci\u00f3n General de An\u00e1lisis y Pol\u00edtica Fiscal del Ministerio de Hacienda; Juan Carlos Arguelles, director de gesti\u00f3n del Sistema Integrado de Administraci\u00f3n Financiera del Estado <a href=\"https:\/\/www.transparenciafiscal.gob.do\/siafe\/sigef\">(SIAFE)<\/a>; Mart\u00edn Zapata S\u00e1nchez, viceministro de la Direcci\u00f3n General de Pol\u00edticas y Legislaci\u00f3n Tributaria; Juan Castillo y Katia Lambis, director ejecutivo e investigadora, respectivamente, de Fundaci\u00f3n Solidaridad.<\/p>\n<p><img decoding=\"async\" class=\"wp-image-35847 alignleft\" src=\"https:\/\/www.digepres.gob.do\/wp-content\/uploads\/2024\/06\/WhatsApp-Image-2024-06-26-at-10.53.01-AM-2-300x199.jpeg\" alt=\"\" width=\"344\" height=\"228\" \/>Rafael Jovine, director de Estudios Econ\u00f3micos y Seguimiento Financiero de Presupuesto, en las palabras de introducci\u00f3n al evento explic\u00f3 que el Encuentro busc\u00f3 fortalecer m\u00e1s la transparencia, control social y rendici\u00f3n de cuentas sobre la gobernanza fiscal del pa\u00eds y el Presupuesto General del Estado de cara a la ciudadan\u00eda.<\/p>\n<p>De su lado, Juan Castillo, de Fundaci\u00f3n Solidaridad, explic\u00f3 que la Encuesta de Presupuesto Abierto cuenta con tres pilares fundamentales, transparencia, participaci\u00f3n y vigilancia. \u201cLa transparencia ayuda al p\u00fablico a comprender las prioridades presupuestarias del Gobierno; la vigilancia formal del presupuesto por parte del poder legislativo gu\u00eda y examina las opciones presupuestarias, mientras, las entidades fiscalizadoras eval\u00faan la legalidad, eficiencia y efectividad del gasto p\u00fablico\u201d, resalt\u00f3 Castillo al socializar la informaci\u00f3n de la Encuesta.<\/p>\n<p>Milagros Ort\u00edz Bosch, directora de la <a href=\"https:\/\/www.digeig.gob.do\/\">DIGEIG<\/a> en su intervenci\u00f3n dijo es altamente gratificante recibir esa evaluaci\u00f3n internacional de la International Budget Partnership, una muestra de que el pa\u00eds sigue avanzando en materia de transparencia y participaci\u00f3n p\u00fablica. \u201cEstamos trabajando bien y estos n\u00fameros en crecimiento lo acreditan\u201d, afirm\u00f3 Ort\u00edz Bosch. Asimismo, dijo que para que esto siga en este ritmo, los ciudadanos deben demandar, se apliquen las leyes.<\/p>\n<p>En las palabras de cierre, Jos\u00e9 Rijo Presbot, manifest\u00f3 el inter\u00e9s del Gobierno de seguir fortaleciendo y empoderando a la ciudadan\u00eda para juntos construir la sociedad que todos queremos.<\/p>\n<p>Presupuesto transparente y participativo<img decoding=\"async\" class=\"alignright wp-image-35846\" src=\"https:\/\/www.digepres.gob.do\/wp-content\/uploads\/2024\/06\/WhatsApp-Image-2024-06-26-at-10.53.01-AM-1-300x199.jpeg\" alt=\"Fundaci\u00f3n Solidaridad entrega resultados\" width=\"380\" height=\"252\" \/><\/p>\n<p>La Encuesta de Presupuesto Abierto de la International Budget Partnership (IBP) es la \u00fanica medida comparativa e independiente de transparencia presupuestaria a nivel mundial, utilizada regularmente por gobiernos, agencias donantes y organizaciones de la sociedad civil para informar sobre reformas presupuestarias y otros temas.<\/p>\n<p>Desde agosto del 2020, la Direcci\u00f3n General de Presupuesto ha implementado medidas y proyectos novedosos que buscan impulsar y fortalecer la transparencia, el control social y la participaci\u00f3n de la ciudadan\u00eda en el ciclo presupuestario. Por primera vez en la historia, desde Digepres, se publica el reporte semanal de la ejecuci\u00f3n presupuestaria, que detalla de manera desagregada el manejo de los recursos p\u00fablicos desde el Gobierno central y que se actualiza al cierre de cada semana todos los martes.<\/p>\n<p>Adem\u00e1s, en un esfuerzo por acercar el Presupuesto a la ciudadan\u00eda, se realizan estos Encuentros Ciudadanos en los que se abordan temas del Presupuesto General del Estado, su formulaci\u00f3n, aprobaci\u00f3n, ejecuci\u00f3n y seguimiento, de manera abierta con distintos sectores de la sociedad civil.<\/p>\n<p>Presupuesto dispone del portal institucional <a href=\"https:\/\/digepres.gob.do\/en\/\">Digepres.gob.do<\/a> y sus redes sociales <a href=\"https:\/\/www.instagram.com\/digepresrd\/\">@DigepresRD<\/a> para poner a la disposici\u00f3n de los ciudadanos toda la informaci\u00f3n presupuestaria.\t\t<\/p>","protected":false},"excerpt":{"rendered":"<p>La Encuesta Presupuesto Abierto, de la International Budget Partnership, indica que el pa\u00eds registr\u00f3 un aumento de 22 puntos, con relaci\u00f3n a la calificaci\u00f3n del 2021 En el marco de un Encuentro Ciudadano con Presupuesto, la Fundaci\u00f3n Solidaridad, organizaci\u00f3n que representa en el pa\u00eds a International Budget Partnership, entreg\u00f3 a la Direcci\u00f3n General de Presupuesto (Digepres) los resultados pa\u00eds de la edici\u00f3n 2023 de la Encuesta Presupuesto Abierto, en la que Rep\u00fablica Dominicana obtuvo una puntuaci\u00f3n de 48 puntos en Participaci\u00f3n P\u00fablica, duplicando la evaluaci\u00f3n del a\u00f1o 2021. En esta versi\u00f3n la Encuesta Presupuesto Abierto Rep\u00fablica Dominicana de La International Budget Partnership (IBP) los resultados ubican al pa\u00eds en el cuarto puesto a nivel mundial dentro de 125 pa\u00edses y el primer lugar entre los pa\u00edses de Am\u00e9rica Latina y El Caribe, seg\u00fan datos de la Encuesta Presupuesto Abierto Rep\u00fablica Dominicana de La International Budget Partnership (IBP). La Encuesta tambi\u00e9n indica que Rep\u00fablica Dominicana aument\u00f3 de 22 puntos, en 2021, a 48 en 2023, registrando un incremento de 26 puntos entre ambas mediciones, datos que fueron socializados durante la entrega formal del documento a la Direcci\u00f3n General de Presupuesto. La Encuesta de Presupuesto Abierto (Open Budget Survey OBS) es el resultado de una investigaci\u00f3n colaborativa entre la Asociaci\u00f3n Internacional de Presupuesto (International Budget Partnership, IBP) y organizaciones de la sociedad civil en 125 pa\u00edses, representando diversas regiones y niveles de ingresos durante un periodo de 16 meses. La actividad estuvo encabezada por Jos\u00e9 Rijo Presbot, director general de Presupuesto; Iv\u00e1n Ram\u00edrez, subdirector general de Presupuesto; Milagros Ort\u00edz Bosch; directora de la Direcci\u00f3n General de \u00c9tica e Integridad Gubernamental (DIGEIG); R\u00f3mulo Arias Moscat, director general de Contabilidad Gubernamental; Derby de los Santos, viceministro del Tesoro; Camila Hern\u00e1ndez Villam\u00e1n; encargada del Departamento de Estudios Fiscales de la Direcci\u00f3n General de An\u00e1lisis y Pol\u00edtica Fiscal del Ministerio de Hacienda; Juan Carlos Arguelles, director de gesti\u00f3n del Sistema Integrado de Administraci\u00f3n Financiera del Estado (SIAFE); Mart\u00edn Zapata S\u00e1nchez, viceministro de la Direcci\u00f3n General de Pol\u00edticas y Legislaci\u00f3n Tributaria; Juan Castillo y Katia Lambis, director ejecutivo e investigadora, respectivamente, de Fundaci\u00f3n Solidaridad. Rafael Jovine, director de Estudios Econ\u00f3micos y Seguimiento Financiero de Presupuesto, en las palabras de introducci\u00f3n al evento explic\u00f3 que el Encuentro busc\u00f3 fortalecer m\u00e1s la transparencia, control social y rendici\u00f3n de cuentas sobre la gobernanza fiscal del pa\u00eds y el Presupuesto General del Estado de cara a la ciudadan\u00eda. De su lado, Juan Castillo, de Fundaci\u00f3n Solidaridad, explic\u00f3 que la Encuesta de Presupuesto Abierto cuenta con tres pilares fundamentales, transparencia, participaci\u00f3n y vigilancia. \u201cLa transparencia ayuda al p\u00fablico a comprender las prioridades presupuestarias del Gobierno; la vigilancia formal del presupuesto por parte del poder legislativo gu\u00eda y examina las opciones presupuestarias, mientras, las entidades fiscalizadoras eval\u00faan la legalidad, eficiencia y efectividad del gasto p\u00fablico\u201d, resalt\u00f3 Castillo al socializar la informaci\u00f3n de la Encuesta. Milagros Ort\u00edz Bosch, directora de la DIGEIG en su intervenci\u00f3n dijo es altamente gratificante recibir esa evaluaci\u00f3n internacional de la International Budget Partnership, una muestra de que el pa\u00eds sigue avanzando en materia de transparencia y participaci\u00f3n p\u00fablica. \u201cEstamos trabajando bien y estos n\u00fameros en crecimiento lo acreditan\u201d, afirm\u00f3 Ort\u00edz Bosch. Asimismo, dijo que para que esto siga en este ritmo, los ciudadanos deben demandar, se apliquen las leyes. En las palabras de cierre, Jos\u00e9 Rijo Presbot, manifest\u00f3 el inter\u00e9s del Gobierno de seguir fortaleciendo y empoderando a la ciudadan\u00eda para juntos construir la sociedad que todos queremos. Presupuesto transparente y participativo La Encuesta de Presupuesto Abierto de la International Budget Partnership (IBP) es la \u00fanica medida comparativa e independiente de transparencia presupuestaria a nivel mundial, utilizada regularmente por gobiernos, agencias donantes y organizaciones de la sociedad civil para informar sobre reformas presupuestarias y otros temas. Desde agosto del 2020, la Direcci\u00f3n General de Presupuesto ha implementado medidas y proyectos novedosos que buscan impulsar y fortalecer la transparencia, el control social y la participaci\u00f3n de la ciudadan\u00eda en el ciclo presupuestario. Por primera vez en la historia, desde Digepres, se publica el reporte semanal de la ejecuci\u00f3n presupuestaria, que detalla de manera desagregada el manejo de los recursos p\u00fablicos desde el Gobierno central y que se actualiza al cierre de cada semana todos los martes. Adem\u00e1s, en un esfuerzo por acercar el Presupuesto a la ciudadan\u00eda, se realizan estos Encuentros Ciudadanos en los que se abordan temas del Presupuesto General del Estado, su formulaci\u00f3n, aprobaci\u00f3n, ejecuci\u00f3n y seguimiento, de manera abierta con distintos sectores de la sociedad civil. Presupuesto dispone del portal institucional Digepres.gob.do y sus redes sociales @DigepresRD para poner a la disposici\u00f3n de los ciudadanos toda la informaci\u00f3n presupuestaria.<\/p>","protected":false},"author":2,"featured_media":38383,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[40,41,81,42,77,55],"class_list":["post-35843","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-institucionales","tag-digepres","tag-direccion-general-de-presupuesto","tag-jose-rijo-presbot","tag-ley-de-presupuesto","tag-poder-ejecutivo","tag-presupuesto-general-del-estado"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Fundaci\u00f3n Solidaridad entrega resultados Encuesta Presupuesto Abierto -<\/title>\n<meta name=\"description\" content=\"Fundaci\u00f3n Solidaridad entrega resultados Encuesta Presupuesto Abierto: RD ocupa puesto n\u00famero 1 a nivel continental en participaci\u00f3n p\u00fablica presupuestaria\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/digepres.gob.do\/en\/fundacion-solidaridad-entrega-resultados\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Fundaci\u00f3n Solidaridad entrega resultados Encuesta Presupuesto Abierto -\" \/>\n<meta property=\"og:description\" content=\"Fundaci\u00f3n Solidaridad entrega resultados Encuesta Presupuesto Abierto: RD ocupa puesto n\u00famero 1 a nivel continental en participaci\u00f3n p\u00fablica presupuestaria\" \/>\n<meta property=\"og:url\" content=\"https:\/\/digepres.gob.do\/en\/fundacion-solidaridad-entrega-resultados\/\" \/>\n<meta property=\"og:site_name\" content=\"Direcci\u00f3n General de Presupuesto - Rep\u00fablica Dominicana\" \/>\n<meta property=\"article:published_time\" content=\"2024-06-26T15:24:11+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-09-15T13:25:17+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/digepres.gob.do\/wp-content\/uploads\/2024\/06\/Fundacion-Solidaridad-entrega-resultados-Encuesta-Presupuesto-Abierto-RD-ocupa-puesto-numero-1-a-nivel-continental-en-participacion-publica-presupuestaria-scaled.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1442\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Pablo Paez\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Pablo Paez\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/digepres.gob.do\\\/fundacion-solidaridad-entrega-resultados\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/digepres.gob.do\\\/fundacion-solidaridad-entrega-resultados\\\/\"},\"author\":{\"name\":\"Pablo Paez\",\"@id\":\"https:\\\/\\\/digepres.gob.do\\\/#\\\/schema\\\/person\\\/f6f6885c1078d1d53221d15413ab38b5\"},\"headline\":\"Fundaci\u00f3n Solidaridad entrega resultados Encuesta Presupuesto Abierto: RD ocupa puesto n\u00famero 1 a nivel continental en participaci\u00f3n p\u00fablica presupuestaria\",\"datePublished\":\"2024-06-26T15:24:11+00:00\",\"dateModified\":\"2025-09-15T13:25:17+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/digepres.gob.do\\\/fundacion-solidaridad-entrega-resultados\\\/\"},\"wordCount\":854,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/digepres.gob.do\\\/fundacion-solidaridad-entrega-resultados\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/digepres.gob.do\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/Fundacion-Solidaridad-entrega-resultados-Encuesta-Presupuesto-Abierto-RD-ocupa-puesto-numero-1-a-nivel-continental-en-participacion-publica-presupuestaria-scaled.jpeg\",\"keywords\":[\"DIGEPRES\",\"Direcci\u00f3n General de Presupuesto\",\"Jos\u00e9 Rijo Presbot\",\"Ley de Presupuesto\",\"Poder Ejecutivo\",\"Presupuesto General del Estado\"],\"articleSection\":[\"Institucionales\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/digepres.gob.do\\\/fundacion-solidaridad-entrega-resultados\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/digepres.gob.do\\\/fundacion-solidaridad-entrega-resultados\\\/\",\"url\":\"https:\\\/\\\/digepres.gob.do\\\/fundacion-solidaridad-entrega-resultados\\\/\",\"name\":\"Fundaci\u00f3n Solidaridad entrega resultados Encuesta Presupuesto Abierto -\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/digepres.gob.do\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/digepres.gob.do\\\/fundacion-solidaridad-entrega-resultados\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/digepres.gob.do\\\/fundacion-solidaridad-entrega-resultados\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/digepres.gob.do\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/Fundacion-Solidaridad-entrega-resultados-Encuesta-Presupuesto-Abierto-RD-ocupa-puesto-numero-1-a-nivel-continental-en-participacion-publica-presupuestaria-scaled.jpeg\",\"datePublished\":\"2024-06-26T15:24:11+00:00\",\"dateModified\":\"2025-09-15T13:25:17+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/digepres.gob.do\\\/#\\\/schema\\\/person\\\/f6f6885c1078d1d53221d15413ab38b5\"},\"description\":\"Fundaci\u00f3n Solidaridad entrega resultados Encuesta Presupuesto Abierto: RD ocupa puesto n\u00famero 1 a nivel continental en participaci\u00f3n p\u00fablica presupuestaria\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/digepres.gob.do\\\/fundacion-solidaridad-entrega-resultados\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/digepres.gob.do\\\/fundacion-solidaridad-entrega-resultados\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/digepres.gob.do\\\/fundacion-solidaridad-entrega-resultados\\\/#primaryimage\",\"url\":\"https:\\\/\\\/digepres.gob.do\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/Fundacion-Solidaridad-entrega-resultados-Encuesta-Presupuesto-Abierto-RD-ocupa-puesto-numero-1-a-nivel-continental-en-participacion-publica-presupuestaria-scaled.jpeg\",\"contentUrl\":\"https:\\\/\\\/digepres.gob.do\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/Fundacion-Solidaridad-entrega-resultados-Encuesta-Presupuesto-Abierto-RD-ocupa-puesto-numero-1-a-nivel-continental-en-participacion-publica-presupuestaria-scaled.jpeg\",\"width\":2560,\"height\":1442,\"caption\":\"Fundaci\u00f3n Solidaridad entrega resultados Encuesta Presupuesto Abierto RD ocupa puesto n\u00famero 1 a nivel continental en participaci\u00f3n p\u00fablica presupuestaria\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/digepres.gob.do\\\/fundacion-solidaridad-entrega-resultados\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/digepres.gob.do\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Fundaci\u00f3n Solidaridad entrega resultados Encuesta Presupuesto Abierto: RD ocupa puesto n\u00famero 1 a nivel continental en participaci\u00f3n p\u00fablica presupuestaria\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/digepres.gob.do\\\/#website\",\"url\":\"https:\\\/\\\/digepres.gob.do\\\/\",\"name\":\"Direcci\u00f3n General de Presupuesto - Rep\u00fablica Dominicana\",\"description\":\"Somos el \u00d3rgano Rector del Sistema Presupuestario Dominicano por mandato de la Ley 423-06.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/digepres.gob.do\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/digepres.gob.do\\\/#\\\/schema\\\/person\\\/f6f6885c1078d1d53221d15413ab38b5\",\"name\":\"Pablo Paez\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e9d364ce257be032b8adf031185529d2677ad33d9298b62704d967cd574fa801?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e9d364ce257be032b8adf031185529d2677ad33d9298b62704d967cd574fa801?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e9d364ce257be032b8adf031185529d2677ad33d9298b62704d967cd574fa801?s=96&d=mm&r=g\",\"caption\":\"Pablo Paez\"},\"url\":\"https:\\\/\\\/digepres.gob.do\\\/en\\\/author\\\/ppaez\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Fundaci\u00f3n Solidaridad entrega resultados Encuesta Presupuesto Abierto -","description":"Fundaci\u00f3n Solidaridad entrega resultados Encuesta Presupuesto Abierto: RD ocupa puesto n\u00famero 1 a nivel continental en participaci\u00f3n p\u00fablica presupuestaria","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/digepres.gob.do\/en\/fundacion-solidaridad-entrega-resultados\/","og_locale":"en_US","og_type":"article","og_title":"Fundaci\u00f3n Solidaridad entrega resultados Encuesta Presupuesto Abierto -","og_description":"Fundaci\u00f3n Solidaridad entrega resultados Encuesta Presupuesto Abierto: RD ocupa puesto n\u00famero 1 a nivel continental en participaci\u00f3n p\u00fablica presupuestaria","og_url":"https:\/\/digepres.gob.do\/en\/fundacion-solidaridad-entrega-resultados\/","og_site_name":"Direcci\u00f3n General de Presupuesto - Rep\u00fablica Dominicana","article_published_time":"2024-06-26T15:24:11+00:00","article_modified_time":"2025-09-15T13:25:17+00:00","og_image":[{"width":2560,"height":1442,"url":"https:\/\/digepres.gob.do\/wp-content\/uploads\/2024\/06\/Fundacion-Solidaridad-entrega-resultados-Encuesta-Presupuesto-Abierto-RD-ocupa-puesto-numero-1-a-nivel-continental-en-participacion-publica-presupuestaria-scaled.jpeg","type":"image\/jpeg"}],"author":"Pablo Paez","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Pablo Paez","Est. reading time":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/digepres.gob.do\/fundacion-solidaridad-entrega-resultados\/#article","isPartOf":{"@id":"https:\/\/digepres.gob.do\/fundacion-solidaridad-entrega-resultados\/"},"author":{"name":"Pablo Paez","@id":"https:\/\/digepres.gob.do\/#\/schema\/person\/f6f6885c1078d1d53221d15413ab38b5"},"headline":"Fundaci\u00f3n Solidaridad entrega resultados Encuesta Presupuesto Abierto: RD ocupa puesto n\u00famero 1 a nivel continental en participaci\u00f3n p\u00fablica presupuestaria","datePublished":"2024-06-26T15:24:11+00:00","dateModified":"2025-09-15T13:25:17+00:00","mainEntityOfPage":{"@id":"https:\/\/digepres.gob.do\/fundacion-solidaridad-entrega-resultados\/"},"wordCount":854,"commentCount":0,"image":{"@id":"https:\/\/digepres.gob.do\/fundacion-solidaridad-entrega-resultados\/#primaryimage"},"thumbnailUrl":"https:\/\/digepres.gob.do\/wp-content\/uploads\/2024\/06\/Fundacion-Solidaridad-entrega-resultados-Encuesta-Presupuesto-Abierto-RD-ocupa-puesto-numero-1-a-nivel-continental-en-participacion-publica-presupuestaria-scaled.jpeg","keywords":["DIGEPRES","Direcci\u00f3n General de Presupuesto","Jos\u00e9 Rijo Presbot","Ley de Presupuesto","Poder Ejecutivo","Presupuesto General del Estado"],"articleSection":["Institucionales"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/digepres.gob.do\/fundacion-solidaridad-entrega-resultados\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/digepres.gob.do\/fundacion-solidaridad-entrega-resultados\/","url":"https:\/\/digepres.gob.do\/fundacion-solidaridad-entrega-resultados\/","name":"Fundaci\u00f3n Solidaridad entrega resultados Encuesta Presupuesto Abierto -","isPartOf":{"@id":"https:\/\/digepres.gob.do\/#website"},"primaryImageOfPage":{"@id":"https:\/\/digepres.gob.do\/fundacion-solidaridad-entrega-resultados\/#primaryimage"},"image":{"@id":"https:\/\/digepres.gob.do\/fundacion-solidaridad-entrega-resultados\/#primaryimage"},"thumbnailUrl":"https:\/\/digepres.gob.do\/wp-content\/uploads\/2024\/06\/Fundacion-Solidaridad-entrega-resultados-Encuesta-Presupuesto-Abierto-RD-ocupa-puesto-numero-1-a-nivel-continental-en-participacion-publica-presupuestaria-scaled.jpeg","datePublished":"2024-06-26T15:24:11+00:00","dateModified":"2025-09-15T13:25:17+00:00","author":{"@id":"https:\/\/digepres.gob.do\/#\/schema\/person\/f6f6885c1078d1d53221d15413ab38b5"},"description":"Fundaci\u00f3n Solidaridad entrega resultados Encuesta Presupuesto Abierto: RD ocupa puesto n\u00famero 1 a nivel continental en participaci\u00f3n p\u00fablica presupuestaria","breadcrumb":{"@id":"https:\/\/digepres.gob.do\/fundacion-solidaridad-entrega-resultados\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/digepres.gob.do\/fundacion-solidaridad-entrega-resultados\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/digepres.gob.do\/fundacion-solidaridad-entrega-resultados\/#primaryimage","url":"https:\/\/digepres.gob.do\/wp-content\/uploads\/2024\/06\/Fundacion-Solidaridad-entrega-resultados-Encuesta-Presupuesto-Abierto-RD-ocupa-puesto-numero-1-a-nivel-continental-en-participacion-publica-presupuestaria-scaled.jpeg","contentUrl":"https:\/\/digepres.gob.do\/wp-content\/uploads\/2024\/06\/Fundacion-Solidaridad-entrega-resultados-Encuesta-Presupuesto-Abierto-RD-ocupa-puesto-numero-1-a-nivel-continental-en-participacion-publica-presupuestaria-scaled.jpeg","width":2560,"height":1442,"caption":"Fundaci\u00f3n Solidaridad entrega resultados Encuesta Presupuesto Abierto RD ocupa puesto n\u00famero 1 a nivel continental en participaci\u00f3n p\u00fablica presupuestaria"},{"@type":"BreadcrumbList","@id":"https:\/\/digepres.gob.do\/fundacion-solidaridad-entrega-resultados\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/digepres.gob.do\/"},{"@type":"ListItem","position":2,"name":"Fundaci\u00f3n Solidaridad entrega resultados Encuesta Presupuesto Abierto: RD ocupa puesto n\u00famero 1 a nivel continental en participaci\u00f3n p\u00fablica presupuestaria"}]},{"@type":"WebSite","@id":"https:\/\/digepres.gob.do\/#website","url":"https:\/\/digepres.gob.do\/","name":"Direcci\u00f3n General de Presupuesto - Rep\u00fablica Dominicana","description":"Somos el \u00d3rgano Rector del Sistema Presupuestario Dominicano por mandato de la Ley 423-06.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/digepres.gob.do\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/digepres.gob.do\/#\/schema\/person\/f6f6885c1078d1d53221d15413ab38b5","name":"Pablo Paez","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/e9d364ce257be032b8adf031185529d2677ad33d9298b62704d967cd574fa801?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/e9d364ce257be032b8adf031185529d2677ad33d9298b62704d967cd574fa801?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/e9d364ce257be032b8adf031185529d2677ad33d9298b62704d967cd574fa801?s=96&d=mm&r=g","caption":"Pablo Paez"},"url":"https:\/\/digepres.gob.do\/en\/author\/ppaez\/"}]}},"_links":{"self":[{"href":"https:\/\/digepres.gob.do\/en\/wp-json\/wp\/v2\/posts\/35843","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/digepres.gob.do\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/digepres.gob.do\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/digepres.gob.do\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/digepres.gob.do\/en\/wp-json\/wp\/v2\/comments?post=35843"}],"version-history":[{"count":1,"href":"https:\/\/digepres.gob.do\/en\/wp-json\/wp\/v2\/posts\/35843\/revisions"}],"predecessor-version":[{"id":38384,"href":"https:\/\/digepres.gob.do\/en\/wp-json\/wp\/v2\/posts\/35843\/revisions\/38384"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/digepres.gob.do\/en\/wp-json\/wp\/v2\/media\/38383"}],"wp:attachment":[{"href":"https:\/\/digepres.gob.do\/en\/wp-json\/wp\/v2\/media?parent=35843"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/digepres.gob.do\/en\/wp-json\/wp\/v2\/categories?post=35843"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/digepres.gob.do\/en\/wp-json\/wp\/v2\/tags?post=35843"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}