
{"id":35461,"date":"2024-05-01T17:01:12","date_gmt":"2024-05-01T21:01:12","guid":{"rendered":"https:\/\/www.digepres.gob.do\/?p=35461"},"modified":"2025-09-15T09:39:23","modified_gmt":"2025-09-15T13:39:23","slug":"digepres-clausura-semana-de-la-etica-junto-a-la-periodista-altagracia-salazar","status":"publish","type":"post","link":"https:\/\/digepres.gob.do\/en\/digepres-clausura-semana-de-la-etica-junto-a-la-periodista-altagracia-salazar\/","title":{"rendered":"Digepres clausura Semana de la \u00c9tica junto a la periodista Altagracia Salazar como referente \u00e9tico"},"content":{"rendered":"<p>\t\t\t\t<strong><em>La destacada comunicadora socializ\u00f3 la importancia de la \u00e9tica para regular el\u00a0 comportamiento moral en lo personal y en el ejercicio profesional.<\/em><\/strong><\/p>\n<p>The General Directorate of Budget <a href=\"https:\/\/digepres.gob.do\/en\/\">(Digepres)<\/a> clausur\u00f3 la \u201cSemana de la \u00c9tica 2024, por una cultura de integridad\u201d con un encuentro con la destacada periodista Altagracia Salazar, a prop\u00f3sito de celebrarse el 29 de abril el D\u00eda Nacional de la \u00c9tica Ciudadana.<\/p>\n<p>Las actividades se llevaron a cabo durante toda una semana con la finalidad de seguir fomentando la cultura \u00e9tica entre los colaboradores de Presupuesto. El evento de cierre estuvo encabezado por el director de la Direcci\u00f3n General de Presupuesto, Jos\u00e9 Rijo Presbot; acompa\u00f1ado del subdirector Ivan Ram\u00edrez, Glenny Villanueva, encargada del departamento de \u00c9tica Publica de la Direcci\u00f3n General de \u00c9tica e Integridad Gubernamental <a href=\"https:\/\/www.digeig.gob.do\/\">(DIGEIG)<\/a>, en representaci\u00f3n de Milagros Ort\u00edz Bosch, as\u00ed como de encargados departamentales, supervisores de \u00e1reas y colaboradores de Presupuesto.<img fetchpriority=\"high\" decoding=\"async\" class=\"alignleft wp-image-35463 size-medium\" src=\"https:\/\/www.digepres.gob.do\/wp-content\/uploads\/2024\/05\/WhatsApp-Image-2024-05-01-at-3.06.00-PM-1-300x200.jpeg\" alt=\"Digepres clausura Semana de\" width=\"300\" height=\"200\" \/><\/p>\n<p>Las palabras de bienvenida estuvieron a cargo de Soribel Medina Lagrange, coordinadora general de la Comisi\u00f3n de Integridad Gubernamental y Cumplimiento Normativo <a href=\"https:\/\/www.digeig.gob.do\/comision-de-integridad-gubernamental-y-cumplimiento-normativo\/\">(CIGCN)<\/a> y Oficial de Integridad Gubernamental (OIG) de la Digepres, quien agradeci\u00f3 la participaci\u00f3n de los presentes y motivo a seguir un compromiso firme con los valores \u00e9ticos dentro y fuera de la instituci\u00f3n.<\/p>\n<p>En su intervenci\u00f3n, el director de Presupuesto, Jos\u00e9 Rijo Presbot, agradeci\u00f3 la presencia de Altagracia Salazar destacando que es una profesional que dignifica el periodismo y referente \u00e9tico\u00a0<em>\u201cAltagracia es una mujer digna, honesta, trabajadora, infranqueable a la malicia, la degradaci\u00f3n, la irresponsabilidad, el chantaje, el soborno o cualquiera de las putrefacciones que se expresan en algunos seres inferiores que dicen ejercer \u201cperiodismo\u201d,<\/em><em>\u00a0<\/em>cit\u00f3 Rijo Presbot haciendo referencia a un editorial del periodista Fausto Rosario sobre la comunicadora<em>.<\/em><\/p>\n<p>Altagracia Salazar, al dirigirse a los presentes explic\u00f3 las situaciones que enfrent\u00f3 por ejercer un period\u00edstico apegado a la \u00e9tica, que la llev\u00f3 a vivir tiempos dif\u00edciles, sin embargo, entendi\u00f3 que era el camino correcto, si quer\u00eda hacer un ejercicio profesional honesto, transparente y justo.\u00a0<em>\u201cLos valores \u00e9ticos no pasan de moda, la mejor forma de hacerlos visibles es la coherencia. Los valores \u00e9ticos nos hacen diferentes e impiden nos compren\u201d, explic\u00f3 la veterana periodista. Asimismo, destac\u00f3 Salazar, que la coherencia juega un papel muy importante, y que los valores no se imponen, sino, que resultan del rico desempe\u00f1o que pongamos para cultivarlos.<\/em><\/p>\n<p>Como parte del programa de cierre fue puesto en circulaci\u00f3n el segundo episodio del documental<em>\u00a0<\/em><em>\u201cEl Presupuesto en la Historia\u201d,<\/em><em>\u00a0<\/em>que cuenta con 6 episodios, esta vez, titulado<em>\u00a0<\/em><em>\u201cInicios de la Econom\u00eda y el Presupuesto en Rep\u00fablica Dominicana\u201d.<\/em><em>\u00a0<\/em>Iniciativa del Departamento de Comunicaciones, como un aporte a la memoria institucional de esta gesti\u00f3n presupuestaria.<img decoding=\"async\" class=\"alignright wp-image-35464 size-medium\" src=\"https:\/\/www.digepres.gob.do\/wp-content\/uploads\/2024\/05\/WhatsApp-Image-2024-05-01-at-3.06.00-PM-3-300x200.jpeg\" alt=\"Digepres clausura Semana de\" width=\"300\" height=\"200\" \/><\/p>\n<p>En la Semana de la \u00c9tica Digepres, se socializ\u00f3 a lo interno y externo de la entidad exaltar el valor de la integridad y la transparencia en la gesti\u00f3n gubernamental. Cont\u00f3 con la participaci\u00f3n de invitados <img decoding=\"async\" class=\"alignleft wp-image-35465 size-medium\" src=\"https:\/\/www.digepres.gob.do\/wp-content\/uploads\/2024\/05\/WhatsApp-Image-2024-05-01-at-3.06.00-PM-2-300x200.jpeg\" alt=\"Digepres clausura Semana de\" width=\"300\" height=\"200\" \/>especiales y colaboradores de Presupuesto.<\/p>\n<p><strong>D\u00eda Nacional de la \u00c9tica Ciudadana y compromiso institucional<\/strong><\/p>\n<p>Cada a\u00f1o, el 29 de abril, el pa\u00eds celebra el \u201cD\u00eda Nacional de la \u00c9tica Ciudadana\u201d y en ese d\u00eda memorable, se exalta a Ulises Francisco Espaillat, uno de los pol\u00edticos m\u00e1s democr\u00e1ticos y honestos que tuvo el pa\u00eds en el siglo XIX, s\u00edmbolo de la honradez y transparencia ciudadana.<\/p>\n<p>Digepres, bajo el liderazgo de la Direcci\u00f3n General de \u00c9tica e Integridad Gubernamental\u00a0<a href=\"https:\/\/nam10.safelinks.protection.outlook.com\/?url=https%3A%2F%2Fwww.digeig.gob.do%2F&amp;data=05%7C02%7Cadlopez%40digepres.gob.do%7Cdc810ea72d8e4bbb9a0108dc6a0d7a8e%7C84c1929114ab48678582dbea5badaa1d%7C0%7C0%7C638501853336877028%7CUnknown%7CTWFpbGZsb3d8eyJWIjoiMC4wLjAwMDAiLCJQIjoiV2luMzIiLCJBTiI6Ik1haWwiLCJXVCI6Mn0%3D%7C0%7C%7C%7C&amp;sdata=HHDGdrdPNu7GuoXO1Gwc43gEkw5Jl%2Be0kacAQ8VZ27A%3D&amp;reserved=0\">(DIGEIG)<\/a>, conform\u00f3 su Comisi\u00f3n de Integridad Gubernamental y Cumplimiento Normativo (CIGCN) en cumplimiento con el Decreto No. 791-21, que declara de alta prioridad nacional el proceso de implementaci\u00f3n y elecci\u00f3n de las Comisiones de Integridad Gubernamental y Cumplimiento Normativo (CIGCN) en todas las instituciones p\u00fablicas.<\/p>\n<p>En la actualidad, se trata de la primera vez que la Comisi\u00f3n de Integridad cuenta con representantes de todos los grupos organizacionales, como una manera de asegurar la participaci\u00f3n y el compromiso de los colaboradores en todos los niveles. La actividad se llev\u00f3 a cabo en el sal\u00f3n Juan Bosch de Digepres.\t\t<\/p>","protected":false},"excerpt":{"rendered":"<p>La destacada comunicadora socializ\u00f3 la importancia de la \u00e9tica para regular el\u00a0 comportamiento moral en lo personal y en el ejercicio profesional. La Direcci\u00f3n General de Presupuesto (Digepres) clausur\u00f3 la \u201cSemana de la \u00c9tica 2024, por una cultura de integridad\u201d con un encuentro con la destacada periodista Altagracia Salazar, a prop\u00f3sito de celebrarse el 29 de abril el D\u00eda Nacional de la \u00c9tica Ciudadana. Las actividades se llevaron a cabo durante toda una semana con la finalidad de seguir fomentando la cultura \u00e9tica entre los colaboradores de Presupuesto. El evento de cierre estuvo encabezado por el director de la Direcci\u00f3n General de Presupuesto, Jos\u00e9 Rijo Presbot; acompa\u00f1ado del subdirector Ivan Ram\u00edrez, Glenny Villanueva, encargada del departamento de \u00c9tica Publica de la Direcci\u00f3n General de \u00c9tica e Integridad Gubernamental (DIGEIG), en representaci\u00f3n de Milagros Ort\u00edz Bosch, as\u00ed como de encargados departamentales, supervisores de \u00e1reas y colaboradores de Presupuesto. Las palabras de bienvenida estuvieron a cargo de Soribel Medina Lagrange, coordinadora general de la Comisi\u00f3n de Integridad Gubernamental y Cumplimiento Normativo (CIGCN) y Oficial de Integridad Gubernamental (OIG) de la Digepres, quien agradeci\u00f3 la participaci\u00f3n de los presentes y motivo a seguir un compromiso firme con los valores \u00e9ticos dentro y fuera de la instituci\u00f3n. En su intervenci\u00f3n, el director de Presupuesto, Jos\u00e9 Rijo Presbot, agradeci\u00f3 la presencia de Altagracia Salazar destacando que es una profesional que dignifica el periodismo y referente \u00e9tico\u00a0\u201cAltagracia es una mujer digna, honesta, trabajadora, infranqueable a la malicia, la degradaci\u00f3n, la irresponsabilidad, el chantaje, el soborno o cualquiera de las putrefacciones que se expresan en algunos seres inferiores que dicen ejercer \u201cperiodismo\u201d,\u00a0cit\u00f3 Rijo Presbot haciendo referencia a un editorial del periodista Fausto Rosario sobre la comunicadora. Altagracia Salazar, al dirigirse a los presentes explic\u00f3 las situaciones que enfrent\u00f3 por ejercer un period\u00edstico apegado a la \u00e9tica, que la llev\u00f3 a vivir tiempos dif\u00edciles, sin embargo, entendi\u00f3 que era el camino correcto, si quer\u00eda hacer un ejercicio profesional honesto, transparente y justo.\u00a0\u201cLos valores \u00e9ticos no pasan de moda, la mejor forma de hacerlos visibles es la coherencia. Los valores \u00e9ticos nos hacen diferentes e impiden nos compren\u201d, explic\u00f3 la veterana periodista. Asimismo, destac\u00f3 Salazar, que la coherencia juega un papel muy importante, y que los valores no se imponen, sino, que resultan del rico desempe\u00f1o que pongamos para cultivarlos. Como parte del programa de cierre fue puesto en circulaci\u00f3n el segundo episodio del documental\u00a0\u201cEl Presupuesto en la Historia\u201d,\u00a0que cuenta con 6 episodios, esta vez, titulado\u00a0\u201cInicios de la Econom\u00eda y el Presupuesto en Rep\u00fablica Dominicana\u201d.\u00a0Iniciativa del Departamento de Comunicaciones, como un aporte a la memoria institucional de esta gesti\u00f3n presupuestaria. En la Semana de la \u00c9tica Digepres, se socializ\u00f3 a lo interno y externo de la entidad exaltar el valor de la integridad y la transparencia en la gesti\u00f3n gubernamental. Cont\u00f3 con la participaci\u00f3n de invitados especiales y colaboradores de Presupuesto. D\u00eda Nacional de la \u00c9tica Ciudadana y compromiso institucional Cada a\u00f1o, el 29 de abril, el pa\u00eds celebra el \u201cD\u00eda Nacional de la \u00c9tica Ciudadana\u201d y en ese d\u00eda memorable, se exalta a Ulises Francisco Espaillat, uno de los pol\u00edticos m\u00e1s democr\u00e1ticos y honestos que tuvo el pa\u00eds en el siglo XIX, s\u00edmbolo de la honradez y transparencia ciudadana. Digepres, bajo el liderazgo de la Direcci\u00f3n General de \u00c9tica e Integridad Gubernamental\u00a0(DIGEIG), conform\u00f3 su Comisi\u00f3n de Integridad Gubernamental y Cumplimiento Normativo (CIGCN) en cumplimiento con el Decreto No. 791-21, que declara de alta prioridad nacional el proceso de implementaci\u00f3n y elecci\u00f3n de las Comisiones de Integridad Gubernamental y Cumplimiento Normativo (CIGCN) en todas las instituciones p\u00fablicas. En la actualidad, se trata de la primera vez que la Comisi\u00f3n de Integridad cuenta con representantes de todos los grupos organizacionales, como una manera de asegurar la participaci\u00f3n y el compromiso de los colaboradores en todos los niveles. La actividad se llev\u00f3 a cabo en el sal\u00f3n Juan Bosch de Digepres.<\/p>","protected":false},"author":2,"featured_media":38420,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[40,41,44,81,77,52,55],"class_list":["post-35461","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-institucionales","tag-digepres","tag-direccion-general-de-presupuesto","tag-ejecucion-presupuestaria","tag-jose-rijo-presbot","tag-poder-ejecutivo","tag-presupuesto","tag-presupuesto-general-del-estado"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Digepres clausura Semana de la \u00c9tica junto a la periodista - DIGEPRES<\/title>\n<meta name=\"description\" content=\"Digepres clausura Semana de la \u00c9tica junto a la periodista Altagracia Salazar como referente \u00e9tico. La destacada comunicadora socializ\u00f3 la importancia de...\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/digepres.gob.do\/en\/digepres-clausura-semana-de-la-etica-junto-a-la-periodista-altagracia-salazar\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Digepres clausura Semana de la \u00c9tica junto a la periodista - DIGEPRES\" \/>\n<meta property=\"og:description\" content=\"Digepres clausura Semana de la \u00c9tica junto a la periodista Altagracia Salazar como referente \u00e9tico. La destacada comunicadora socializ\u00f3 la importancia de...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/digepres.gob.do\/en\/digepres-clausura-semana-de-la-etica-junto-a-la-periodista-altagracia-salazar\/\" \/>\n<meta property=\"og:site_name\" content=\"Direcci\u00f3n General de Presupuesto - Rep\u00fablica Dominicana\" \/>\n<meta property=\"article:published_time\" content=\"2024-05-01T21:01:12+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-09-15T13:39:23+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/digepres.gob.do\/wp-content\/uploads\/2024\/05\/Digepres-clausura-Semana-de-la-Etica-junto-a-la-periodista-Altagracia-Salazar-como-referente-etico-scaled.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1442\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Pablo Paez\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Pablo Paez\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/digepres.gob.do\\\/digepres-clausura-semana-de-la-etica-junto-a-la-periodista-altagracia-salazar\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/digepres.gob.do\\\/digepres-clausura-semana-de-la-etica-junto-a-la-periodista-altagracia-salazar\\\/\"},\"author\":{\"name\":\"Pablo Paez\",\"@id\":\"https:\\\/\\\/digepres.gob.do\\\/#\\\/schema\\\/person\\\/f6f6885c1078d1d53221d15413ab38b5\"},\"headline\":\"Digepres clausura Semana de la \u00c9tica junto a la periodista Altagracia Salazar como referente \u00e9tico\",\"datePublished\":\"2024-05-01T21:01:12+00:00\",\"dateModified\":\"2025-09-15T13:39:23+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/digepres.gob.do\\\/digepres-clausura-semana-de-la-etica-junto-a-la-periodista-altagracia-salazar\\\/\"},\"wordCount\":701,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/digepres.gob.do\\\/digepres-clausura-semana-de-la-etica-junto-a-la-periodista-altagracia-salazar\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/digepres.gob.do\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/Digepres-clausura-Semana-de-la-Etica-junto-a-la-periodista-Altagracia-Salazar-como-referente-etico-scaled.jpeg\",\"keywords\":[\"DIGEPRES\",\"Direcci\u00f3n General de Presupuesto\",\"Ejecuci\u00f3n Presupuestaria\",\"Jos\u00e9 Rijo Presbot\",\"Poder Ejecutivo\",\"Presupuesto\",\"Presupuesto General del Estado\"],\"articleSection\":[\"Institucionales\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/digepres.gob.do\\\/digepres-clausura-semana-de-la-etica-junto-a-la-periodista-altagracia-salazar\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/digepres.gob.do\\\/digepres-clausura-semana-de-la-etica-junto-a-la-periodista-altagracia-salazar\\\/\",\"url\":\"https:\\\/\\\/digepres.gob.do\\\/digepres-clausura-semana-de-la-etica-junto-a-la-periodista-altagracia-salazar\\\/\",\"name\":\"Digepres clausura Semana de la \u00c9tica junto a la periodista - DIGEPRES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/digepres.gob.do\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/digepres.gob.do\\\/digepres-clausura-semana-de-la-etica-junto-a-la-periodista-altagracia-salazar\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/digepres.gob.do\\\/digepres-clausura-semana-de-la-etica-junto-a-la-periodista-altagracia-salazar\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/digepres.gob.do\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/Digepres-clausura-Semana-de-la-Etica-junto-a-la-periodista-Altagracia-Salazar-como-referente-etico-scaled.jpeg\",\"datePublished\":\"2024-05-01T21:01:12+00:00\",\"dateModified\":\"2025-09-15T13:39:23+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/digepres.gob.do\\\/#\\\/schema\\\/person\\\/f6f6885c1078d1d53221d15413ab38b5\"},\"description\":\"Digepres clausura Semana de la \u00c9tica junto a la periodista Altagracia Salazar como referente \u00e9tico. La destacada comunicadora socializ\u00f3 la importancia de...\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/digepres.gob.do\\\/digepres-clausura-semana-de-la-etica-junto-a-la-periodista-altagracia-salazar\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/digepres.gob.do\\\/digepres-clausura-semana-de-la-etica-junto-a-la-periodista-altagracia-salazar\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/digepres.gob.do\\\/digepres-clausura-semana-de-la-etica-junto-a-la-periodista-altagracia-salazar\\\/#primaryimage\",\"url\":\"https:\\\/\\\/digepres.gob.do\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/Digepres-clausura-Semana-de-la-Etica-junto-a-la-periodista-Altagracia-Salazar-como-referente-etico-scaled.jpeg\",\"contentUrl\":\"https:\\\/\\\/digepres.gob.do\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/Digepres-clausura-Semana-de-la-Etica-junto-a-la-periodista-Altagracia-Salazar-como-referente-etico-scaled.jpeg\",\"width\":2560,\"height\":1442,\"caption\":\"Digepres clausura Semana de la \u00c9tica junto a la periodista Altagracia Salazar como referente \u00e9tico\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/digepres.gob.do\\\/digepres-clausura-semana-de-la-etica-junto-a-la-periodista-altagracia-salazar\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/digepres.gob.do\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Digepres clausura Semana de la \u00c9tica junto a la periodista Altagracia Salazar como referente \u00e9tico\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/digepres.gob.do\\\/#website\",\"url\":\"https:\\\/\\\/digepres.gob.do\\\/\",\"name\":\"Direcci\u00f3n General de Presupuesto - Rep\u00fablica Dominicana\",\"description\":\"Somos el \u00d3rgano Rector del Sistema Presupuestario Dominicano por mandato de la Ley 423-06.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/digepres.gob.do\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/digepres.gob.do\\\/#\\\/schema\\\/person\\\/f6f6885c1078d1d53221d15413ab38b5\",\"name\":\"Pablo Paez\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e9d364ce257be032b8adf031185529d2677ad33d9298b62704d967cd574fa801?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e9d364ce257be032b8adf031185529d2677ad33d9298b62704d967cd574fa801?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e9d364ce257be032b8adf031185529d2677ad33d9298b62704d967cd574fa801?s=96&d=mm&r=g\",\"caption\":\"Pablo Paez\"},\"url\":\"https:\\\/\\\/digepres.gob.do\\\/en\\\/author\\\/ppaez\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Digepres clausura Semana de la \u00c9tica junto a la periodista - DIGEPRES","description":"Digepres clausura Semana de la \u00c9tica junto a la periodista Altagracia Salazar como referente \u00e9tico. La destacada comunicadora socializ\u00f3 la importancia de...","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/digepres.gob.do\/en\/digepres-clausura-semana-de-la-etica-junto-a-la-periodista-altagracia-salazar\/","og_locale":"en_US","og_type":"article","og_title":"Digepres clausura Semana de la \u00c9tica junto a la periodista - DIGEPRES","og_description":"Digepres clausura Semana de la \u00c9tica junto a la periodista Altagracia Salazar como referente \u00e9tico. La destacada comunicadora socializ\u00f3 la importancia de...","og_url":"https:\/\/digepres.gob.do\/en\/digepres-clausura-semana-de-la-etica-junto-a-la-periodista-altagracia-salazar\/","og_site_name":"Direcci\u00f3n General de Presupuesto - Rep\u00fablica Dominicana","article_published_time":"2024-05-01T21:01:12+00:00","article_modified_time":"2025-09-15T13:39:23+00:00","og_image":[{"width":2560,"height":1442,"url":"https:\/\/digepres.gob.do\/wp-content\/uploads\/2024\/05\/Digepres-clausura-Semana-de-la-Etica-junto-a-la-periodista-Altagracia-Salazar-como-referente-etico-scaled.jpeg","type":"image\/jpeg"}],"author":"Pablo Paez","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Pablo Paez","Est. reading time":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/digepres.gob.do\/digepres-clausura-semana-de-la-etica-junto-a-la-periodista-altagracia-salazar\/#article","isPartOf":{"@id":"https:\/\/digepres.gob.do\/digepres-clausura-semana-de-la-etica-junto-a-la-periodista-altagracia-salazar\/"},"author":{"name":"Pablo Paez","@id":"https:\/\/digepres.gob.do\/#\/schema\/person\/f6f6885c1078d1d53221d15413ab38b5"},"headline":"Digepres clausura Semana de la \u00c9tica junto a la periodista Altagracia Salazar como referente \u00e9tico","datePublished":"2024-05-01T21:01:12+00:00","dateModified":"2025-09-15T13:39:23+00:00","mainEntityOfPage":{"@id":"https:\/\/digepres.gob.do\/digepres-clausura-semana-de-la-etica-junto-a-la-periodista-altagracia-salazar\/"},"wordCount":701,"commentCount":0,"image":{"@id":"https:\/\/digepres.gob.do\/digepres-clausura-semana-de-la-etica-junto-a-la-periodista-altagracia-salazar\/#primaryimage"},"thumbnailUrl":"https:\/\/digepres.gob.do\/wp-content\/uploads\/2024\/05\/Digepres-clausura-Semana-de-la-Etica-junto-a-la-periodista-Altagracia-Salazar-como-referente-etico-scaled.jpeg","keywords":["DIGEPRES","Direcci\u00f3n General de Presupuesto","Ejecuci\u00f3n Presupuestaria","Jos\u00e9 Rijo Presbot","Poder Ejecutivo","Presupuesto","Presupuesto General del Estado"],"articleSection":["Institucionales"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/digepres.gob.do\/digepres-clausura-semana-de-la-etica-junto-a-la-periodista-altagracia-salazar\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/digepres.gob.do\/digepres-clausura-semana-de-la-etica-junto-a-la-periodista-altagracia-salazar\/","url":"https:\/\/digepres.gob.do\/digepres-clausura-semana-de-la-etica-junto-a-la-periodista-altagracia-salazar\/","name":"Digepres clausura Semana de la \u00c9tica junto a la periodista - DIGEPRES","isPartOf":{"@id":"https:\/\/digepres.gob.do\/#website"},"primaryImageOfPage":{"@id":"https:\/\/digepres.gob.do\/digepres-clausura-semana-de-la-etica-junto-a-la-periodista-altagracia-salazar\/#primaryimage"},"image":{"@id":"https:\/\/digepres.gob.do\/digepres-clausura-semana-de-la-etica-junto-a-la-periodista-altagracia-salazar\/#primaryimage"},"thumbnailUrl":"https:\/\/digepres.gob.do\/wp-content\/uploads\/2024\/05\/Digepres-clausura-Semana-de-la-Etica-junto-a-la-periodista-Altagracia-Salazar-como-referente-etico-scaled.jpeg","datePublished":"2024-05-01T21:01:12+00:00","dateModified":"2025-09-15T13:39:23+00:00","author":{"@id":"https:\/\/digepres.gob.do\/#\/schema\/person\/f6f6885c1078d1d53221d15413ab38b5"},"description":"Digepres clausura Semana de la \u00c9tica junto a la periodista Altagracia Salazar como referente \u00e9tico. La destacada comunicadora socializ\u00f3 la importancia de...","breadcrumb":{"@id":"https:\/\/digepres.gob.do\/digepres-clausura-semana-de-la-etica-junto-a-la-periodista-altagracia-salazar\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/digepres.gob.do\/digepres-clausura-semana-de-la-etica-junto-a-la-periodista-altagracia-salazar\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/digepres.gob.do\/digepres-clausura-semana-de-la-etica-junto-a-la-periodista-altagracia-salazar\/#primaryimage","url":"https:\/\/digepres.gob.do\/wp-content\/uploads\/2024\/05\/Digepres-clausura-Semana-de-la-Etica-junto-a-la-periodista-Altagracia-Salazar-como-referente-etico-scaled.jpeg","contentUrl":"https:\/\/digepres.gob.do\/wp-content\/uploads\/2024\/05\/Digepres-clausura-Semana-de-la-Etica-junto-a-la-periodista-Altagracia-Salazar-como-referente-etico-scaled.jpeg","width":2560,"height":1442,"caption":"Digepres clausura Semana de la \u00c9tica junto a la periodista Altagracia Salazar como referente \u00e9tico"},{"@type":"BreadcrumbList","@id":"https:\/\/digepres.gob.do\/digepres-clausura-semana-de-la-etica-junto-a-la-periodista-altagracia-salazar\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/digepres.gob.do\/"},{"@type":"ListItem","position":2,"name":"Digepres clausura Semana de la \u00c9tica junto a la periodista Altagracia Salazar como referente \u00e9tico"}]},{"@type":"WebSite","@id":"https:\/\/digepres.gob.do\/#website","url":"https:\/\/digepres.gob.do\/","name":"Direcci\u00f3n General de Presupuesto - Rep\u00fablica Dominicana","description":"Somos el \u00d3rgano Rector del Sistema Presupuestario Dominicano por mandato de la Ley 423-06.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/digepres.gob.do\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/digepres.gob.do\/#\/schema\/person\/f6f6885c1078d1d53221d15413ab38b5","name":"Pablo Paez","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/e9d364ce257be032b8adf031185529d2677ad33d9298b62704d967cd574fa801?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/e9d364ce257be032b8adf031185529d2677ad33d9298b62704d967cd574fa801?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/e9d364ce257be032b8adf031185529d2677ad33d9298b62704d967cd574fa801?s=96&d=mm&r=g","caption":"Pablo Paez"},"url":"https:\/\/digepres.gob.do\/en\/author\/ppaez\/"}]}},"_links":{"self":[{"href":"https:\/\/digepres.gob.do\/en\/wp-json\/wp\/v2\/posts\/35461","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/digepres.gob.do\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/digepres.gob.do\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/digepres.gob.do\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/digepres.gob.do\/en\/wp-json\/wp\/v2\/comments?post=35461"}],"version-history":[{"count":1,"href":"https:\/\/digepres.gob.do\/en\/wp-json\/wp\/v2\/posts\/35461\/revisions"}],"predecessor-version":[{"id":38421,"href":"https:\/\/digepres.gob.do\/en\/wp-json\/wp\/v2\/posts\/35461\/revisions\/38421"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/digepres.gob.do\/en\/wp-json\/wp\/v2\/media\/38420"}],"wp:attachment":[{"href":"https:\/\/digepres.gob.do\/en\/wp-json\/wp\/v2\/media?parent=35461"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/digepres.gob.do\/en\/wp-json\/wp\/v2\/categories?post=35461"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/digepres.gob.do\/en\/wp-json\/wp\/v2\/tags?post=35461"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}