
{"id":33935,"date":"2023-12-07T14:39:30","date_gmt":"2023-12-07T18:39:30","guid":{"rendered":"https:\/\/www.digepres.gob.do\/?p=33935"},"modified":"2025-09-12T11:19:31","modified_gmt":"2025-09-12T15:19:31","slug":"proyecto-de-presupuesto-plurianual-orientado-a-resultados-es-presentado-por-digepres","status":"publish","type":"post","link":"https:\/\/digepres.gob.do\/en\/proyecto-de-presupuesto-plurianual-orientado-a-resultados-es-presentado-por-digepres\/","title":{"rendered":"Digepres presenta modelo conceptual del nuevo Proyecto de Presupuesto Plurianual Orientado a Resultados"},"content":{"rendered":"<p>\t\t\t\t<em>La propuesta, que se lleva a cabo en coordinaci\u00f3n con el Ministerio de Hacienda y el Banco Interamericano de Desarrollo (BID), busca impactar positivamente en la cultura presupuestaria del \u00e1mbito estatal<\/em><\/p>\n<figure id=\"attachment_33938\" aria-describedby=\"caption-attachment-33938\" style=\"width: 300px\" class=\"wp-caption alignright\"><img fetchpriority=\"high\" decoding=\"async\" class=\"wp-image-33938 size-medium\" title=\" Proyecto de Presupuesto POR\" src=\"https:\/\/www.digepres.gob.do\/wp-content\/uploads\/2023\/12\/ac00ff30-3eea-44e5-aa7a-539db23d211c-300x200.jpeg\" alt=\" Proyecto de Presupuesto POR\" width=\"300\" height=\"200\" \/><figcaption id=\"caption-attachment-33938\" class=\"wp-caption-text\">Jose Rijo Presbot<\/figcaption><\/figure>\n<p>La Direcci\u00f3n General de Presupuesto present\u00f3 a diversas autoridades las principales caracter\u00edsticas y atributos del nuevo Proyecto Presupuesto Plurianual Orientado a Resultados con Modalidad Din\u00e1mica, en coordinaci\u00f3n con el Ministerio de Hacienda y el Banco Interamericano de Desarrollo (BID). Esta actividad, se suma a las acciones que promueven la transformaci\u00f3n y mejora de la Administraci\u00f3n Tributaria, que impactar\u00e1 positivamente en la cultura presupuestaria del \u00e1mbito estatal.<\/p>\n<p>El acto de apertura fue encabezado por el ministro de Hacienda, Jos\u00e9 Manuel (Jochi) Vicente; el director general de Presupuesto, Jos\u00e9 Rijo Presbot; Iv\u00e1n Ram\u00edrez, subdirector de la <a href=\"https:\/\/digepres.gob.do\/en\/\">General Budget Directorate<\/a>; Ariel Teodoro Zaltsman, especialista l\u00edder en Gesti\u00f3n Fiscal del Banco Interamericano de Desarrollo (BID) y Griselda G\u00f3mez, directora de Calidad y Evaluaci\u00f3n del Gasto P\u00fablico de Presupuesto.<\/p>\n<p>Jos\u00e9 Manuel Vicente, ministro de Hacienda, quien dio las palabras de apertura al evento, agradeci\u00f3 las acciones que las instituciones involucradas en el nuevo sistema vienen realizando y destac\u00f3 que es parte de los trabajos que marcan la ruta hacia la mejora de la calidad del gasto p\u00fablico e intervenciones estatales<em>. <\/em>Indic\u00f3 que la propuesta del modelo conceptual de los procesos presupuestarios presentada busca que el Estado dominicano cuente con un mejor sistema presupuestario que contribuya y garantice la eficacia, eficiencia, calidad de gesti\u00f3n de los recursos p\u00fablicos y la mejora en los procesos vinculados. <em>\u201cEsta es una obra en construcci\u00f3n, hoy podemos decir que hemos avanzado y actualizado diversos procesos como las acciones que se enmarcan dentro el Proyecto Presupuesto Plurianual Orientado a Resultados con Modalidad Din\u00e1mica\u201d<\/em>, dijo el ministro de Hacienda.<\/p>\n<figure id=\"attachment_33939\" aria-describedby=\"caption-attachment-33939\" style=\"width: 300px\" class=\"wp-caption alignleft\"><img decoding=\"async\" class=\"wp-image-33939 size-medium\" title=\" Proyecto de Presupuesto POR\" src=\"https:\/\/www.digepres.gob.do\/wp-content\/uploads\/2023\/12\/WhatsApp-Image-2023-12-07-at-2.22.20-PM-2-300x200.jpeg\" alt=\" Proyecto de Presupuesto POR\" width=\"300\" height=\"200\" \/><figcaption id=\"caption-attachment-33939\" class=\"wp-caption-text\">Jochi Vicente (Ministro de Hacienda)<\/figcaption><\/figure>\n<p>Al cierre del evento, Jos\u00e9 Rijo Presbot, director de Presupuesto entreg\u00f3 ejemplares del Modelo Conceptual a Dar\u00edo Castillo, ministro de Administraci\u00f3n P\u00fablica; R\u00f3mulo Arias Moscat, director de Contabilidad Gubernamental y Luis Madera, viceministro de Planificaci\u00f3n e Inversi\u00f3n P\u00fablica del Ministerio de Econom\u00eda, Planificaci\u00f3n y Desarrollo. Rijo Presbot, en su intervenci\u00f3n destac\u00f3 la importancia del Modelo Conceptual y enfatiz\u00f3 la importancia del trabajo que viene realizando Digepres en torno a la implementaci\u00f3n de una nueva estructura program\u00e1tica de los gobiernos locales, para mejorar la formulaci\u00f3n de los presupuestos de cada ayuntamiento, y con ello, los servicios que ofrecen a los ciudadanos.<\/p>\n<p><strong>Generales del proyecto<\/strong><\/p>\n<p>El objetivo del proyecto es fortalecer la eficiencia y la calidad en la gesti\u00f3n de los recursos p\u00fablicos a trav\u00e9s de la elaboraci\u00f3n de un modelo conceptual, funcional y el desarrollo tecnol\u00f3gico para el nuevo sistema presupuestario dominicano, incorporando la plurianualidad y atributos din\u00e1micos en todo el ciclo.<\/p>\n<figure id=\"attachment_33940\" aria-describedby=\"caption-attachment-33940\" style=\"width: 300px\" class=\"wp-caption alignright\"><img decoding=\"async\" class=\"wp-image-33940 size-medium\" title=\" Proyecto de Presupuesto POR\" src=\"https:\/\/www.digepres.gob.do\/wp-content\/uploads\/2023\/12\/WhatsApp-Image-2023-12-07-at-2.22.20-PM-1-300x200.jpeg\" alt=\" Proyecto de Presupuesto POR\" width=\"300\" height=\"200\" \/><figcaption id=\"caption-attachment-33940\" class=\"wp-caption-text\">Griselda G\u00f3mez<\/figcaption><\/figure>\n<p>Para ampliar las generales del proyecto, la actividad cont\u00f3 con un panel que llev\u00f3 por nombre <em>\u201cModelo Funcional de Programaci\u00f3n y propuesta de interoperabilidad, retos y desaf\u00edos del proyecto Presupuesto Plurianual Orientado a Resultados con Modalidad Din\u00e1mica\u201d,<\/em> liderado por Griselda G\u00f3mez, directora del proyecto y Waldo Guti\u00e9rrez, consultor vinculado a la propuesta.<\/p>\n<p>Griselda G\u00f3mez y Waldo Guti\u00e9rrez, durante su participaci\u00f3n, de manera indistinta, explicaron en l\u00edneas generales a los presentes las caracter\u00edsticas y atributos del nuevo sistema presupuestario, los conexos del\u00a0Sistema Integrado de Administraci\u00f3n Financiera del Estado\u00a0(SIAFE), nuevas normativas del Sistema de Informaci\u00f3n de la Gesti\u00f3n Financiera (<a href=\"https:\/\/sigef.hacienda.gob.do\/sigef\/principal.jsp\">SIGEF<\/a>), el Modelo Integral de Gesti\u00f3n Financiera P\u00fablica y el Proyecto de Presupuesto Plurianual Orientado a Resultados con Modalidad Din\u00e1mica (PPORMD) finalizando con los retos, desaf\u00edos y pr\u00f3ximos como parte de la propuesta.<\/p>\n<p>&nbsp;\t\t<\/p>","protected":false},"excerpt":{"rendered":"<p>La propuesta, que se lleva a cabo en coordinaci\u00f3n con el Ministerio de Hacienda y el Banco Interamericano de Desarrollo (BID), busca impactar positivamente en la cultura presupuestaria del \u00e1mbito estatal La Direcci\u00f3n General de Presupuesto present\u00f3 a diversas autoridades las principales caracter\u00edsticas y atributos del nuevo Proyecto Presupuesto Plurianual Orientado a Resultados con Modalidad Din\u00e1mica, en coordinaci\u00f3n con el Ministerio de Hacienda y el Banco Interamericano de Desarrollo (BID). Esta actividad, se suma a las acciones que promueven la transformaci\u00f3n y mejora de la Administraci\u00f3n Tributaria, que impactar\u00e1 positivamente en la cultura presupuestaria del \u00e1mbito estatal. El acto de apertura fue encabezado por el ministro de Hacienda, Jos\u00e9 Manuel (Jochi) Vicente; el director general de Presupuesto, Jos\u00e9 Rijo Presbot; Iv\u00e1n Ram\u00edrez, subdirector de la Direcci\u00f3n General de Presupuesto; Ariel Teodoro Zaltsman, especialista l\u00edder en Gesti\u00f3n Fiscal del Banco Interamericano de Desarrollo (BID) y Griselda G\u00f3mez, directora de Calidad y Evaluaci\u00f3n del Gasto P\u00fablico de Presupuesto. Jos\u00e9 Manuel Vicente, ministro de Hacienda, quien dio las palabras de apertura al evento, agradeci\u00f3 las acciones que las instituciones involucradas en el nuevo sistema vienen realizando y destac\u00f3 que es parte de los trabajos que marcan la ruta hacia la mejora de la calidad del gasto p\u00fablico e intervenciones estatales. Indic\u00f3 que la propuesta del modelo conceptual de los procesos presupuestarios presentada busca que el Estado dominicano cuente con un mejor sistema presupuestario que contribuya y garantice la eficacia, eficiencia, calidad de gesti\u00f3n de los recursos p\u00fablicos y la mejora en los procesos vinculados. \u201cEsta es una obra en construcci\u00f3n, hoy podemos decir que hemos avanzado y actualizado diversos procesos como las acciones que se enmarcan dentro el Proyecto Presupuesto Plurianual Orientado a Resultados con Modalidad Din\u00e1mica\u201d, dijo el ministro de Hacienda. Al cierre del evento, Jos\u00e9 Rijo Presbot, director de Presupuesto entreg\u00f3 ejemplares del Modelo Conceptual a Dar\u00edo Castillo, ministro de Administraci\u00f3n P\u00fablica; R\u00f3mulo Arias Moscat, director de Contabilidad Gubernamental y Luis Madera, viceministro de Planificaci\u00f3n e Inversi\u00f3n P\u00fablica del Ministerio de Econom\u00eda, Planificaci\u00f3n y Desarrollo. Rijo Presbot, en su intervenci\u00f3n destac\u00f3 la importancia del Modelo Conceptual y enfatiz\u00f3 la importancia del trabajo que viene realizando Digepres en torno a la implementaci\u00f3n de una nueva estructura program\u00e1tica de los gobiernos locales, para mejorar la formulaci\u00f3n de los presupuestos de cada ayuntamiento, y con ello, los servicios que ofrecen a los ciudadanos. Generales del proyecto El objetivo del proyecto es fortalecer la eficiencia y la calidad en la gesti\u00f3n de los recursos p\u00fablicos a trav\u00e9s de la elaboraci\u00f3n de un modelo conceptual, funcional y el desarrollo tecnol\u00f3gico para el nuevo sistema presupuestario dominicano, incorporando la plurianualidad y atributos din\u00e1micos en todo el ciclo. Para ampliar las generales del proyecto, la actividad cont\u00f3 con un panel que llev\u00f3 por nombre \u201cModelo Funcional de Programaci\u00f3n y propuesta de interoperabilidad, retos y desaf\u00edos del proyecto Presupuesto Plurianual Orientado a Resultados con Modalidad Din\u00e1mica\u201d, liderado por Griselda G\u00f3mez, directora del proyecto y Waldo Guti\u00e9rrez, consultor vinculado a la propuesta. Griselda G\u00f3mez y Waldo Guti\u00e9rrez, durante su participaci\u00f3n, de manera indistinta, explicaron en l\u00edneas generales a los presentes las caracter\u00edsticas y atributos del nuevo sistema presupuestario, los conexos del\u00a0Sistema Integrado de Administraci\u00f3n Financiera del Estado\u00a0(SIAFE), nuevas normativas del Sistema de Informaci\u00f3n de la Gesti\u00f3n Financiera (SIGEF), el Modelo Integral de Gesti\u00f3n Financiera P\u00fablica y el Proyecto de Presupuesto Plurianual Orientado a Resultados con Modalidad Din\u00e1mica (PPORMD) finalizando con los retos, desaf\u00edos y pr\u00f3ximos como parte de la propuesta. &nbsp;<\/p>","protected":false},"author":2,"featured_media":34160,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[115,40,41,81],"class_list":["post-33935","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-institucionales","tag-bid","tag-digepres","tag-direccion-general-de-presupuesto","tag-jose-rijo-presbot"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Proyecto de Presupuesto POR es presentado por DIGEPRES<\/title>\n<meta name=\"description\" content=\"Proyecto de Presupuesto POR es presentado por DIGEPRES: Propuesta que busca impactar positivamente en la cultura presupuestaria del \u00e1mbito estatal.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/digepres.gob.do\/en\/proyecto-de-presupuesto-plurianual-orientado-a-resultados-es-presentado-por-digepres\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Proyecto de Presupuesto POR es presentado por DIGEPRES\" \/>\n<meta property=\"og:description\" content=\"Proyecto de Presupuesto POR es presentado por DIGEPRES: Propuesta que busca impactar positivamente en la cultura presupuestaria del \u00e1mbito estatal.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/digepres.gob.do\/en\/proyecto-de-presupuesto-plurianual-orientado-a-resultados-es-presentado-por-digepres\/\" \/>\n<meta property=\"og:site_name\" content=\"Direcci\u00f3n General de Presupuesto - Rep\u00fablica Dominicana\" \/>\n<meta property=\"article:published_time\" content=\"2023-12-07T18:39:30+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-09-12T15:19:31+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/digepres.gob.do\/wp-content\/uploads\/2023\/12\/Digepres-presenta-modelo-conceptual-del-nuevo-Proyecto-de-Presupuesto-Plurianual-Orientado-a-Resultados.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1600\" \/>\n\t<meta property=\"og:image:height\" content=\"901\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Pablo Paez\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Pablo Paez\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/digepres.gob.do\\\/proyecto-de-presupuesto-plurianual-orientado-a-resultados-es-presentado-por-digepres\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/digepres.gob.do\\\/proyecto-de-presupuesto-plurianual-orientado-a-resultados-es-presentado-por-digepres\\\/\"},\"author\":{\"name\":\"Pablo Paez\",\"@id\":\"https:\\\/\\\/digepres.gob.do\\\/#\\\/schema\\\/person\\\/f6f6885c1078d1d53221d15413ab38b5\"},\"headline\":\"Digepres presenta modelo conceptual del nuevo Proyecto de Presupuesto Plurianual Orientado a Resultados\",\"datePublished\":\"2023-12-07T18:39:30+00:00\",\"dateModified\":\"2025-09-12T15:19:31+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/digepres.gob.do\\\/proyecto-de-presupuesto-plurianual-orientado-a-resultados-es-presentado-por-digepres\\\/\"},\"wordCount\":675,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/digepres.gob.do\\\/proyecto-de-presupuesto-plurianual-orientado-a-resultados-es-presentado-por-digepres\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/digepres.gob.do\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/Digepres-presenta-modelo-conceptual-del-nuevo-Proyecto-de-Presupuesto-Plurianual-Orientado-a-Resultados.jpeg\",\"keywords\":[\"BID\",\"DIGEPRES\",\"Direcci\u00f3n General de Presupuesto\",\"Jos\u00e9 Rijo Presbot\"],\"articleSection\":[\"Institucionales\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/digepres.gob.do\\\/proyecto-de-presupuesto-plurianual-orientado-a-resultados-es-presentado-por-digepres\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/digepres.gob.do\\\/proyecto-de-presupuesto-plurianual-orientado-a-resultados-es-presentado-por-digepres\\\/\",\"url\":\"https:\\\/\\\/digepres.gob.do\\\/proyecto-de-presupuesto-plurianual-orientado-a-resultados-es-presentado-por-digepres\\\/\",\"name\":\"Proyecto de Presupuesto POR es presentado por DIGEPRES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/digepres.gob.do\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/digepres.gob.do\\\/proyecto-de-presupuesto-plurianual-orientado-a-resultados-es-presentado-por-digepres\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/digepres.gob.do\\\/proyecto-de-presupuesto-plurianual-orientado-a-resultados-es-presentado-por-digepres\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/digepres.gob.do\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/Digepres-presenta-modelo-conceptual-del-nuevo-Proyecto-de-Presupuesto-Plurianual-Orientado-a-Resultados.jpeg\",\"datePublished\":\"2023-12-07T18:39:30+00:00\",\"dateModified\":\"2025-09-12T15:19:31+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/digepres.gob.do\\\/#\\\/schema\\\/person\\\/f6f6885c1078d1d53221d15413ab38b5\"},\"description\":\"Proyecto de Presupuesto POR es presentado por DIGEPRES: Propuesta que busca impactar positivamente en la cultura presupuestaria del \u00e1mbito estatal.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/digepres.gob.do\\\/proyecto-de-presupuesto-plurianual-orientado-a-resultados-es-presentado-por-digepres\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/digepres.gob.do\\\/proyecto-de-presupuesto-plurianual-orientado-a-resultados-es-presentado-por-digepres\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/digepres.gob.do\\\/proyecto-de-presupuesto-plurianual-orientado-a-resultados-es-presentado-por-digepres\\\/#primaryimage\",\"url\":\"https:\\\/\\\/digepres.gob.do\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/Digepres-presenta-modelo-conceptual-del-nuevo-Proyecto-de-Presupuesto-Plurianual-Orientado-a-Resultados.jpeg\",\"contentUrl\":\"https:\\\/\\\/digepres.gob.do\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/Digepres-presenta-modelo-conceptual-del-nuevo-Proyecto-de-Presupuesto-Plurianual-Orientado-a-Resultados.jpeg\",\"width\":1600,\"height\":901,\"caption\":\"Digepres presenta modelo conceptual del nuevo Proyecto de Presupuesto Plurianual Orientado a Resultados\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/digepres.gob.do\\\/proyecto-de-presupuesto-plurianual-orientado-a-resultados-es-presentado-por-digepres\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/digepres.gob.do\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Digepres presenta modelo conceptual del nuevo Proyecto de Presupuesto Plurianual Orientado a Resultados\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/digepres.gob.do\\\/#website\",\"url\":\"https:\\\/\\\/digepres.gob.do\\\/\",\"name\":\"Direcci\u00f3n General de Presupuesto - Rep\u00fablica Dominicana\",\"description\":\"Somos el \u00d3rgano Rector del Sistema Presupuestario Dominicano por mandato de la Ley 423-06.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/digepres.gob.do\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/digepres.gob.do\\\/#\\\/schema\\\/person\\\/f6f6885c1078d1d53221d15413ab38b5\",\"name\":\"Pablo Paez\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e9d364ce257be032b8adf031185529d2677ad33d9298b62704d967cd574fa801?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e9d364ce257be032b8adf031185529d2677ad33d9298b62704d967cd574fa801?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e9d364ce257be032b8adf031185529d2677ad33d9298b62704d967cd574fa801?s=96&d=mm&r=g\",\"caption\":\"Pablo Paez\"},\"url\":\"https:\\\/\\\/digepres.gob.do\\\/en\\\/author\\\/ppaez\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Proyecto de Presupuesto POR es presentado por DIGEPRES","description":"Proyecto de Presupuesto POR es presentado por DIGEPRES: Propuesta que busca impactar positivamente en la cultura presupuestaria del \u00e1mbito estatal.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/digepres.gob.do\/en\/proyecto-de-presupuesto-plurianual-orientado-a-resultados-es-presentado-por-digepres\/","og_locale":"en_US","og_type":"article","og_title":"Proyecto de Presupuesto POR es presentado por DIGEPRES","og_description":"Proyecto de Presupuesto POR es presentado por DIGEPRES: Propuesta que busca impactar positivamente en la cultura presupuestaria del \u00e1mbito estatal.","og_url":"https:\/\/digepres.gob.do\/en\/proyecto-de-presupuesto-plurianual-orientado-a-resultados-es-presentado-por-digepres\/","og_site_name":"Direcci\u00f3n General de Presupuesto - Rep\u00fablica Dominicana","article_published_time":"2023-12-07T18:39:30+00:00","article_modified_time":"2025-09-12T15:19:31+00:00","og_image":[{"width":1600,"height":901,"url":"https:\/\/digepres.gob.do\/wp-content\/uploads\/2023\/12\/Digepres-presenta-modelo-conceptual-del-nuevo-Proyecto-de-Presupuesto-Plurianual-Orientado-a-Resultados.jpeg","type":"image\/jpeg"}],"author":"Pablo Paez","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Pablo Paez","Est. reading time":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/digepres.gob.do\/proyecto-de-presupuesto-plurianual-orientado-a-resultados-es-presentado-por-digepres\/#article","isPartOf":{"@id":"https:\/\/digepres.gob.do\/proyecto-de-presupuesto-plurianual-orientado-a-resultados-es-presentado-por-digepres\/"},"author":{"name":"Pablo Paez","@id":"https:\/\/digepres.gob.do\/#\/schema\/person\/f6f6885c1078d1d53221d15413ab38b5"},"headline":"Digepres presenta modelo conceptual del nuevo Proyecto de Presupuesto Plurianual Orientado a Resultados","datePublished":"2023-12-07T18:39:30+00:00","dateModified":"2025-09-12T15:19:31+00:00","mainEntityOfPage":{"@id":"https:\/\/digepres.gob.do\/proyecto-de-presupuesto-plurianual-orientado-a-resultados-es-presentado-por-digepres\/"},"wordCount":675,"commentCount":0,"image":{"@id":"https:\/\/digepres.gob.do\/proyecto-de-presupuesto-plurianual-orientado-a-resultados-es-presentado-por-digepres\/#primaryimage"},"thumbnailUrl":"https:\/\/digepres.gob.do\/wp-content\/uploads\/2023\/12\/Digepres-presenta-modelo-conceptual-del-nuevo-Proyecto-de-Presupuesto-Plurianual-Orientado-a-Resultados.jpeg","keywords":["BID","DIGEPRES","Direcci\u00f3n General de Presupuesto","Jos\u00e9 Rijo Presbot"],"articleSection":["Institucionales"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/digepres.gob.do\/proyecto-de-presupuesto-plurianual-orientado-a-resultados-es-presentado-por-digepres\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/digepres.gob.do\/proyecto-de-presupuesto-plurianual-orientado-a-resultados-es-presentado-por-digepres\/","url":"https:\/\/digepres.gob.do\/proyecto-de-presupuesto-plurianual-orientado-a-resultados-es-presentado-por-digepres\/","name":"Proyecto de Presupuesto POR es presentado por DIGEPRES","isPartOf":{"@id":"https:\/\/digepres.gob.do\/#website"},"primaryImageOfPage":{"@id":"https:\/\/digepres.gob.do\/proyecto-de-presupuesto-plurianual-orientado-a-resultados-es-presentado-por-digepres\/#primaryimage"},"image":{"@id":"https:\/\/digepres.gob.do\/proyecto-de-presupuesto-plurianual-orientado-a-resultados-es-presentado-por-digepres\/#primaryimage"},"thumbnailUrl":"https:\/\/digepres.gob.do\/wp-content\/uploads\/2023\/12\/Digepres-presenta-modelo-conceptual-del-nuevo-Proyecto-de-Presupuesto-Plurianual-Orientado-a-Resultados.jpeg","datePublished":"2023-12-07T18:39:30+00:00","dateModified":"2025-09-12T15:19:31+00:00","author":{"@id":"https:\/\/digepres.gob.do\/#\/schema\/person\/f6f6885c1078d1d53221d15413ab38b5"},"description":"Proyecto de Presupuesto POR es presentado por DIGEPRES: Propuesta que busca impactar positivamente en la cultura presupuestaria del \u00e1mbito estatal.","breadcrumb":{"@id":"https:\/\/digepres.gob.do\/proyecto-de-presupuesto-plurianual-orientado-a-resultados-es-presentado-por-digepres\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/digepres.gob.do\/proyecto-de-presupuesto-plurianual-orientado-a-resultados-es-presentado-por-digepres\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/digepres.gob.do\/proyecto-de-presupuesto-plurianual-orientado-a-resultados-es-presentado-por-digepres\/#primaryimage","url":"https:\/\/digepres.gob.do\/wp-content\/uploads\/2023\/12\/Digepres-presenta-modelo-conceptual-del-nuevo-Proyecto-de-Presupuesto-Plurianual-Orientado-a-Resultados.jpeg","contentUrl":"https:\/\/digepres.gob.do\/wp-content\/uploads\/2023\/12\/Digepres-presenta-modelo-conceptual-del-nuevo-Proyecto-de-Presupuesto-Plurianual-Orientado-a-Resultados.jpeg","width":1600,"height":901,"caption":"Digepres presenta modelo conceptual del nuevo Proyecto de Presupuesto Plurianual Orientado a Resultados"},{"@type":"BreadcrumbList","@id":"https:\/\/digepres.gob.do\/proyecto-de-presupuesto-plurianual-orientado-a-resultados-es-presentado-por-digepres\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/digepres.gob.do\/"},{"@type":"ListItem","position":2,"name":"Digepres presenta modelo conceptual del nuevo Proyecto de Presupuesto Plurianual Orientado a Resultados"}]},{"@type":"WebSite","@id":"https:\/\/digepres.gob.do\/#website","url":"https:\/\/digepres.gob.do\/","name":"Direcci\u00f3n General de Presupuesto - Rep\u00fablica Dominicana","description":"Somos el \u00d3rgano Rector del Sistema Presupuestario Dominicano por mandato de la Ley 423-06.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/digepres.gob.do\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/digepres.gob.do\/#\/schema\/person\/f6f6885c1078d1d53221d15413ab38b5","name":"Pablo Paez","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/e9d364ce257be032b8adf031185529d2677ad33d9298b62704d967cd574fa801?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/e9d364ce257be032b8adf031185529d2677ad33d9298b62704d967cd574fa801?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/e9d364ce257be032b8adf031185529d2677ad33d9298b62704d967cd574fa801?s=96&d=mm&r=g","caption":"Pablo Paez"},"url":"https:\/\/digepres.gob.do\/en\/author\/ppaez\/"}]}},"_links":{"self":[{"href":"https:\/\/digepres.gob.do\/en\/wp-json\/wp\/v2\/posts\/33935","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/digepres.gob.do\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/digepres.gob.do\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/digepres.gob.do\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/digepres.gob.do\/en\/wp-json\/wp\/v2\/comments?post=33935"}],"version-history":[{"count":1,"href":"https:\/\/digepres.gob.do\/en\/wp-json\/wp\/v2\/posts\/33935\/revisions"}],"predecessor-version":[{"id":34161,"href":"https:\/\/digepres.gob.do\/en\/wp-json\/wp\/v2\/posts\/33935\/revisions\/34161"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/digepres.gob.do\/en\/wp-json\/wp\/v2\/media\/34160"}],"wp:attachment":[{"href":"https:\/\/digepres.gob.do\/en\/wp-json\/wp\/v2\/media?parent=33935"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/digepres.gob.do\/en\/wp-json\/wp\/v2\/categories?post=33935"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/digepres.gob.do\/en\/wp-json\/wp\/v2\/tags?post=33935"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}