
{"id":32534,"date":"2023-08-18T10:27:44","date_gmt":"2023-08-18T14:27:44","guid":{"rendered":"https:\/\/www.digepres.gob.do\/?p=32534"},"modified":"2025-09-15T07:43:30","modified_gmt":"2025-09-15T11:43:30","slug":"presupuesto-recibe-mision-argentina-para-compartir-y-elevar-practicas-de-gestion-presupuestaria-con-el-apoyo-de-unicef","status":"publish","type":"post","link":"https:\/\/digepres.gob.do\/en\/presupuesto-recibe-mision-argentina-para-compartir-y-elevar-practicas-de-gestion-presupuestaria-con-el-apoyo-de-unicef\/","title":{"rendered":"Presupuesto recibe misi\u00f3n argentina para compartir y elevar pr\u00e1cticas de gesti\u00f3n presupuestaria con el apoyo de UNICEF"},"content":{"rendered":"<p>\t\t\t\t<em>La delegaci\u00f3n argentina estar\u00e1 agotando una agenda en materia econ\u00f3mica a favor de la ni\u00f1ez a trav\u00e9s del Presupuesto<\/em><\/p>\n<p>The director of the <a href=\"https:\/\/digepres.gob.do\/en\/\">General Budget Directorate<\/a>, Jos\u00e9 Rijo Presbot, recibi\u00f3 a representantes del Fondo de las Naciones Unidas para la Infancia (<a href=\"https:\/\/www.unicef.org\/es\">UNICEF<\/a>), de la Oficina Nacional de Presupuesto (ONP) y del Ministerio de Econom\u00eda de la Rep\u00fablica Argentina con el objetivo de seguir promoviendo la cooperaci\u00f3n triangular entre pa\u00edses de Am\u00e9rica Latina y el Caribe en materia de inversi\u00f3n p\u00fablica en ni\u00f1ez y adolescencia.<\/p>\n<p>La actividad fue encabezada por Rijo Presbot junto al subdirector general de Presupuesto, Iv\u00e1n Ram\u00edrez, quienes recibieron a Carlos Carrera, representante y a Gavino Severino, Oficial de Pol\u00edticas Sociales, del Fondo de las Naciones Unidas para la Infancia (UNICEF) en Rep\u00fablica Dominicana; Julia Frenkel, asistente t\u00e9cnica de UNICEF en Argentina; Guillermo Valentino, director de Evaluaci\u00f3n de la Oficina Nacional de Presupuesto del Ministerio de Econom\u00eda de Argentina y Gustavo Merino, de la Direcci\u00f3n General de Sistemas Inform\u00e1ticos de Administraci\u00f3n Financiera (DGSIAF) de la Rep\u00fablica de Argentina.<\/p>\n<p>En las palabras de bienvenida, el director de Presupuesto destac\u00f3 la importancia del intercambio entre las instituciones presentes, al tiempo de dar a conocer el contexto pa\u00eds en materia econ\u00f3mica y las reformas que ha implementado el Gobierno del presidente Luis Abinader para consolidar la transparencia y promover la participaci\u00f3n de la ciudadan\u00eda en el Presupuesto General del Estado (PGE).<img fetchpriority=\"high\" decoding=\"async\" class=\"alignright wp-image-32535 size-medium\" title=\"Presupuesto recibe misi\u00f3n argentina\" src=\"https:\/\/www.digepres.gob.do\/wp-content\/uploads\/2023\/08\/WhatsApp-Image-2023-08-18-at-10.09.01-AM-300x200.jpeg\" alt=\"Presupuesto recibe misi\u00f3n argentina\" width=\"300\" height=\"200\" \/><\/p>\n<p><em>\u201cDesde nuestra llegada a Presupuesto apostamos a la transparencia y al control social para enfrentar la corrupci\u00f3n, promover la \u00e9tica y generar la confianza ciudadana\u201d,<\/em> dijo Rijo Presbot. Destac\u00f3, tambi\u00e9n la iniciativa de su gesti\u00f3n de realizar los Encuentros Ciudadanos, para fomentar la participaci\u00f3n social reafirmando el compromiso institucional con el derecho a saber.<\/p>\n<p>Rijo Presbot y su equipo t\u00e9cnico explicaron los procesos que intervienen en el quehacer institucional como la planificaci\u00f3n estrat\u00e9gica, presupuesto plurianual y orientado a resultados, la creaci\u00f3n del clasificador funcional de g\u00e9nero y el cambio clim\u00e1tico, y el manejo sostenible de la deuda. Entre otros aspectos, las acciones del Gobierno en materia educativa, la eliminaci\u00f3n de la deuda administrativa y el trabajo conjunto con el Ministerio de Econom\u00eda, Planificaci\u00f3n y Desarrollo (MEPyD) para incorporar las demandas territoriales en el Presupuesto.<\/p>\n<p><img decoding=\"async\" class=\"alignleft wp-image-32536 size-medium\" title=\"Presupuesto recibe misi\u00f3n argentina\" src=\"https:\/\/www.digepres.gob.do\/wp-content\/uploads\/2023\/08\/WhatsApp-Image-2023-08-18-at-10.09.00-AM-300x200.jpeg\" alt=\"Presupuesto recibe misi\u00f3n argentina\" width=\"300\" height=\"200\" \/>El director de Presupuesto concluy\u00f3 recordando que Rep\u00fablica Dominicana est\u00e1 entre los primeros 10 pa\u00edses del mundo en materia de transparencia de acuerdo con las mediciones que realiza International Budget Partnership (IBP) que cuenta con un significativo crecimiento econ\u00f3mico avalado por la calificadora de riesgos Moody\u2019s y que, por\u00a0primera vez, alcanz\u00f3 la calificaci\u00f3n crediticia \u201cBB\u201d, otorgada por la agencia\u00a0Standard &amp; Poor\u2019s (S&amp;P).<\/p>\n<p>De su lado, Carrera, de UNICEF valor\u00f3 el presupuesto p\u00fablico, consider\u00e1ndolo un instrumento clave para proteger los derechos de la ni\u00f1ez. <em>\u201cLas pol\u00edticas p\u00fablicas tienen que verse reflejadas en el presupuesto para que tengan efecto; el compromiso de un gobierno para con sus ni\u00f1as, ni\u00f1os y adolescentes se debe expresar necesariamente en el aumento de la inversi\u00f3n en los servicios y programas sociales m\u00e1s esenciales\u201d<\/em>.<\/p>\n<p>Guillermo Valentino de la ONP, se enfoc\u00f3 en la vinculaci\u00f3n entre el presupuesto y la planificaci\u00f3n como herramienta central para mejorar la administraci\u00f3n de los recursos. De igual forma, Julia Frenkel consider\u00f3 importante que los derechos de la ni\u00f1ez est\u00e9n en el centro de las pol\u00edticas p\u00fablicas y explic\u00f3 las acciones que viene realizando su instituci\u00f3n en Argentina para ampliar los conocimientos de los congresistas en materia econ\u00f3mica y su impacto en la ni\u00f1ez.<\/p>\n<p><strong>Informaci\u00f3n de la misi\u00f3n<img decoding=\"async\" class=\"alignright wp-image-32537 size-medium\" title=\"Presupuesto recibe misi\u00f3n argentina\" src=\"https:\/\/www.digepres.gob.do\/wp-content\/uploads\/2023\/08\/WhatsApp-Image-2023-08-18-at-10.09.01-AM-1-300x200.jpeg\" alt=\"Presupuesto recibe misi\u00f3n argentina\" width=\"300\" height=\"200\" \/><\/strong><\/p>\n<p>Esta iniciativa resulta de las conclusiones del seminario internacional <em>\u201cInversi\u00f3n en la Infancia en Am\u00e9rica Latina y el Caribe: Una estrategia para acelerar el logro de los Objetivos de Desarrollo Sostenible\u201d<\/em>, realizado en el pa\u00eds en 2019. La misi\u00f3n estar\u00e1 en el pa\u00eds trabajando una agenda a favor de mejoras en el presupuesto en materia infancia.<\/p>\n<p>Al director de Presupuesto, le acompa\u00f1\u00f3 un equipo t\u00e9cnico integrado por Jenny Batista, encargada del departamento Servicios Sociales; Ana Miguelina Terrero, encargada de Evaluaci\u00f3n del Desempe\u00f1o Presupuestario; Sorangel Gonz\u00e1lez, encargada del departamento de An\u00e1lisis y Estudios Econ\u00f3micos; Odilys Hidalgo, de la Direcci\u00f3n de Servicios Presupuestarios; Mar\u00eda Victoria Ort\u00edz, encargada del departamento de Normas y Metodolog\u00edas, y Juan Portalat\u00edn, encargado de Gesti\u00f3n Financiera de Formulaci\u00f3n y Ejecuci\u00f3n de la Digepres.<\/p>\n<p>&nbsp;\t\t<\/p>","protected":false},"excerpt":{"rendered":"<p>La delegaci\u00f3n argentina estar\u00e1 agotando una agenda en materia econ\u00f3mica a favor de la ni\u00f1ez a trav\u00e9s del Presupuesto El director de la Direcci\u00f3n General de Presupuesto, Jos\u00e9 Rijo Presbot, recibi\u00f3 a representantes del Fondo de las Naciones Unidas para la Infancia (UNICEF), de la Oficina Nacional de Presupuesto (ONP) y del Ministerio de Econom\u00eda de la Rep\u00fablica Argentina con el objetivo de seguir promoviendo la cooperaci\u00f3n triangular entre pa\u00edses de Am\u00e9rica Latina y el Caribe en materia de inversi\u00f3n p\u00fablica en ni\u00f1ez y adolescencia. La actividad fue encabezada por Rijo Presbot junto al subdirector general de Presupuesto, Iv\u00e1n Ram\u00edrez, quienes recibieron a Carlos Carrera, representante y a Gavino Severino, Oficial de Pol\u00edticas Sociales, del Fondo de las Naciones Unidas para la Infancia (UNICEF) en Rep\u00fablica Dominicana; Julia Frenkel, asistente t\u00e9cnica de UNICEF en Argentina; Guillermo Valentino, director de Evaluaci\u00f3n de la Oficina Nacional de Presupuesto del Ministerio de Econom\u00eda de Argentina y Gustavo Merino, de la Direcci\u00f3n General de Sistemas Inform\u00e1ticos de Administraci\u00f3n Financiera (DGSIAF) de la Rep\u00fablica de Argentina. En las palabras de bienvenida, el director de Presupuesto destac\u00f3 la importancia del intercambio entre las instituciones presentes, al tiempo de dar a conocer el contexto pa\u00eds en materia econ\u00f3mica y las reformas que ha implementado el Gobierno del presidente Luis Abinader para consolidar la transparencia y promover la participaci\u00f3n de la ciudadan\u00eda en el Presupuesto General del Estado (PGE). \u201cDesde nuestra llegada a Presupuesto apostamos a la transparencia y al control social para enfrentar la corrupci\u00f3n, promover la \u00e9tica y generar la confianza ciudadana\u201d, dijo Rijo Presbot. Destac\u00f3, tambi\u00e9n la iniciativa de su gesti\u00f3n de realizar los Encuentros Ciudadanos, para fomentar la participaci\u00f3n social reafirmando el compromiso institucional con el derecho a saber. Rijo Presbot y su equipo t\u00e9cnico explicaron los procesos que intervienen en el quehacer institucional como la planificaci\u00f3n estrat\u00e9gica, presupuesto plurianual y orientado a resultados, la creaci\u00f3n del clasificador funcional de g\u00e9nero y el cambio clim\u00e1tico, y el manejo sostenible de la deuda. Entre otros aspectos, las acciones del Gobierno en materia educativa, la eliminaci\u00f3n de la deuda administrativa y el trabajo conjunto con el Ministerio de Econom\u00eda, Planificaci\u00f3n y Desarrollo (MEPyD) para incorporar las demandas territoriales en el Presupuesto. El director de Presupuesto concluy\u00f3 recordando que Rep\u00fablica Dominicana est\u00e1 entre los primeros 10 pa\u00edses del mundo en materia de transparencia de acuerdo con las mediciones que realiza International Budget Partnership (IBP) que cuenta con un significativo crecimiento econ\u00f3mico avalado por la calificadora de riesgos Moody\u2019s y que, por\u00a0primera vez, alcanz\u00f3 la calificaci\u00f3n crediticia \u201cBB\u201d, otorgada por la agencia\u00a0Standard &amp; Poor\u2019s (S&amp;P). De su lado, Carrera, de UNICEF valor\u00f3 el presupuesto p\u00fablico, consider\u00e1ndolo un instrumento clave para proteger los derechos de la ni\u00f1ez. \u201cLas pol\u00edticas p\u00fablicas tienen que verse reflejadas en el presupuesto para que tengan efecto; el compromiso de un gobierno para con sus ni\u00f1as, ni\u00f1os y adolescentes se debe expresar necesariamente en el aumento de la inversi\u00f3n en los servicios y programas sociales m\u00e1s esenciales\u201d. Guillermo Valentino de la ONP, se enfoc\u00f3 en la vinculaci\u00f3n entre el presupuesto y la planificaci\u00f3n como herramienta central para mejorar la administraci\u00f3n de los recursos. De igual forma, Julia Frenkel consider\u00f3 importante que los derechos de la ni\u00f1ez est\u00e9n en el centro de las pol\u00edticas p\u00fablicas y explic\u00f3 las acciones que viene realizando su instituci\u00f3n en Argentina para ampliar los conocimientos de los congresistas en materia econ\u00f3mica y su impacto en la ni\u00f1ez. Informaci\u00f3n de la misi\u00f3n Esta iniciativa resulta de las conclusiones del seminario internacional \u201cInversi\u00f3n en la Infancia en Am\u00e9rica Latina y el Caribe: Una estrategia para acelerar el logro de los Objetivos de Desarrollo Sostenible\u201d, realizado en el pa\u00eds en 2019. La misi\u00f3n estar\u00e1 en el pa\u00eds trabajando una agenda a favor de mejoras en el presupuesto en materia infancia. Al director de Presupuesto, le acompa\u00f1\u00f3 un equipo t\u00e9cnico integrado por Jenny Batista, encargada del departamento Servicios Sociales; Ana Miguelina Terrero, encargada de Evaluaci\u00f3n del Desempe\u00f1o Presupuestario; Sorangel Gonz\u00e1lez, encargada del departamento de An\u00e1lisis y Estudios Econ\u00f3micos; Odilys Hidalgo, de la Direcci\u00f3n de Servicios Presupuestarios; Mar\u00eda Victoria Ort\u00edz, encargada del departamento de Normas y Metodolog\u00edas, y Juan Portalat\u00edn, encargado de Gesti\u00f3n Financiera de Formulaci\u00f3n y Ejecuci\u00f3n de la Digepres. &nbsp;<\/p>","protected":false},"author":2,"featured_media":34297,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[40,41,79,81,55],"class_list":["post-32534","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-institucionales","tag-digepres","tag-direccion-general-de-presupuesto","tag-director-general-de-presupuesto","tag-jose-rijo-presbot","tag-presupuesto-general-del-estado"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Presupuesto recibe misi\u00f3n argentina para compartir y elevar pr\u00e1cticas<\/title>\n<meta name=\"description\" content=\"Presupuesto recibe misi\u00f3n argentina para compartir y elevar pr\u00e1cticas de gesti\u00f3n presupuestaria con el apoyo de UNICEF a favor de la ni\u00f1ez a trav\u00e9s del PGE.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/digepres.gob.do\/en\/presupuesto-recibe-mision-argentina-para-compartir-y-elevar-practicas-de-gestion-presupuestaria-con-el-apoyo-de-unicef\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Presupuesto recibe misi\u00f3n argentina para compartir y elevar pr\u00e1cticas\" \/>\n<meta property=\"og:description\" content=\"Presupuesto recibe misi\u00f3n argentina para compartir y elevar pr\u00e1cticas de gesti\u00f3n presupuestaria con el apoyo de UNICEF a favor de la ni\u00f1ez a trav\u00e9s del PGE.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/digepres.gob.do\/en\/presupuesto-recibe-mision-argentina-para-compartir-y-elevar-practicas-de-gestion-presupuestaria-con-el-apoyo-de-unicef\/\" \/>\n<meta property=\"og:site_name\" content=\"Direcci\u00f3n General de Presupuesto - Rep\u00fablica Dominicana\" \/>\n<meta property=\"article:published_time\" content=\"2023-08-18T14:27:44+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-09-15T11:43:30+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/digepres.gob.do\/wp-content\/uploads\/2023\/08\/Presupuesto-recibe-mision-argentina-para-compartir-y-elevar-practicas-de-gestion-presupuestaria-con-el-apoyo-de-UNICEF.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1600\" \/>\n\t<meta property=\"og:image:height\" content=\"1064\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Pablo Paez\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Pablo Paez\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/digepres.gob.do\\\/en\\\/presupuesto-recibe-mision-argentina-para-compartir-y-elevar-practicas-de-gestion-presupuestaria-con-el-apoyo-de-unicef\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/digepres.gob.do\\\/en\\\/presupuesto-recibe-mision-argentina-para-compartir-y-elevar-practicas-de-gestion-presupuestaria-con-el-apoyo-de-unicef\\\/\"},\"author\":{\"name\":\"Pablo Paez\",\"@id\":\"https:\\\/\\\/digepres.gob.do\\\/#\\\/schema\\\/person\\\/f6f6885c1078d1d53221d15413ab38b5\"},\"headline\":\"Presupuesto recibe misi\u00f3n argentina para compartir y elevar pr\u00e1cticas de gesti\u00f3n presupuestaria con el apoyo de UNICEF\",\"datePublished\":\"2023-08-18T14:27:44+00:00\",\"dateModified\":\"2025-09-15T11:43:30+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/digepres.gob.do\\\/en\\\/presupuesto-recibe-mision-argentina-para-compartir-y-elevar-practicas-de-gestion-presupuestaria-con-el-apoyo-de-unicef\\\/\"},\"wordCount\":805,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/digepres.gob.do\\\/en\\\/presupuesto-recibe-mision-argentina-para-compartir-y-elevar-practicas-de-gestion-presupuestaria-con-el-apoyo-de-unicef\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/digepres.gob.do\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/Presupuesto-recibe-mision-argentina-para-compartir-y-elevar-practicas-de-gestion-presupuestaria-con-el-apoyo-de-UNICEF.jpeg\",\"keywords\":[\"DIGEPRES\",\"Direcci\u00f3n General de Presupuesto\",\"Director General de Presupuesto\",\"Jos\u00e9 Rijo Presbot\",\"Presupuesto General del Estado\"],\"articleSection\":[\"Institucionales\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/digepres.gob.do\\\/en\\\/presupuesto-recibe-mision-argentina-para-compartir-y-elevar-practicas-de-gestion-presupuestaria-con-el-apoyo-de-unicef\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/digepres.gob.do\\\/en\\\/presupuesto-recibe-mision-argentina-para-compartir-y-elevar-practicas-de-gestion-presupuestaria-con-el-apoyo-de-unicef\\\/\",\"url\":\"https:\\\/\\\/digepres.gob.do\\\/en\\\/presupuesto-recibe-mision-argentina-para-compartir-y-elevar-practicas-de-gestion-presupuestaria-con-el-apoyo-de-unicef\\\/\",\"name\":\"Presupuesto recibe misi\u00f3n argentina para compartir y elevar pr\u00e1cticas\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/digepres.gob.do\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/digepres.gob.do\\\/en\\\/presupuesto-recibe-mision-argentina-para-compartir-y-elevar-practicas-de-gestion-presupuestaria-con-el-apoyo-de-unicef\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/digepres.gob.do\\\/en\\\/presupuesto-recibe-mision-argentina-para-compartir-y-elevar-practicas-de-gestion-presupuestaria-con-el-apoyo-de-unicef\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/digepres.gob.do\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/Presupuesto-recibe-mision-argentina-para-compartir-y-elevar-practicas-de-gestion-presupuestaria-con-el-apoyo-de-UNICEF.jpeg\",\"datePublished\":\"2023-08-18T14:27:44+00:00\",\"dateModified\":\"2025-09-15T11:43:30+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/digepres.gob.do\\\/#\\\/schema\\\/person\\\/f6f6885c1078d1d53221d15413ab38b5\"},\"description\":\"Presupuesto recibe misi\u00f3n argentina para compartir y elevar pr\u00e1cticas de gesti\u00f3n presupuestaria con el apoyo de UNICEF a favor de la ni\u00f1ez a trav\u00e9s del PGE.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/digepres.gob.do\\\/en\\\/presupuesto-recibe-mision-argentina-para-compartir-y-elevar-practicas-de-gestion-presupuestaria-con-el-apoyo-de-unicef\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/digepres.gob.do\\\/en\\\/presupuesto-recibe-mision-argentina-para-compartir-y-elevar-practicas-de-gestion-presupuestaria-con-el-apoyo-de-unicef\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/digepres.gob.do\\\/en\\\/presupuesto-recibe-mision-argentina-para-compartir-y-elevar-practicas-de-gestion-presupuestaria-con-el-apoyo-de-unicef\\\/#primaryimage\",\"url\":\"https:\\\/\\\/digepres.gob.do\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/Presupuesto-recibe-mision-argentina-para-compartir-y-elevar-practicas-de-gestion-presupuestaria-con-el-apoyo-de-UNICEF.jpeg\",\"contentUrl\":\"https:\\\/\\\/digepres.gob.do\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/Presupuesto-recibe-mision-argentina-para-compartir-y-elevar-practicas-de-gestion-presupuestaria-con-el-apoyo-de-UNICEF.jpeg\",\"width\":1600,\"height\":1064,\"caption\":\"Presupuesto recibe misi\u00f3n argentina para compartir y elevar pr\u00e1cticas de gesti\u00f3n presupuestaria con el apoyo de UNICEF\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/digepres.gob.do\\\/en\\\/presupuesto-recibe-mision-argentina-para-compartir-y-elevar-practicas-de-gestion-presupuestaria-con-el-apoyo-de-unicef\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/digepres.gob.do\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Presupuesto recibe misi\u00f3n argentina para compartir y elevar pr\u00e1cticas de gesti\u00f3n presupuestaria con el apoyo de UNICEF\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/digepres.gob.do\\\/#website\",\"url\":\"https:\\\/\\\/digepres.gob.do\\\/\",\"name\":\"Direcci\u00f3n General de Presupuesto - Rep\u00fablica Dominicana\",\"description\":\"Somos el \u00d3rgano Rector del Sistema Presupuestario Dominicano por mandato de la Ley 423-06.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/digepres.gob.do\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/digepres.gob.do\\\/#\\\/schema\\\/person\\\/f6f6885c1078d1d53221d15413ab38b5\",\"name\":\"Pablo Paez\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e9d364ce257be032b8adf031185529d2677ad33d9298b62704d967cd574fa801?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e9d364ce257be032b8adf031185529d2677ad33d9298b62704d967cd574fa801?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e9d364ce257be032b8adf031185529d2677ad33d9298b62704d967cd574fa801?s=96&d=mm&r=g\",\"caption\":\"Pablo Paez\"},\"url\":\"https:\\\/\\\/digepres.gob.do\\\/en\\\/author\\\/ppaez\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Presupuesto recibe misi\u00f3n argentina para compartir y elevar pr\u00e1cticas","description":"Presupuesto recibe misi\u00f3n argentina para compartir y elevar pr\u00e1cticas de gesti\u00f3n presupuestaria con el apoyo de UNICEF a favor de la ni\u00f1ez a trav\u00e9s del PGE.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/digepres.gob.do\/en\/presupuesto-recibe-mision-argentina-para-compartir-y-elevar-practicas-de-gestion-presupuestaria-con-el-apoyo-de-unicef\/","og_locale":"en_US","og_type":"article","og_title":"Presupuesto recibe misi\u00f3n argentina para compartir y elevar pr\u00e1cticas","og_description":"Presupuesto recibe misi\u00f3n argentina para compartir y elevar pr\u00e1cticas de gesti\u00f3n presupuestaria con el apoyo de UNICEF a favor de la ni\u00f1ez a trav\u00e9s del PGE.","og_url":"https:\/\/digepres.gob.do\/en\/presupuesto-recibe-mision-argentina-para-compartir-y-elevar-practicas-de-gestion-presupuestaria-con-el-apoyo-de-unicef\/","og_site_name":"Direcci\u00f3n General de Presupuesto - Rep\u00fablica Dominicana","article_published_time":"2023-08-18T14:27:44+00:00","article_modified_time":"2025-09-15T11:43:30+00:00","og_image":[{"width":1600,"height":1064,"url":"https:\/\/digepres.gob.do\/wp-content\/uploads\/2023\/08\/Presupuesto-recibe-mision-argentina-para-compartir-y-elevar-practicas-de-gestion-presupuestaria-con-el-apoyo-de-UNICEF.jpeg","type":"image\/jpeg"}],"author":"Pablo Paez","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Pablo Paez","Est. reading time":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/digepres.gob.do\/en\/presupuesto-recibe-mision-argentina-para-compartir-y-elevar-practicas-de-gestion-presupuestaria-con-el-apoyo-de-unicef\/#article","isPartOf":{"@id":"https:\/\/digepres.gob.do\/en\/presupuesto-recibe-mision-argentina-para-compartir-y-elevar-practicas-de-gestion-presupuestaria-con-el-apoyo-de-unicef\/"},"author":{"name":"Pablo Paez","@id":"https:\/\/digepres.gob.do\/#\/schema\/person\/f6f6885c1078d1d53221d15413ab38b5"},"headline":"Presupuesto recibe misi\u00f3n argentina para compartir y elevar pr\u00e1cticas de gesti\u00f3n presupuestaria con el apoyo de UNICEF","datePublished":"2023-08-18T14:27:44+00:00","dateModified":"2025-09-15T11:43:30+00:00","mainEntityOfPage":{"@id":"https:\/\/digepres.gob.do\/en\/presupuesto-recibe-mision-argentina-para-compartir-y-elevar-practicas-de-gestion-presupuestaria-con-el-apoyo-de-unicef\/"},"wordCount":805,"commentCount":0,"image":{"@id":"https:\/\/digepres.gob.do\/en\/presupuesto-recibe-mision-argentina-para-compartir-y-elevar-practicas-de-gestion-presupuestaria-con-el-apoyo-de-unicef\/#primaryimage"},"thumbnailUrl":"https:\/\/digepres.gob.do\/wp-content\/uploads\/2023\/08\/Presupuesto-recibe-mision-argentina-para-compartir-y-elevar-practicas-de-gestion-presupuestaria-con-el-apoyo-de-UNICEF.jpeg","keywords":["DIGEPRES","Direcci\u00f3n General de Presupuesto","Director General de Presupuesto","Jos\u00e9 Rijo Presbot","Presupuesto General del Estado"],"articleSection":["Institucionales"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/digepres.gob.do\/en\/presupuesto-recibe-mision-argentina-para-compartir-y-elevar-practicas-de-gestion-presupuestaria-con-el-apoyo-de-unicef\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/digepres.gob.do\/en\/presupuesto-recibe-mision-argentina-para-compartir-y-elevar-practicas-de-gestion-presupuestaria-con-el-apoyo-de-unicef\/","url":"https:\/\/digepres.gob.do\/en\/presupuesto-recibe-mision-argentina-para-compartir-y-elevar-practicas-de-gestion-presupuestaria-con-el-apoyo-de-unicef\/","name":"Presupuesto recibe misi\u00f3n argentina para compartir y elevar pr\u00e1cticas","isPartOf":{"@id":"https:\/\/digepres.gob.do\/#website"},"primaryImageOfPage":{"@id":"https:\/\/digepres.gob.do\/en\/presupuesto-recibe-mision-argentina-para-compartir-y-elevar-practicas-de-gestion-presupuestaria-con-el-apoyo-de-unicef\/#primaryimage"},"image":{"@id":"https:\/\/digepres.gob.do\/en\/presupuesto-recibe-mision-argentina-para-compartir-y-elevar-practicas-de-gestion-presupuestaria-con-el-apoyo-de-unicef\/#primaryimage"},"thumbnailUrl":"https:\/\/digepres.gob.do\/wp-content\/uploads\/2023\/08\/Presupuesto-recibe-mision-argentina-para-compartir-y-elevar-practicas-de-gestion-presupuestaria-con-el-apoyo-de-UNICEF.jpeg","datePublished":"2023-08-18T14:27:44+00:00","dateModified":"2025-09-15T11:43:30+00:00","author":{"@id":"https:\/\/digepres.gob.do\/#\/schema\/person\/f6f6885c1078d1d53221d15413ab38b5"},"description":"Presupuesto recibe misi\u00f3n argentina para compartir y elevar pr\u00e1cticas de gesti\u00f3n presupuestaria con el apoyo de UNICEF a favor de la ni\u00f1ez a trav\u00e9s del PGE.","breadcrumb":{"@id":"https:\/\/digepres.gob.do\/en\/presupuesto-recibe-mision-argentina-para-compartir-y-elevar-practicas-de-gestion-presupuestaria-con-el-apoyo-de-unicef\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/digepres.gob.do\/en\/presupuesto-recibe-mision-argentina-para-compartir-y-elevar-practicas-de-gestion-presupuestaria-con-el-apoyo-de-unicef\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/digepres.gob.do\/en\/presupuesto-recibe-mision-argentina-para-compartir-y-elevar-practicas-de-gestion-presupuestaria-con-el-apoyo-de-unicef\/#primaryimage","url":"https:\/\/digepres.gob.do\/wp-content\/uploads\/2023\/08\/Presupuesto-recibe-mision-argentina-para-compartir-y-elevar-practicas-de-gestion-presupuestaria-con-el-apoyo-de-UNICEF.jpeg","contentUrl":"https:\/\/digepres.gob.do\/wp-content\/uploads\/2023\/08\/Presupuesto-recibe-mision-argentina-para-compartir-y-elevar-practicas-de-gestion-presupuestaria-con-el-apoyo-de-UNICEF.jpeg","width":1600,"height":1064,"caption":"Presupuesto recibe misi\u00f3n argentina para compartir y elevar pr\u00e1cticas de gesti\u00f3n presupuestaria con el apoyo de UNICEF"},{"@type":"BreadcrumbList","@id":"https:\/\/digepres.gob.do\/en\/presupuesto-recibe-mision-argentina-para-compartir-y-elevar-practicas-de-gestion-presupuestaria-con-el-apoyo-de-unicef\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/digepres.gob.do\/"},{"@type":"ListItem","position":2,"name":"Presupuesto recibe misi\u00f3n argentina para compartir y elevar pr\u00e1cticas de gesti\u00f3n presupuestaria con el apoyo de UNICEF"}]},{"@type":"WebSite","@id":"https:\/\/digepres.gob.do\/#website","url":"https:\/\/digepres.gob.do\/","name":"Direcci\u00f3n General de Presupuesto - Rep\u00fablica Dominicana","description":"Somos el \u00d3rgano Rector del Sistema Presupuestario Dominicano por mandato de la Ley 423-06.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/digepres.gob.do\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/digepres.gob.do\/#\/schema\/person\/f6f6885c1078d1d53221d15413ab38b5","name":"Pablo Paez","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/e9d364ce257be032b8adf031185529d2677ad33d9298b62704d967cd574fa801?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/e9d364ce257be032b8adf031185529d2677ad33d9298b62704d967cd574fa801?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/e9d364ce257be032b8adf031185529d2677ad33d9298b62704d967cd574fa801?s=96&d=mm&r=g","caption":"Pablo Paez"},"url":"https:\/\/digepres.gob.do\/en\/author\/ppaez\/"}]}},"_links":{"self":[{"href":"https:\/\/digepres.gob.do\/en\/wp-json\/wp\/v2\/posts\/32534","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/digepres.gob.do\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/digepres.gob.do\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/digepres.gob.do\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/digepres.gob.do\/en\/wp-json\/wp\/v2\/comments?post=32534"}],"version-history":[{"count":1,"href":"https:\/\/digepres.gob.do\/en\/wp-json\/wp\/v2\/posts\/32534\/revisions"}],"predecessor-version":[{"id":34298,"href":"https:\/\/digepres.gob.do\/en\/wp-json\/wp\/v2\/posts\/32534\/revisions\/34298"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/digepres.gob.do\/en\/wp-json\/wp\/v2\/media\/34297"}],"wp:attachment":[{"href":"https:\/\/digepres.gob.do\/en\/wp-json\/wp\/v2\/media?parent=32534"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/digepres.gob.do\/en\/wp-json\/wp\/v2\/categories?post=32534"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/digepres.gob.do\/en\/wp-json\/wp\/v2\/tags?post=32534"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}