
{"id":1342,"date":"2025-03-26T12:26:39","date_gmt":"2025-03-26T16:26:39","guid":{"rendered":"http:\/\/digepres.gob.do\/?page_id=1342"},"modified":"2026-02-24T12:32:52","modified_gmt":"2026-02-24T16:32:52","slug":"plan-estrategico","status":"publish","type":"page","link":"https:\/\/digepres.gob.do\/en\/plan-estrategico\/","title":{"rendered":"Strategic Plan"},"content":{"rendered":"<div data-elementor-type=\"wp-page\" data-elementor-id=\"1342\" class=\"elementor elementor-1342\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5865b73c e-flex e-con-boxed wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-parent\" data-id=\"5865b73c\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4a1d33c6 elementor-widget elementor-widget-text-editor\" data-id=\"4a1d33c6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/digepres.gob.do\/en\/#facebook\" rel=\"noreferrer noopener\" target=\"_blank\"><\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-23a7e5f e-flex e-con-boxed wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-parent\" data-id=\"23a7e5f\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1dba900 elementor-widget elementor-widget-hfe-breadcrumbs-widget\" data-id=\"1dba900\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"hfe-breadcrumbs-widget.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<nav aria-label=\"Breadcrumb\"><ul class=\"hfe-breadcrumbs hfe-breadcrumbs-show-home\"><li class=\"hfe-breadcrumbs-item hfe-breadcrumbs-first\"><span class=\"hfe-breadcrumbs-home-icon\"><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-home\" viewbox=\"0 0 576 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M280.37 148.26L96 300.11V464a16 16 0 0 0 16 16l112.06-.29a16 16 0 0 0 15.92-16V368a16 16 0 0 1 16-16h64a16 16 0 0 1 16 16v95.64a16 16 0 0 0 16 16.05L464 480a16 16 0 0 0 16-16V300L295.67 148.26a12.19 12.19 0 0 0-15.3 0zM571.6 251.47L488 182.56V44.05a12 12 0 0 0-12-12h-56a12 12 0 0 0-12 12v72.61L318.47 43a48 48 0 0 0-61 0L4.34 251.47a12 12 0 0 0-1.6 16.9l25.5 31A12 12 0 0 0 45.15 301l235.22-193.74a12.19 12.19 0 0 1 15.3 0L530.9 301a12 12 0 0 0 16.9-1.6l25.5-31a12 12 0 0 0-1.7-16.93z\"><\/path><\/svg><\/span><a href=\"https:\/\/digepres.gob.do\/en\"><span class=\"hfe-breadcrumbs-text\">Start<\/span><\/a><\/li><\/ul><\/nav>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-ba9f59d e-flex e-con-boxed wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-parent\" data-id=\"ba9f59d\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-d88c3a5 e-con-full elementor-hidden-mobile e-flex wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-child\" data-id=\"d88c3a5\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-d81e817 elementor-widget elementor-widget-image\" data-id=\"d81e817\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"2084\" height=\"2084\" src=\"https:\/\/digepres.gob.do\/wp-content\/uploads\/2025\/03\/cupula-18.png\" class=\"attachment-full size-full wp-image-1072\" alt=\"Balance Presupuestario, Gastos, Ingresos. Informe Ejecuci\u00f3n Presupuestaria 2026, Gobierno General Nacional, Informes, Circulares\" srcset=\"https:\/\/digepres.gob.do\/wp-content\/uploads\/2025\/03\/cupula-18.png 2084w, https:\/\/digepres.gob.do\/wp-content\/uploads\/2025\/03\/cupula-18-300x300.png 300w, https:\/\/digepres.gob.do\/wp-content\/uploads\/2025\/03\/cupula-18-1024x1024.png 1024w, https:\/\/digepres.gob.do\/wp-content\/uploads\/2025\/03\/cupula-18-150x150.png 150w, https:\/\/digepres.gob.do\/wp-content\/uploads\/2025\/03\/cupula-18-768x768.png 768w, https:\/\/digepres.gob.do\/wp-content\/uploads\/2025\/03\/cupula-18-1536x1536.png 1536w, https:\/\/digepres.gob.do\/wp-content\/uploads\/2025\/03\/cupula-18-2048x2048.png 2048w, https:\/\/digepres.gob.do\/wp-content\/uploads\/2025\/03\/cupula-18-12x12.png 12w\" sizes=\"(max-width: 2084px) 100vw, 2084px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-b7ddd16 e-con-full e-flex wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-child\" data-id=\"b7ddd16\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-b807f37 e-flex e-con-boxed wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-parent\" data-id=\"b807f37\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-503732b wpr-advanced-accordion-icon-no-box elementor-widget elementor-widget-wpr-advanced-accordion\" data-id=\"503732b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"wpr-advanced-accordion.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n            <div class=\"wpr-advanced-accordion\" data-accordion-type=\"accordion\" data-active-index=\"0\" data-accordion-trigger=\"click\" data-interaction-speed=\"0.4\">\n\n\t\t\t\n                \n\t\t\t\t\t<div class=\"wpr-accordion-item-wrap\">\n\t\t\t\t\t\t<button class=\"wpr-acc-button\">\n\t\t\t\t\t\t\t<span class=\"wpr-acc-item-title\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"wpr-title-icon\">\n\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-folder-open\" viewbox=\"0 0 576 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M572.694 292.093L500.27 416.248A63.997 63.997 0 0 1 444.989 448H45.025c-18.523 0-30.064-20.093-20.731-36.093l72.424-124.155A64 64 0 0 1 152 256h399.964c18.523 0 30.064 20.093 20.73 36.093zM152 224h328v-48c0-26.51-21.49-48-48-48H272l-64-64H48C21.49 64 0 85.49 0 112v278.046l69.077-118.418C86.214 242.25 117.989 224 152 224z\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t\n\t\t\t\t\t\t\t\t<span class=\"wpr-acc-title-text\">2021-2024<\/span>\n\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"wpr-toggle-icon wpr-ti-close\"><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-plus-circle\" viewbox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M256 8C119 8 8 119 8 256s111 248 248 248 248-111 248-248S393 8 256 8zm144 276c0 6.6-5.4 12-12 12h-92v92c0 6.6-5.4 12-12 12h-56c-6.6 0-12-5.4-12-12v-92h-92c-6.6 0-12-5.4-12-12v-56c0-6.6 5.4-12 12-12h92v-92c0-6.6 5.4-12 12-12h56c6.6 0 12 5.4 12 12v92h92c6.6 0 12 5.4 12 12v56z\"><\/path><\/svg><\/span>\n\t\t\t\t<span class=\"wpr-toggle-icon wpr-ti-open\"><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-minus\" viewbox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h384c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t<\/button>\n\n\t\t\t\t\t\t<div class=\"wpr-acc-panel\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"wpr-acc-panel-content\"><p>\t\t<div data-elementor-type=\"page\" data-elementor-id=\"43762\" class=\"elementor elementor-43762\" data-elementor-post-type=\"elementor_library\">\n\t\t\t\t<div class=\"elementor-element elementor-element-22d7af5 e-con-full e-flex wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-parent\" data-id=\"22d7af5\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-8456f69 e-con-full e-flex wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-child\" data-id=\"8456f69\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-fff9b2b e-con-full e-flex wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-child\" data-id=\"fff9b2b\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7e4f9a0 elementor-widget__width-initial elementor-widget-mobile__width-initial elementor-widget elementor-widget-image\" data-id=\"7e4f9a0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"512\" height=\"512\" src=\"https:\/\/digepres.gob.do\/wp-content\/uploads\/2025\/03\/pdf-1.png\" class=\"attachment-full size-full wp-image-1231\" alt=\"\" srcset=\"https:\/\/digepres.gob.do\/wp-content\/uploads\/2025\/03\/pdf-1.png 512w, https:\/\/digepres.gob.do\/wp-content\/uploads\/2025\/03\/pdf-1-300x300.png 300w, https:\/\/digepres.gob.do\/wp-content\/uploads\/2025\/03\/pdf-1-150x150.png 150w, https:\/\/digepres.gob.do\/wp-content\/uploads\/2025\/03\/pdf-1-12x12.png 12w\" sizes=\"(max-width: 512px) 100vw, 512px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-94bc262 elementor-widget__width-initial elementor-widget-tablet__width-initial elementor-widget elementor-widget-heading\" data-id=\"94bc262\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Plan Estrat\u00e9gico 2021-2024<\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5b40bf6 elementor-hidden-mobile elementor-widget elementor-widget-button\" data-id=\"5b40bf6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/digepres.gob.do\/wp-content\/uploads\/2026\/02\/plan-estrategico-institucional.pdf\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Discharge<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-767eb97 elementor-widget elementor-widget-text-editor\" data-id=\"767eb97\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<pre class=\"info\">Upload date: <span style=\"color: #e4242c;\"><strong><span class=\"value\"> 14 \/ 09\/ 2022 <\/span><\/strong><\/span>  Tama\u00f1o: 13<span style=\"color: #e4242c;\"><strong><span class=\"value\"> MB <\/span><\/strong><\/span>- Format:\u00a0<span style=\"color: #e4242c;\"><strong><span class=\"value\">PDF<\/span><\/strong><\/span><\/pre>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4b94d2c elementor-hidden-desktop elementor-hidden-tablet elementor-widget elementor-widget-button\" data-id=\"4b94d2c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/digepres.gob.do\/wp-content\/uploads\/2026\/02\/plan-estrategico-institucional.pdf\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Discharge<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<\/p><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n                    <\/div>\n\n                \n\t\t\t\t\t<div class=\"wpr-accordion-item-wrap\">\n\t\t\t\t\t\t<button class=\"wpr-acc-button\">\n\t\t\t\t\t\t\t<span class=\"wpr-acc-item-title\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"wpr-title-icon\">\n\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-folder-open\" viewbox=\"0 0 576 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M572.694 292.093L500.27 416.248A63.997 63.997 0 0 1 444.989 448H45.025c-18.523 0-30.064-20.093-20.731-36.093l72.424-124.155A64 64 0 0 1 152 256h399.964c18.523 0 30.064 20.093 20.73 36.093zM152 224h328v-48c0-26.51-21.49-48-48-48H272l-64-64H48C21.49 64 0 85.49 0 112v278.046l69.077-118.418C86.214 242.25 117.989 224 152 224z\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t\n\t\t\t\t\t\t\t\t<span class=\"wpr-acc-title-text\">2018-2020<\/span>\n\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"wpr-toggle-icon wpr-ti-close\"><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-plus-circle\" viewbox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M256 8C119 8 8 119 8 256s111 248 248 248 248-111 248-248S393 8 256 8zm144 276c0 6.6-5.4 12-12 12h-92v92c0 6.6-5.4 12-12 12h-56c-6.6 0-12-5.4-12-12v-92h-92c-6.6 0-12-5.4-12-12v-56c0-6.6 5.4-12 12-12h92v-92c0-6.6 5.4-12 12-12h56c6.6 0 12 5.4 12 12v92h92c6.6 0 12 5.4 12 12v56z\"><\/path><\/svg><\/span>\n\t\t\t\t<span class=\"wpr-toggle-icon wpr-ti-open\"><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-minus\" viewbox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h384c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t<\/button>\n\n\t\t\t\t\t\t<div class=\"wpr-acc-panel\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"wpr-acc-panel-content\"><p>\t\t<div data-elementor-type=\"page\" data-elementor-id=\"43770\" class=\"elementor elementor-43770\" data-elementor-post-type=\"elementor_library\">\n\t\t\t\t<div class=\"elementor-element elementor-element-22d7af5 e-con-full e-flex wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-parent\" data-id=\"22d7af5\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-8456f69 e-con-full e-flex wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-child\" data-id=\"8456f69\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-fff9b2b e-con-full e-flex wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-child\" data-id=\"fff9b2b\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7e4f9a0 elementor-widget__width-initial elementor-widget-mobile__width-initial elementor-widget elementor-widget-image\" data-id=\"7e4f9a0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"512\" height=\"512\" src=\"https:\/\/digepres.gob.do\/wp-content\/uploads\/2025\/03\/pdf-1.png\" class=\"attachment-full size-full wp-image-1231\" alt=\"\" srcset=\"https:\/\/digepres.gob.do\/wp-content\/uploads\/2025\/03\/pdf-1.png 512w, https:\/\/digepres.gob.do\/wp-content\/uploads\/2025\/03\/pdf-1-300x300.png 300w, https:\/\/digepres.gob.do\/wp-content\/uploads\/2025\/03\/pdf-1-150x150.png 150w, https:\/\/digepres.gob.do\/wp-content\/uploads\/2025\/03\/pdf-1-12x12.png 12w\" sizes=\"(max-width: 512px) 100vw, 512px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-94bc262 elementor-widget__width-initial elementor-widget-tablet__width-initial elementor-widget elementor-widget-heading\" data-id=\"94bc262\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Plan Estrat\u00e9gico\n2018-2020<\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5b40bf6 elementor-hidden-mobile elementor-widget elementor-widget-button\" data-id=\"5b40bf6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/digepres.gob.do\/wp-content\/uploads\/2026\/02\/Plan-Estrategico-Institucional-2018-2020.pdf\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Discharge<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-767eb97 elementor-widget elementor-widget-text-editor\" data-id=\"767eb97\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<pre class=\"info\">Upload date: <span style=\"color: #e4242c;\"><strong><span class=\"value\"> 13 \/ 08\/ 2019 <\/span><\/strong><\/span>  Tama\u00f1o: 13<span style=\"color: #e4242c;\"><strong><span class=\"value\"> MB <\/span><\/strong><\/span>- Format:\u00a0<span style=\"color: #e4242c;\"><strong><span class=\"value\">PDF<\/span><\/strong><\/span><\/pre>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4b94d2c elementor-hidden-desktop elementor-hidden-tablet elementor-widget elementor-widget-button\" data-id=\"4b94d2c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/digepres.gob.do\/wp-content\/uploads\/2026\/02\/Plan-Estrategico-Institucional-2018-2020.pdf\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Discharge<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<\/p><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n                    <\/div>\n\n                \n\t\t\t\t\t<div class=\"wpr-accordion-item-wrap\">\n\t\t\t\t\t\t<button class=\"wpr-acc-button\">\n\t\t\t\t\t\t\t<span class=\"wpr-acc-item-title\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"wpr-title-icon\">\n\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-folder-open\" viewbox=\"0 0 576 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M572.694 292.093L500.27 416.248A63.997 63.997 0 0 1 444.989 448H45.025c-18.523 0-30.064-20.093-20.731-36.093l72.424-124.155A64 64 0 0 1 152 256h399.964c18.523 0 30.064 20.093 20.73 36.093zM152 224h328v-48c0-26.51-21.49-48-48-48H272l-64-64H48C21.49 64 0 85.49 0 112v278.046l69.077-118.418C86.214 242.25 117.989 224 152 224z\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t\n\t\t\t\t\t\t\t\t<span class=\"wpr-acc-title-text\">2013-2017<\/span>\n\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"wpr-toggle-icon wpr-ti-close\"><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-plus-circle\" viewbox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M256 8C119 8 8 119 8 256s111 248 248 248 248-111 248-248S393 8 256 8zm144 276c0 6.6-5.4 12-12 12h-92v92c0 6.6-5.4 12-12 12h-56c-6.6 0-12-5.4-12-12v-92h-92c-6.6 0-12-5.4-12-12v-56c0-6.6 5.4-12 12-12h92v-92c0-6.6 5.4-12 12-12h56c6.6 0 12 5.4 12 12v92h92c6.6 0 12 5.4 12 12v56z\"><\/path><\/svg><\/span>\n\t\t\t\t<span class=\"wpr-toggle-icon wpr-ti-open\"><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-minus\" viewbox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h384c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t<\/button>\n\n\t\t\t\t\t\t<div class=\"wpr-acc-panel\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"wpr-acc-panel-content\"><p>\t\t<div data-elementor-type=\"page\" data-elementor-id=\"43777\" class=\"elementor elementor-43777\" data-elementor-post-type=\"elementor_library\">\n\t\t\t\t<div class=\"elementor-element elementor-element-22d7af5 e-con-full e-flex wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-parent\" data-id=\"22d7af5\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-8456f69 e-con-full e-flex wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-child\" data-id=\"8456f69\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-fff9b2b e-con-full e-flex wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-child\" data-id=\"fff9b2b\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7e4f9a0 elementor-widget__width-initial elementor-widget-mobile__width-initial elementor-widget elementor-widget-image\" data-id=\"7e4f9a0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"512\" height=\"512\" src=\"https:\/\/digepres.gob.do\/wp-content\/uploads\/2025\/03\/pdf-1.png\" class=\"attachment-full size-full wp-image-1231\" alt=\"\" srcset=\"https:\/\/digepres.gob.do\/wp-content\/uploads\/2025\/03\/pdf-1.png 512w, https:\/\/digepres.gob.do\/wp-content\/uploads\/2025\/03\/pdf-1-300x300.png 300w, https:\/\/digepres.gob.do\/wp-content\/uploads\/2025\/03\/pdf-1-150x150.png 150w, https:\/\/digepres.gob.do\/wp-content\/uploads\/2025\/03\/pdf-1-12x12.png 12w\" sizes=\"(max-width: 512px) 100vw, 512px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-94bc262 elementor-widget__width-initial elementor-widget-tablet__width-initial elementor-widget elementor-widget-heading\" data-id=\"94bc262\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Plan Estrat\u00e9gico 2013-2017<\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5b40bf6 elementor-hidden-mobile elementor-widget elementor-widget-button\" data-id=\"5b40bf6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/digepres.gob.do\/wp-content\/uploads\/2026\/02\/Plan-Estrategico-DIGEPRES-2013-2017-Informe-PEI-DIGEPRES-10-7-2013.pdf\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Discharge<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-767eb97 elementor-widget elementor-widget-text-editor\" data-id=\"767eb97\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<pre class=\"info\">Upload date: <span style=\"color: #e4242c;\"><strong><span class=\"value\"> 16 \/ 08\/ 2019 <\/span><\/strong><\/span>  Tama\u00f1o: 1.02<span style=\"color: #e4242c;\"><strong><span class=\"value\"> MB <\/span><\/strong><\/span>- Format:\u00a0<span style=\"color: #e4242c;\"><strong><span class=\"value\">PDF<\/span><\/strong><\/span><\/pre>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4b94d2c elementor-hidden-desktop elementor-hidden-tablet elementor-widget elementor-widget-button\" data-id=\"4b94d2c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/digepres.gob.do\/wp-content\/uploads\/2026\/02\/Plan-Estrategico-DIGEPRES-2013-2017-Informe-PEI-DIGEPRES-10-7-2013.pdf\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Discharge<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<\/p><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n                    <\/div>\n\n                            <\/div>\n        \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Inicio 2021-2024 2018-2020 2013-2017<\/p>","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_canvas","meta":{"footnotes":""},"class_list":["post-1342","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Plan Estrat\u00e9gico - Direcci\u00f3n General de Presupuesto - Rep\u00fablica Dominicana<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/digepres.gob.do\/en\/plan-estrategico\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Plan Estrat\u00e9gico - Direcci\u00f3n General de Presupuesto - Rep\u00fablica Dominicana\" \/>\n<meta property=\"og:description\" content=\"Inicio 2021-2024 2018-2020 2013-2017\" \/>\n<meta property=\"og:url\" content=\"https:\/\/digepres.gob.do\/en\/plan-estrategico\/\" \/>\n<meta property=\"og:site_name\" content=\"Direcci\u00f3n General de Presupuesto - Rep\u00fablica Dominicana\" \/>\n<meta property=\"article:modified_time\" content=\"2026-02-24T16:32:52+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/digepres.gob.do\/wp-content\/uploads\/2025\/03\/cupula-18.png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/digepres.gob.do\\\/plan-estrategico\\\/\",\"url\":\"https:\\\/\\\/digepres.gob.do\\\/plan-estrategico\\\/\",\"name\":\"Plan Estrat\u00e9gico - Direcci\u00f3n General de Presupuesto - Rep\u00fablica Dominicana\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/digepres.gob.do\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/digepres.gob.do\\\/plan-estrategico\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/digepres.gob.do\\\/plan-estrategico\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/digepres.gob.do\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/cupula-18.png\",\"datePublished\":\"2025-03-26T16:26:39+00:00\",\"dateModified\":\"2026-02-24T16:32:52+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/digepres.gob.do\\\/plan-estrategico\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/digepres.gob.do\\\/plan-estrategico\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/digepres.gob.do\\\/plan-estrategico\\\/#primaryimage\",\"url\":\"https:\\\/\\\/digepres.gob.do\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/cupula-18.png\",\"contentUrl\":\"https:\\\/\\\/digepres.gob.do\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/cupula-18.png\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/digepres.gob.do\\\/plan-estrategico\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/digepres.gob.do\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Plan Estrat\u00e9gico\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/digepres.gob.do\\\/#website\",\"url\":\"https:\\\/\\\/digepres.gob.do\\\/\",\"name\":\"Direcci\u00f3n General de Presupuesto - Rep\u00fablica Dominicana\",\"description\":\"Somos el \u00d3rgano Rector del Sistema Presupuestario Dominicano por mandato de la Ley 423-06.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/digepres.gob.do\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Plan Estrat\u00e9gico - Direcci\u00f3n General de Presupuesto - Rep\u00fablica Dominicana","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/digepres.gob.do\/en\/plan-estrategico\/","og_locale":"en_US","og_type":"article","og_title":"Plan Estrat\u00e9gico - Direcci\u00f3n General de Presupuesto - Rep\u00fablica Dominicana","og_description":"Inicio 2021-2024 2018-2020 2013-2017","og_url":"https:\/\/digepres.gob.do\/en\/plan-estrategico\/","og_site_name":"Direcci\u00f3n General de Presupuesto - Rep\u00fablica Dominicana","article_modified_time":"2026-02-24T16:32:52+00:00","og_image":[{"url":"https:\/\/digepres.gob.do\/wp-content\/uploads\/2025\/03\/cupula-18.png","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/digepres.gob.do\/plan-estrategico\/","url":"https:\/\/digepres.gob.do\/plan-estrategico\/","name":"Plan Estrat\u00e9gico - Direcci\u00f3n General de Presupuesto - Rep\u00fablica Dominicana","isPartOf":{"@id":"https:\/\/digepres.gob.do\/#website"},"primaryImageOfPage":{"@id":"https:\/\/digepres.gob.do\/plan-estrategico\/#primaryimage"},"image":{"@id":"https:\/\/digepres.gob.do\/plan-estrategico\/#primaryimage"},"thumbnailUrl":"https:\/\/digepres.gob.do\/wp-content\/uploads\/2025\/03\/cupula-18.png","datePublished":"2025-03-26T16:26:39+00:00","dateModified":"2026-02-24T16:32:52+00:00","breadcrumb":{"@id":"https:\/\/digepres.gob.do\/plan-estrategico\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/digepres.gob.do\/plan-estrategico\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/digepres.gob.do\/plan-estrategico\/#primaryimage","url":"https:\/\/digepres.gob.do\/wp-content\/uploads\/2025\/03\/cupula-18.png","contentUrl":"https:\/\/digepres.gob.do\/wp-content\/uploads\/2025\/03\/cupula-18.png"},{"@type":"BreadcrumbList","@id":"https:\/\/digepres.gob.do\/plan-estrategico\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/digepres.gob.do\/"},{"@type":"ListItem","position":2,"name":"Plan Estrat\u00e9gico"}]},{"@type":"WebSite","@id":"https:\/\/digepres.gob.do\/#website","url":"https:\/\/digepres.gob.do\/","name":"Direcci\u00f3n General de Presupuesto - Rep\u00fablica Dominicana","description":"Somos el \u00d3rgano Rector del Sistema Presupuestario Dominicano por mandato de la Ley 423-06.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/digepres.gob.do\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/digepres.gob.do\/en\/wp-json\/wp\/v2\/pages\/1342","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/digepres.gob.do\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/digepres.gob.do\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/digepres.gob.do\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/digepres.gob.do\/en\/wp-json\/wp\/v2\/comments?post=1342"}],"version-history":[{"count":31,"href":"https:\/\/digepres.gob.do\/en\/wp-json\/wp\/v2\/pages\/1342\/revisions"}],"predecessor-version":[{"id":43811,"href":"https:\/\/digepres.gob.do\/en\/wp-json\/wp\/v2\/pages\/1342\/revisions\/43811"}],"wp:attachment":[{"href":"https:\/\/digepres.gob.do\/en\/wp-json\/wp\/v2\/media?parent=1342"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}